{"id":18898,"date":"2020-02-11T19:47:27","date_gmt":"2024-06-03T07:28:17","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/"},"modified":"2024-06-03T07:28:27","modified_gmt":"2024-06-03T07:28:27","slug":"dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/","title":{"rendered":"Dario Jazbec Hrvatin &#8211; f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mein Name ist Dario Jazbec Hrvatin und ich bin f\u00fcr die Dokumentation aller OnTheGoSystems-Projekte zust\u00e4ndig. Hier ist eine kleine Geschichte \u00fcber mich und dar\u00fcber, wie es ist, aus der Ferne zu arbeiten.<\/p>\n\n<h2 class=\"wp-block-heading\">Ein wenig \u00fcber meinen Hintergrund<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-768x1024.jpg\" alt=\"\" class=\"wp-image-6548 lazyload\" width=\"218\" height=\"290\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-768x1024.jpg 768w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-225x300.jpg 225w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-1152x1536.jpg 1152w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-1536x2048.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3.jpg 1200w\" data-sizes=\"(max-width: 218px) 100vw, 218px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 218px; --smush-placeholder-aspect-ratio: 218\/290;\" \/><figcaption class=\"wp-element-caption\"> <em>Schlittschuhlaufen mit meiner Tochter Gloria<\/em><\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Ich lebe in Slowenien, zusammen mit meiner Frau, unserer Tochter und dem s\u00fc\u00dfesten kleinen Chihuahua namens Mrfi (wie Murphy).<\/p>\n\n<p class=\"wp-block-paragraph\">Als ich jung war<strong>,<\/strong> wollte ich immer Musiker werden. Ich sch\u00e4tze, Musik war und ist immer noch in meiner DNA. Ich erinnere mich noch gut daran, wie ich als Kind auf den Feldern rund um unser Haus herumlief und Paul McCartneys Kompilation &#8222;All the best! Wenn ich nur einen Tag lang einen anderen Job haben k\u00f6nnte, w\u00e4re ich Musiker (das haben Sie nicht kommen sehen, oder?). Allerdings habe ich eine Band namens Helika und wir haben vor ein paar Jahren ein Album ver\u00f6ffentlicht. Ich habe noch viele weitere Songs, aber ich warte darauf, dass ich etwas Zeit finde, um sie aufzunehmen. Ich bin wirklich am gl\u00fccklichsten, wenn ich meiner Familie meine Lieder vorspiele. :)<\/p>\n\n<p class=\"wp-block-paragraph\">Das soll nicht hei\u00dfen, dass ich keine anderen Tr\u00e4ume hatte. Eigentlich wollte ich schon immer einmal versuchen, mit einem Fallschirm aus einem Flugzeug zu springen, aber r\u00fcckblickend bin ich froh, dass ich diesen Drang verloren habe. Ich ziehe es vor, mein Leben nicht mehr auf diese Weise zu riskieren!<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_guitar-2-683x1024.jpg\" alt=\"\" class=\"wp-image-6489 lazyload\" width=\"175\" height=\"260\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 175px; --smush-placeholder-aspect-ratio: 175\/260;\" \/><figcaption class=\"wp-element-caption\"><br\/><em>Ein Konzert mit meiner Band Helika zu spielen<\/em><\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Das Schwierigste, was ich bisher tun musste, und ich bin wirklich ein sehr gl\u00fccklicher Mensch, dass dies das Schwierigste war, war der Abschluss meines Universit\u00e4tsstudiums in Wirtschaftswissenschaften. Es gibt viel \u00fcber Wirtschaft, das ich interessant finde, aber die Art und Weise, wie der Lehrplan geplant war, hat mir einfach nicht gefallen. Aber aus irgendeinem Grund habe ich durchgehalten und es nach 15 schmerzhaften Jahren beendet. Die Lektion: Machen Sie das, was Sie im Leben wirklich interessiert und wissen Sie, wann Sie aufh\u00f6ren m\u00fcssen, wenn es nicht funktioniert. Machen Sie es nicht wie ich :)<\/p>\n\n<p class=\"wp-block-paragraph\">Einer der ungew\u00f6hnlichsten Jobs, die ich je hatte, war, f\u00fcr ein paar Tage als Statist an einem Filmset in einem Tanzclub zu arbeiten. Das hat Spa\u00df gemacht, aber meine Haupteinnahmequelle war die Arbeit f\u00fcr ein Marketingunternehmen. Der Job war jedoch nicht zu retten. Ich habe WPML und das Types-Plugin in all meinen Projekten verwendet, w\u00e4hrend ich mit diesem Unternehmen gearbeitet habe. Ich hatte volles Vertrauen in diese Plugins und merkte bald, dass ich OnTheGoSystems, den Machern von WPML und Toolset, wertvolle F\u00e4higkeiten zu bieten hatte. Der Gedanke blieb bestehen. Das war etwas, das ich tun musste. Die Zeit war reif, und mit einem sanften Vertrauensvorschuss meiner Frau bin ich nun hier!<br\/><\/p>\n\n<h2 class=\"wp-block-heading\">Wie es wirklich ist, bei OnTheGoSystems zu arbeiten<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/OTGS-1024x798.jpg\" alt=\"\" class=\"wp-image-6510 lazyload\" width=\"300\" height=\"234\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/OTGS-1024x798.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/OTGS-300x233.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/OTGS-1536x1197.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/OTGS-2048x1596.jpg 2048w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/OTGS.jpg 512w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/234;\" \/><figcaption class=\"wp-element-caption\"><br\/><em>Das OnTheGoSystems-Team auf dem WordCamp Europe Belgrad<\/em><\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Ich habe sehr viel gelernt. Ich habe als Testerin angefangen und leite jetzt die Dokumentation. Ich arbeite eng mit fast allen Mitarbeitern des Unternehmens zusammen. Das ist tats\u00e4chlich eine seltene und gro\u00dfartige Position. Meine Sprachkenntnisse haben sich verbessert und das hat mein Vertrauen in meine englischen Sprachf\u00e4higkeiten gest\u00e4rkt. Ich entdeckte und entwickelte ein Talent f\u00fcr die Videoproduktion und machte mich auch mit einer Reihe von Entwicklungs- und Nicht-Entwicklungs-Tools vertraut.<\/p>\n\n<h2 class=\"wp-block-heading\">Mit der WordPress-Community in Verbindung treten<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/WordCamp-1024x392.jpg\" alt=\"\" class=\"wp-image-6533 lazyload\" width=\"361\" height=\"138\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/WordCamp-1024x392.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/WordCamp-300x114.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/WordCamp-1536x588.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/WordCamp-2048x784.jpg 2048w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/WordCamp.jpg 512w\" data-sizes=\"(max-width: 361px) 100vw, 361px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 361px; --smush-placeholder-aspect-ratio: 361\/138;\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">In genau einem Monat werde ich auf der WC Prague sprechen und wir werden einen Toolset-Tisch haben, an dem meine Kollegen und ich den Teilnehmern die Toolset-Bl\u00f6cke vorstellen werden. Dies ist das 3. gr\u00f6\u00dfte WordCamp in Europa. Hier ist das soeben ver\u00f6ffentlichte kleine Interview mit mir: <a href=\"https:\/\/2020.prague.wordcamp.org\/2020\/01\/29\/dario-jazbec-hrvatin\/\">https:\/\/2020.prague.wordcamp.org\/2020\/01\/29\/dario-jazbec-hrvatin\/<\/a><\/p>\n\n<h2 class=\"wp-block-heading\">Momente, an die man sich bei OnTheGoSystems erinnert<\/h2>\n\n<p class=\"wp-block-paragraph\">Es gab viele aufregende Zeiten in meiner Karriere bei OnTheGoSystems<strong>.<\/strong> Mein Lieblingsprojekt war die k\u00fcrzliche Ver\u00f6ffentlichung von<a href=\"https:\/\/toolset.com\/2019\/11\/toolset-views-becoming-toolset-blocks\/\"> Toolset Blocks<\/a>, weil es ein so tolles Produkt ist. Es ist ein sehr anspruchsvolles Projekt, das noch nicht abgeschlossen ist.<\/p>\n\n<p class=\"wp-block-paragraph\">Dies ist das zweite Mal, dass ich zum Mitarbeiter des Monats gew\u00e4hlt wurde, und beide Male bedeutet mir das sehr viel und macht mich stolz.<\/p>\n\n<p class=\"wp-block-paragraph\">Es hat auch peinliche Momente gegeben. Ich erinnere mich an einen Fall mit unserer lieben Verwaltungsassistentin, als ich ihr in unserer Google+ Community zum Geburtstag gratulierte, ohne zu wissen, dass sie keine Geburtstage feiert. Das war peinlich! :) Aber alles war gut und wurde in guter Stimmung aufgenommen!<\/p>\n\n<h2 class=\"wp-block-heading\">Alles in allem&#8230;<\/h2>\n\n<p class=\"wp-block-paragraph\">Ja, die Arbeit bei OnTheGoSystems ist mehr als eine Karriere. Sie hat mir ein erf\u00fclltes Leben beschert und mir erm\u00f6glicht, fantastische Menschen auf der ganzen Welt kennenzulernen.<\/p>\n\n<p class=\"wp-block-paragraph\">Ein Ratschlag f\u00fcr angehende Kandidaten: Seien Sie Sie selbst und seien Sie ehrlich. Sie sind zu viel mehr f\u00e4hig, als Sie wissen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mein Name ist Dario Jazbec Hrvatin und ich bin f\u00fcr die Dokumentation aller OnTheGoSystems-Projekte zust\u00e4ndig. Hier ist eine kleine Geschichte \u00fcber mich und dar\u00fcber, wie es ist, aus der Ferne zu arbeiten. Ein wenig \u00fcber meinen Hintergrund Ich lebe in Slowenien, zusammen mit meiner Frau, unserer Tochter und dem s\u00fc\u00dfesten kleinen Chihuahua namens Mrfi (wie [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-18898","post","type-post","status-publish","format-standard","hentry","category-treffen-sie-unser-team"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dario Jazbec Hrvatin - f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dario Jazbec Hrvatin - f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Mein Name ist Dario Jazbec Hrvatin und ich bin f\u00fcr die Dokumentation aller OnTheGoSystems-Projekte zust\u00e4ndig. Hier ist eine kleine Geschichte \u00fcber mich und dar\u00fcber, wie es ist, aus der Ferne zu arbeiten. Ein wenig \u00fcber meinen Hintergrund Ich lebe in Slowenien, zusammen mit meiner Frau, unserer Tochter und dem s\u00fc\u00dfesten kleinen Chihuahua namens Mrfi (wie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:28:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-03T07:28:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-768x1024.jpg\" \/>\n<meta name=\"author\" content=\"Helena Petridou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Petridou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/\"},\"author\":{\"name\":\"Helena Petridou\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\"},\"headline\":\"Dario Jazbec Hrvatin &#8211; f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere\",\"datePublished\":\"2024-06-03T07:28:17+00:00\",\"dateModified\":\"2024-06-03T07:28:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/\"},\"wordCount\":793,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Dario_Gloria-3-768x1024.jpg\",\"articleSection\":[\"Treffen Sie unser Team\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/\",\"name\":\"Dario Jazbec Hrvatin - f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Dario_Gloria-3-768x1024.jpg\",\"datePublished\":\"2024-06-03T07:28:17+00:00\",\"dateModified\":\"2024-06-03T07:28:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Dario_Gloria-3-768x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Dario_Gloria-3-768x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2020\\\/02\\\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dario Jazbec Hrvatin &#8211; f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\",\"name\":\"Helena Petridou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"caption\":\"Helena Petridou\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/author\\\/helena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dario Jazbec Hrvatin - f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/","og_locale":"de_DE","og_type":"article","og_title":"Dario Jazbec Hrvatin - f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere - OnTheGoSystems","og_description":"Mein Name ist Dario Jazbec Hrvatin und ich bin f\u00fcr die Dokumentation aller OnTheGoSystems-Projekte zust\u00e4ndig. Hier ist eine kleine Geschichte \u00fcber mich und dar\u00fcber, wie es ist, aus der Ferne zu arbeiten. Ein wenig \u00fcber meinen Hintergrund Ich lebe in Slowenien, zusammen mit meiner Frau, unserer Tochter und dem s\u00fc\u00dfesten kleinen Chihuahua namens Mrfi (wie [&hellip;]","og_url":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:28:17+00:00","article_modified_time":"2024-06-03T07:28:27+00:00","og_image":[{"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-768x1024.jpg","type":"","width":"","height":""}],"author":"Helena Petridou","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Helena Petridou","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/"},"author":{"name":"Helena Petridou","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555"},"headline":"Dario Jazbec Hrvatin &#8211; f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere","datePublished":"2024-06-03T07:28:17+00:00","dateModified":"2024-06-03T07:28:27+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/"},"wordCount":793,"publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-768x1024.jpg","articleSection":["Treffen Sie unser Team"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/","url":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/","name":"Dario Jazbec Hrvatin - f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-768x1024.jpg","datePublished":"2024-06-03T07:28:17+00:00","dateModified":"2024-06-03T07:28:27+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-768x1024.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/02\/Dario_Gloria-3-768x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/de\/2020\/02\/dario-jazbec-hrvatin-fuer-onthegosystems-zu-arbeiten-ist-mehr-als-eine-karriere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/de\/"},{"@type":"ListItem","position":2,"name":"Dario Jazbec Hrvatin &#8211; f\u00fcr OnTheGoSystems zu arbeiten ist mehr als eine Karriere"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/de\/#website","url":"https:\/\/onthegosystems.com\/de\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/de\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555","name":"Helena Petridou","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","caption":"Helena Petridou"},"url":"https:\/\/onthegosystems.com\/de\/author\/helena\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/18898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/comments?post=18898"}],"version-history":[{"count":1,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/18898\/revisions"}],"predecessor-version":[{"id":18900,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/18898\/revisions\/18900"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/media?parent=18898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/categories?post=18898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/tags?post=18898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}