{"id":19243,"date":"2021-03-29T19:51:08","date_gmt":"2024-06-03T07:32:31","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/"},"modified":"2024-06-03T07:32:42","modified_gmt":"2024-06-03T07:32:42","slug":"die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/","title":{"rendered":"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde"},"content":{"rendered":"\n<p><strong>Unser Star des Monats Februar ist <a href=\"https:\/\/onthegosystems.com\/team\/andres-cifuentes\/\">Andres Cifuentes<\/a>! Lesen Sie \u00fcber seinen Weg vom Chemieingenieur in Kolumbien zum Webdesigner in Frankreich und schlie\u00dflich zu einem WPML-Unterst\u00fctzer, der aus der Ferne in Spanien arbeitet.  <\/strong><\/p>\n\n<h2 class=\"wp-block-heading\">Erz\u00e4hlen Sie uns ein wenig \u00fcber sich!<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/05\/andres-cifuentes-wpcf_190x190.jpg\" alt=\"\" class=\"wp-image-2110 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/05\/andres-cifuentes-wpcf_190x190.jpg 190w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/05\/andres-cifuentes-wpcf_190x190-150x150.jpg 150w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;\" \/><\/figure>\n<\/div>\n<p><br\/>Ich komme aus Kolumbien. Ich habe einen Abschluss als Chemieingenieur und habe einige Jahre in einem gro\u00dfen Pharmaunternehmen gearbeitet. Mit diesem Job konnte ich etwas Geld verdienen, aber ich wollte etwas anderes machen. Als der Moment kam, nahm ich ein Sabbatical und zog nach Frankreich, um Franz\u00f6sisch zu lernen.<\/p>\n\n<p>Da ich in der Vergangenheit bereits mit <em>Flash<\/em> gearbeitet habe, habe ich mich nach einem Web-Major umgesehen. In dem Moment, als ich anfing, wusste ich, dass ich mein Leben \u00e4ndern wollte, also absolvierte ich ein 2-Jahres-Programm und arbeitete anschlie\u00dfend einige Jahre in einer Webagentur.<\/p>\n\n<p>Nach 5 Jahren in Frankreich war es an der Zeit, weiterzuziehen und nach langem \u00dcberlegen fiel die Wahl auf Spanien. Es war ein bisschen be\u00e4ngstigend wegen des wirtschaftlichen Moments, aber es endete gro\u00dfartig.  <\/p>\n\n<h2 class=\"wp-block-heading\">Haben Sie irgendwelche Haustiere oder Hobbys?<\/h2>\n\n<p>Wenn Sie schon einmal einen Videoanruf mit mir gef\u00fchrt haben, wissen Sie \u00fcber meine Haustiere und Hobbys Bescheid! Ich habe 3 Katzen: Candela, Plugin und Ninja. Ich habe bereits akzeptiert, dass ich <em>die alte verr\u00fcckte Katzenlady der Simpsons<\/em> bin <em>.<\/em> Ich schw\u00f6re, wenn ich arbeite, ignorieren sie mich einfach, aber sobald ich in einem Videoanruf bin, fangen sie an, vor der Kamera vorbeizugehen oder \u00fcber die Tastatur zu laufen, ich bin sicher, sie wissen, was sie tun.  <\/p>\n\n<p>Was mein Hobby angeht, k\u00f6nnen Sie auch mein Fahrrad hinter mir sehen. Ich versuche, zweimal pro Woche damit zu fahren, aber einer meiner Vors\u00e4tze f\u00fcr dieses Jahr ist, mich mehr anzustrengen und l\u00e4ngere Strecken zu fahren. Mit all den COVID-Einschr\u00e4nkungen war das nicht m\u00f6glich, aber es steht immer noch auf meiner <em>To-Do-Liste.<\/em><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2021\/03\/my-cats-768x1024.jpg\" alt=\"\" class=\"wp-image-11923 lazyload\" width=\"674\" height=\"897\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 674px; --smush-placeholder-aspect-ratio: 674\/897;\" \/><figcaption class=\"wp-element-caption\">Meine Katzen<\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\">Wie haben Sie von OntheGoSystems erfahren?<\/h2>\n\n<p><br\/>Als wir das erste Mal nach Spanien kamen, war ich mir nicht sicher, ob es f\u00fcr ein paar Wochen oder Monate sein w\u00fcrde. Es war eine wirtschaftlich schwierige Zeit hier und es war nicht einfach, einen Job zu finden. Aber ich hatte Gl\u00fcck, ich habe OTGS gefunden.<br\/><br\/>Zu diesem Zeitpunkt suchte ich angesichts der Umst\u00e4nde nach einem Fernarbeitsplatz und habe mich bereits bei OTGS beworben. Ich war neu in der Stadt und besuchte regelm\u00e4\u00dfig WP Meetups, weil ich Leute kennenlernen wollte. Zu meinem Gl\u00fcck gab es ein Treffen, das von Amit pr\u00e4sentiert wurde. Ich habe es als ein Zeichen verstanden!  <\/p>\n\n<p><br\/>Ich folgte dem Prozess und nach ein paar Wochen begann ich zu arbeiten. Und hier bin ich nun, fast 6 Jahre sp\u00e4ter.<br\/><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2021\/03\/me-768x1024.jpg\" alt=\"\" class=\"wp-image-11914 lazyload\" width=\"678\" height=\"901\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 678px; --smush-placeholder-aspect-ratio: 678\/901;\" \/><figcaption class=\"wp-element-caption\">Ich<\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\">Wie sieht ein typischer Tag aus, an dem Sie aus der Ferne arbeiten?<\/h2>\n\n<p>Derzeit \u00e4ndert sich mein Zeitplan wegen COVID stark. Da sich die \u00f6rtlichen Beschr\u00e4nkungen fast alle 2 Wochen \u00e4ndern, habe ich gesehen, wie ich mich st\u00e4ndig an die neuen Bedingungen angepasst habe. Das ist eines der Dinge, die ich an meiner Arbeit liebe.<\/p>\n\n<p>Ich wache gerne fr\u00fch auf, also sitze ich gegen 7 Uhr morgens mit einer gro\u00dfen Tasse guten Kaffees vor dem Computer. Da ich f\u00fcr das franz\u00f6sische Forum zust\u00e4ndig bin, nehme ich alle verf\u00fcgbaren franz\u00f6sischen Tickets und je nach Auslastung auch die Tickets aus dem spanischen oder englischen Forum.  <\/p>\n\n<p>Wenn ich alle E-Mails vom Vortag beantwortet und meine Warteschlange geleert habe, habe ich mir ein gutes Fr\u00fchst\u00fcck verdient, also mache ich eine Pause.  <\/p>\n\n<p>Sobald ich zur\u00fcck bin, pr\u00fcfe ich, ob es etwas Dringendes gibt. Andernfalls gehe ich zu meinem Mentor <a href=\"https:\/\/onthegosystems.com\/team\/otto-wald\/\">Otto<\/a> und pr\u00fcfe, ob wir etwas in der Kompatibilit\u00e4ts-Warteschlange bearbeiten k\u00f6nnen. Das ist etwas, das mir sehr viel Spa\u00df macht. Es ist eine Herausforderung, aber ich habe einen guten Mentor mit viel Geduld. Normalerweise beenden wir unsere Sitzung vor dem Mittagessen.<\/p>\n\n<p>Wenn ich zur\u00fcck bin, pr\u00fcfe ich noch einmal den Stand der Warteschlange und je nachdem gehe ich ins Forum oder stehe f\u00fcr Chats zur Verf\u00fcgung, bis ich meinen Tag beendet habe.<\/p>\n\n<p>Dann ist es Zeit f\u00fcr etwas Bewegung, also nehme ich mein Fahrrad und fahre in einen Park am Fluss. Ich mache kurze Ausritte (10 km), aber ich versuche, sie so hart wie m\u00f6glich zu machen.  <\/p>\n\n<p>Im Rahmen meines <a href=\"https:\/\/onthegosystems.com\/2020\/09\/happy-and-healthy-people-behind-wpml-and-toolset-plugins-part-iii\/\">Stipendiums<\/a> belege ich einige Kurse \u00fcber Javascript. Abends versuche ich, etwa 45 Minuten zu lernen und dann ein wenig zu lesen oder mit meinen Katzen zu spielen.<\/p>\n\n<h2 class=\"wp-block-heading\">Was ist Ihrer Erfahrung nach das Beste und das Schlimmste an der Arbeit aus der Ferne?<\/h2>\n\n<p>Eines der Dinge, die ich an der Arbeit aus der Ferne am meisten mag, ist die M\u00f6glichkeit zu reisen. Ich hatte die Gelegenheit, Europa zu bereisen, aber vor allem habe ich mehrere Monate mit meiner Familie in Kolumbien verbracht. Das w\u00e4re mit einem herk\u00f6mmlichen Job unm\u00f6glich gewesen.<\/p>\n\n<p>Heutzutage ist es nicht das beste Szenario zu reisen, aber COVID zeigt uns, wie wichtig die Arbeit aus der Ferne ist, und w\u00e4hrend es f\u00fcr einen gro\u00dfen Teil der Bev\u00f6lkerung ein Novum war und viele Herausforderungen mit sich brachte, war es f\u00fcr uns<em> einfach ein weiterer Tag im B\u00fcro<\/em>:)<\/p>\n\n<p>Die gr\u00f6\u00dfte Herausforderung f\u00fcr mich war es zu lernen, aus der Arbeit herauszukommen. Es ist leicht, den ganzen Tag in Verbindung zu bleiben, denn die Technologie hat es uns leicht gemacht, E-Mails und Benachrichtigungen zu erhalten. Ich glaube jedoch, dass wir, um produktiver zu werden, eine Auszeit brauchen, andere Aktivit\u00e4ten unternehmen und Zeit mit unserer Familie und unseren Freunden verbringen sollten.  <\/p>\n\n<h2 class=\"wp-block-heading\">Was sind Ihre Hoffnungen und Pl\u00e4ne f\u00fcr die Zukunft?<\/h2>\n\n<p>Mein Vorhaben f\u00fcr dieses Jahr ist es, technisch st\u00e4rker zu werden. Ich habe mein <a href=\"https:\/\/onthegosystems.com\/2020\/09\/happy-and-healthy-people-behind-wpml-and-toolset-plugins-part-iii\/\">Stipendium<\/a> in einer Online-Akademie genutzt und nehme an einem Trainingskurs bei Otto teil. Im Moment lerne ich sehr viel. Manchmal ist es schwer und frustrierend, aber wenn man dann eine L\u00f6sung gefunden hat, ist es sehr lohnend. Warten wir das Ergebnis bis Ende des Jahres ab und dr\u00fccken wir die Daumen!  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser Star des Monats Februar ist Andres Cifuentes! Lesen Sie \u00fcber seinen Weg vom Chemieingenieur in Kolumbien zum Webdesigner in Frankreich und schlie\u00dflich zu einem WPML-Unterst\u00fctzer, der aus der Ferne in Spanien arbeitet. Erz\u00e4hlen Sie uns ein wenig \u00fcber sich! Ich komme aus Kolumbien. Ich habe einen Abschluss als Chemieingenieur und habe einige Jahre in [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":19246,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[149,151],"tags":[],"class_list":["post-19243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeit-und-geschichten","category-treffen-sie-unser-team"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Unser Star des Monats Februar ist Andres Cifuentes! Lesen Sie \u00fcber seinen Weg vom Chemieingenieur in Kolumbien zum Webdesigner in Frankreich und schlie\u00dflich zu einem WPML-Unterst\u00fctzer, der aus der Ferne in Spanien arbeitet. Erz\u00e4hlen Sie uns ein wenig \u00fcber sich! Ich komme aus Kolumbien. Ich habe einen Abschluss als Chemieingenieur und habe einige Jahre in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:32:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-03T07:32:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2021\/03\/me-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1242\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dario Jazbec Hrvatin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dario Jazbec Hrvatin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/\"},\"author\":{\"name\":\"Dario Jazbec Hrvatin\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/b1f055ef760205c01fbe3c4abd79f5fa\"},\"headline\":\"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde\",\"datePublished\":\"2024-06-03T07:32:31+00:00\",\"dateModified\":\"2024-06-03T07:32:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/\"},\"wordCount\":1032,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/me-2.jpg\",\"articleSection\":[\"Arbeit und Geschichten\",\"Treffen Sie unser Team\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/\",\"name\":\"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/me-2.jpg\",\"datePublished\":\"2024-06-03T07:32:31+00:00\",\"dateModified\":\"2024-06-03T07:32:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/me-2.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/me-2.jpg\",\"width\":1200,\"height\":1242},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2021\\\/03\\\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/b1f055ef760205c01fbe3c4abd79f5fa\",\"name\":\"Dario Jazbec Hrvatin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g\",\"caption\":\"Dario Jazbec Hrvatin\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/author\\\/dario-h\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/","og_locale":"de_DE","og_type":"article","og_title":"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde - OnTheGoSystems","og_description":"Unser Star des Monats Februar ist Andres Cifuentes! Lesen Sie \u00fcber seinen Weg vom Chemieingenieur in Kolumbien zum Webdesigner in Frankreich und schlie\u00dflich zu einem WPML-Unterst\u00fctzer, der aus der Ferne in Spanien arbeitet. Erz\u00e4hlen Sie uns ein wenig \u00fcber sich! Ich komme aus Kolumbien. Ich habe einen Abschluss als Chemieingenieur und habe einige Jahre in [&hellip;]","og_url":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:32:31+00:00","article_modified_time":"2024-06-03T07:32:42+00:00","og_image":[{"width":1200,"height":1242,"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2021\/03\/me-2.jpg","type":"image\/jpeg"}],"author":"Dario Jazbec Hrvatin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dario Jazbec Hrvatin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/"},"author":{"name":"Dario Jazbec Hrvatin","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/b1f055ef760205c01fbe3c4abd79f5fa"},"headline":"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde","datePublished":"2024-06-03T07:32:31+00:00","dateModified":"2024-06-03T07:32:42+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/"},"wordCount":1032,"publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2021\/03\/me-2.jpg","articleSection":["Arbeit und Geschichten","Treffen Sie unser Team"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/","url":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/","name":"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2021\/03\/me-2.jpg","datePublished":"2024-06-03T07:32:31+00:00","dateModified":"2024-06-03T07:32:42+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2021\/03\/me-2.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2021\/03\/me-2.jpg","width":1200,"height":1242},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/de\/2021\/03\/die-zeichen-lesen-wie-ein-wordpress-treffen-zu-einer-karriere-fuer-andres-cifuentes-wurde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die Zeichen lesen: Wie ein WordPress-Treffen zu einer Karriere f\u00fcr Andres Cifuentes wurde"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/de\/#website","url":"https:\/\/onthegosystems.com\/de\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/de\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/b1f055ef760205c01fbe3c4abd79f5fa","name":"Dario Jazbec Hrvatin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g","caption":"Dario Jazbec Hrvatin"},"url":"https:\/\/onthegosystems.com\/de\/author\/dario-h\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/19243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/comments?post=19243"}],"version-history":[{"count":1,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/19243\/revisions"}],"predecessor-version":[{"id":19249,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/19243\/revisions\/19249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/media\/19246"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/media?parent=19243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/categories?post=19243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/tags?post=19243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}