{"id":20242,"date":"2017-02-20T10:28:01","date_gmt":"2024-06-03T07:38:21","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/vincenzo-carrubba\/"},"modified":"2024-06-03T07:38:21","modified_gmt":"2024-06-03T07:38:21","slug":"vincenzo-carrubba","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/","title":{"rendered":"Vincenzo Carrubba"},"content":{"rendered":"<h2>Von den Spezialkr\u00e4ften zur OTGS<\/h2>\n<p>Vincenzo Carrubba: &#8222;Die Arbeit im WPML-Support ist eine anspruchsvolle und sich st\u00e4ndig ver\u00e4ndernde Erfahrung.&#8220;<\/p>\n<h2>Vincenzo, Sie sind im M\u00e4rz 2015 zur OTGS gekommen. Welche Art von Arbeit machen Sie genau?<\/h2>\n<figure id=\"attachment_3668\" aria-describedby=\"caption-attachment-3668\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Vincenzo.jpg\"><img decoding=\"async\" class=\"wp-image-3668 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Vincenzo-300x200.jpg\" width=\"300\" height=\"200\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\"><\/a><figcaption id=\"caption-attachment-3668\" class=\"wp-caption-text\">Vincenzo<\/figcaption><\/figure>\n<p>Im Jahr 2014 erhielt ich eine E-Mail von OTGS \u00fcber einen Supporter-Job f\u00fcr das italienische Forum. Diese Aufgabe erfordert eine gro\u00dfe Leidenschaft f\u00fcr die L\u00f6sung von Problemen und f\u00fcr die Hilfe f\u00fcr Menschen. Nat\u00fcrlich sind Kenntnisse in CSS, PHP und Javascript unabdingbar, aber Sie m\u00fcssen sich auch st\u00e4ndig \u00fcber die neuesten Entwicklungen bei WordPress und WPML informieren. Eine gute Kenntnis des WordPress Codex kann sehr hilfreich sein.<\/p>\n<p>Die Arbeit im WPML-Support ist eine herausfordernde und sich st\u00e4ndig ver\u00e4ndernde Erfahrung, aber sie ist auch sehr lohnend. Wir versuchen, alle in unseren Support-Foren ge\u00f6ffneten Anfragen zu l\u00f6sen und zu beantworten. Manchmal m\u00fcssen Sie seltsame Probleme mit komplizierten WordPress-Installationen l\u00f6sen.<\/p>\n<h2>Das klingt sehr entmutigend und herausfordernd<\/h2>\n<figure id=\"attachment_3670\" aria-describedby=\"caption-attachment-3670\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/work-station.jpg\"><img decoding=\"async\" class=\"wp-image-3670 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/work-station-300x200.jpg\" width=\"300\" height=\"200\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\"><\/a><figcaption id=\"caption-attachment-3670\" class=\"wp-caption-text\">Arbeiten im Support-Forum<\/figcaption><\/figure>\n<p>Hier kommt die gr\u00fcndliche Schulung durch die OTGS zum Tragen. Es ist nicht so \u00fcberw\u00e4ltigend, wenn man Schritt f\u00fcr Schritt vorgeht. Wie Denise, meine Trainerin, mir beigebracht hat, beginne ich immer damit, die Beschreibung des Problems des Kunden zu lesen. Dann werfe ich einen kurzen Blick auf die Debug-Informationen, um nach allgemeinen Problemen zu suchen (z.B. veraltete oder inkompatible Themes und Plugins). Danach gehe ich zur\u00fcck und lese das gesamte Ticket noch einmal, beginnend mit dem Titel. Manchmal sagt der Titel mehr aus als die Beschreibung. Bei Bedarf suche ich schnell nach \u00e4hnlichen Themen. Dies reicht in der Regel f\u00fcr eine erste Antwort aus.<\/p>\n<p>Es ist ein wirklich lohnender Job, besonders wenn Sie gerne Menschen helfen. Es ist toll, wenn der Kunde dankbar antwortet, weil Sie ihm geholfen haben. Ich versuche immer daran zu denken, dass hinter den Tickets Menschen stehen, die Probleme haben und mich um Hilfe bitten.<\/p>\n<h2>Aus welcher Gegend Italiens kommen Sie? Was w\u00fcrden Sie uns gerne \u00fcber Ihre Heimatstadt erz\u00e4hlen?<\/h2>\n<figure id=\"attachment_3672\" aria-describedby=\"caption-attachment-3672\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/siracusa-1.jpg\"><img decoding=\"async\" class=\"wp-image-3672 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/siracusa-1-300x200.jpg\" width=\"300\" height=\"200\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\"><\/a><figcaption id=\"caption-attachment-3672\" class=\"wp-caption-text\">Siracusa<\/figcaption><\/figure>\n<p>Ich lebe in Siracusa auf Sizilien, einer Stadt, die von griechischen Kolonisten aus Korinth im 8. Jahrhundert v. Chr. gegr\u00fcndet wurde. Der Mathematiker Archimedes wurde hier im 3. Jahrhundert v. Chr. geboren. Siracusa hat eine reiche Geschichte. Nach der engen Verbindung mit dem antiken Griechenland wurde Sizilien von Rom, den Byzantinern, arabischen Muslimen und im Mittelalter von verschiedenen siegreichen Kreuzfahrern regiert. Schlie\u00dflich wurde das Haus der Bourbonen gest\u00fcrzt und der Weg f\u00fcr die Einigung Italiens im Jahr 1865 geebnet.<\/p>\n<p>Seit 2005 geh\u00f6rt die gesamte Stadt Syrakus zusammen mit der Nekropole von Pantalica in der Provinz Syrakus zum Weltkulturerbe der UNESCO. Syrakus wurde ausgew\u00e4hlt, weil &#8222;die Denkm\u00e4ler und arch\u00e4ologischen St\u00e4tten in Syrakus die besten Beispiele f\u00fcr herausragendes architektonisches Schaffen sind, das mehrere kulturelle Aspekte umfasst: griechisch, r\u00f6misch und barock&#8220;. Das antike Syrakus war &#8222;direkt mit Ereignissen, Ideen und literarischen Werken von herausragender universeller Bedeutung verbunden&#8220;. Zu einem Besuch in Siracusa geh\u00f6rt unbedingt ein Ausflug zum \u00c4tna, der nur 1 \u00bd Autostunden n\u00f6rdlich liegt. Der \u00c4tna ist einer der aktivsten Vulkane der Welt und befindet sich in einem fast st\u00e4ndigen Zustand der Aktivit\u00e4t.<a href=\"https:\/\/en.wikipedia.org\/wiki\/Sicily\">  https:\/\/en.wikipedia.org\/wiki\/Sicily<\/a><\/p>\n<h2>Bevor Sie zu OTGS kamen, was f\u00fcr eine Art von Arbeit haben Sie da gemacht?<\/h2>\n<figure id=\"attachment_3674\" aria-describedby=\"caption-attachment-3674\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/siracusa-4.jpg\"><img decoding=\"async\" class=\"wp-image-3674 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/siracusa-4-300x169.jpg\" width=\"300\" height=\"169\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/169;\"><\/a><figcaption id=\"caption-attachment-3674\" class=\"wp-caption-text\">Siracusa am Meer<\/figcaption><\/figure>\n<p>Mein ganzes Leben lang habe ich versucht, meine Leidenschaften in Arbeit umzusetzen. Schon als Kind begeisterte ich mich f\u00fcr Informationstechnologie, Fotografie und die Special Forces. Vor etwa 25 Jahren habe ich mit Spezialeinheiten verschiedener Nationen trainiert und f\u00fcr die UNO gearbeitet, um Menschen in Not in Kriegsgebieten zu helfen. Ich habe etwa ein Jahr lang in den italienischen Spezialeinheiten (Luftlandetruppen) gedient und wurde w\u00e4hrend dieser Zeit f\u00fcr ein paar Monate in Somalia eingesetzt. Nach dieser Erfahrung setzte ich meine Ausbildung mit Fallschirmspringen und Ger\u00e4tetauchen fort und arbeitete eine Zeit lang f\u00fcr ein Unterwasserbauunternehmen. Sp\u00e4ter arbeitete ich haupts\u00e4chlich im IT-Bereich als Netzwerk- und UNIX-Systemadministrator bei verschiedenen Internetfirmen und sogar als Hochzeitsfotograf f\u00fcr ein Studio in Catania. In dieser Zeit habe ich auch ihre Website mit WordPress und WPML erstellt.<\/p>\n<h2>Beschreiben Sie einen typischen Arbeitstag<\/h2>\n<figure id=\"attachment_3676\" aria-describedby=\"caption-attachment-3676\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Italian-breakfast.jpg\"><img decoding=\"async\" class=\"wp-image-3676 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Italian-breakfast-300x200.jpg\" width=\"300\" height=\"200\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\"><\/a><figcaption id=\"caption-attachment-3676\" class=\"wp-caption-text\">Typisch italienisches Fr\u00fchst\u00fcck<\/figcaption><\/figure>\n<p>Eines der besten Dinge an der Arbeit bei OTGS ist, dass Sie von zu Hause aus arbeiten k\u00f6nnen oder von wo auch immer Sie wollen. Das habe ich mir immer vorgestellt, als ich ein Kind war und an die Zukunft dachte. Nat\u00fcrlich m\u00fcssen Sie selbstdiszipliniert und ehrlich sein, aber wenn Sie lieben, was Sie tun, ist das eine leichte Aufgabe.<\/p>\n<p>Ich beginne meinen Tag mit einem italienischen Fr\u00fchst\u00fcck. Dies ist meine bevorzugte Mahlzeit des Tages. Der Gedanke an einen Cappuccino und ein Geb\u00e4ck mit Ricotta kann mich wirklich aus dem Bett rei\u00dfen! Ich schalte meinen Laptop mit den beiden externen Monitoren ein und nachdem ich meine Freunde begr\u00fc\u00dft habe, gehe ich meine E-Mails durch, um nach dringenden Angelegenheiten zu suchen. Dann st\u00fcrze ich mich in meine Warteschlange und versuche, so viele Probleme wie m\u00f6glich zu l\u00f6sen.<\/p>\n<p>Wenn ich merke, dass meine Konzentration nachl\u00e4sst, \u00f6ffne ich Spotify und starte meine bevorzugte Wiedergabeliste &#8211; &#8222;Late Night Jazz&#8220;.<\/p>\n<p>Jazz ist nicht meine Art von Musik, aber ich habe das Gef\u00fchl, dass es f\u00fcr mich die beste Musik ist, wenn ich arbeite, weil sie einfach leise im Hintergrund spielt. All meine ablenkenden Gedanken verlassen mich und ich kann mich auf die anstehende Aufgabe konzentrieren.<\/p>\n<p>Ein guter italienischer Kaffee hilft mir, den richtigen Rhythmus zu finden!<\/p>\n<p>Wenn m\u00f6glich, behalte ich auch am Ende des Tages unsere Support-Slack-Gruppe im Auge, falls ein Kollege Hilfe bei einem Problem ben\u00f6tigt oder einen netten Witz erz\u00e4hlen m\u00f6chte.<\/p>\n<h2>Sie arbeiten zwar hart, aber ich bin sicher, dass Sie auch Zeit zum Entspannen finden. Welche Aktivit\u00e4ten machen Ihnen Spa\u00df?<\/h2>\n<figure id=\"attachment_3678\" aria-describedby=\"caption-attachment-3678\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/vincenzo-01.jpg\"><img decoding=\"async\" class=\"wp-image-3678 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/vincenzo-01-300x200.jpg\" width=\"300\" height=\"200\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\"><\/a><figcaption id=\"caption-attachment-3678\" class=\"wp-caption-text\">Vincenzo ist leidenschaftlicher Fotograf<\/figcaption><\/figure>\n<p>Sobald ich meinen Arbeitstag beendet habe, entspanne ich mich mit einem sch\u00f6nen &#8222;Lesesoundtrack&#8220; (Musik, die nicht vom Lesen ablenkt) und beginne meine Bibel zu lesen. Ich habe das Gef\u00fchl, dass die Anweisungen, die ich auf diesen Seiten finde, meine Pers\u00f6nlichkeit verbessert und mich meinem Sch\u00f6pfer n\u00e4her gebracht haben. Da mein Job ein &#8222;sitzender&#8220; Job ist, versuche ich, mich jeden Tag in irgendeiner Form k\u00f6rperlich zu bet\u00e4tigen. Ich liebe es, Menschen und Orte zu fotografieren, vor allem an Wochenenden, aber am liebsten fotografiere ich Portr\u00e4ts.<\/p>\n<h2 class=\"clear\">Wie sehen Sie Ihre Zukunft?<\/h2>\n<p>In der Zukunft? Ich w\u00fcrde gerne weiter mit WordPress arbeiten, weil ich die Community rund um WordPress liebe. Ich werde mein Wissen und meine F\u00e4higkeiten weiter ausbauen, um OTGS, dem Unternehmen, das mir zur Seite stand, als ich es am meisten brauchte, etwas Substanzielles zur\u00fcckgeben zu k\u00f6nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von den Spezialkr\u00e4ften zur OTGS Vincenzo Carrubba: &#8222;Die Arbeit im WPML-Support ist eine anspruchsvolle und sich st\u00e4ndig ver\u00e4ndernde Erfahrung.&#8220; Vincenzo, Sie sind im M\u00e4rz 2015 zur OTGS gekommen. Welche Art von Arbeit machen Sie genau? Im Jahr 2014 erhielt ich eine E-Mail von OTGS \u00fcber einen Supporter-Job f\u00fcr das italienische Forum. Diese Aufgabe erfordert eine [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-20242","post","type-post","status-publish","format-standard","hentry","category-treffen-sie-unser-team"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vincenzo Carrubba - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vincenzo Carrubba - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Von den Spezialkr\u00e4ften zur OTGS Vincenzo Carrubba: &#8222;Die Arbeit im WPML-Support ist eine anspruchsvolle und sich st\u00e4ndig ver\u00e4ndernde Erfahrung.&#8220; Vincenzo, Sie sind im M\u00e4rz 2015 zur OTGS gekommen. Welche Art von Arbeit machen Sie genau? Im Jahr 2014 erhielt ich eine E-Mail von OTGS \u00fcber einen Supporter-Job f\u00fcr das italienische Forum. Diese Aufgabe erfordert eine [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:38:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Vincenzo-300x200.jpg\" \/>\n<meta name=\"author\" content=\"Helena Petridou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Petridou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/\"},\"author\":{\"name\":\"Helena Petridou\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\"},\"headline\":\"Vincenzo Carrubba\",\"datePublished\":\"2024-06-03T07:38:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/\"},\"wordCount\":1176,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Vincenzo-300x200.jpg\",\"articleSection\":[\"Treffen Sie unser Team\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/\",\"name\":\"Vincenzo Carrubba - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Vincenzo-300x200.jpg\",\"datePublished\":\"2024-06-03T07:38:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Vincenzo-300x200.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Vincenzo-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2017\\\/02\\\/vincenzo-carrubba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vincenzo Carrubba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\",\"name\":\"Helena Petridou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"caption\":\"Helena Petridou\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/author\\\/helena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vincenzo Carrubba - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/","og_locale":"de_DE","og_type":"article","og_title":"Vincenzo Carrubba - OnTheGoSystems","og_description":"Von den Spezialkr\u00e4ften zur OTGS Vincenzo Carrubba: &#8222;Die Arbeit im WPML-Support ist eine anspruchsvolle und sich st\u00e4ndig ver\u00e4ndernde Erfahrung.&#8220; Vincenzo, Sie sind im M\u00e4rz 2015 zur OTGS gekommen. Welche Art von Arbeit machen Sie genau? Im Jahr 2014 erhielt ich eine E-Mail von OTGS \u00fcber einen Supporter-Job f\u00fcr das italienische Forum. Diese Aufgabe erfordert eine [&hellip;]","og_url":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:38:21+00:00","og_image":[{"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Vincenzo-300x200.jpg","type":"","width":"","height":""}],"author":"Helena Petridou","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Helena Petridou","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/"},"author":{"name":"Helena Petridou","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555"},"headline":"Vincenzo Carrubba","datePublished":"2024-06-03T07:38:21+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/"},"wordCount":1176,"publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Vincenzo-300x200.jpg","articleSection":["Treffen Sie unser Team"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/","url":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/","name":"Vincenzo Carrubba - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Vincenzo-300x200.jpg","datePublished":"2024-06-03T07:38:21+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Vincenzo-300x200.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/02\/Vincenzo-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/de\/2017\/02\/vincenzo-carrubba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/de\/"},{"@type":"ListItem","position":2,"name":"Vincenzo Carrubba"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/de\/#website","url":"https:\/\/onthegosystems.com\/de\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/de\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555","name":"Helena Petridou","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","caption":"Helena Petridou"},"url":"https:\/\/onthegosystems.com\/de\/author\/helena\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/20242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/comments?post=20242"}],"version-history":[{"count":0,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/20242\/revisions"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/media?parent=20242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/categories?post=20242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/tags?post=20242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}