{"id":25930,"date":"2015-10-30T11:36:05","date_gmt":"2015-10-30T11:36:05","guid":{"rendered":"https:\/\/onthegosystems.com\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/"},"modified":"2015-10-30T11:36:05","modified_gmt":"2015-10-30T11:36:05","slug":"konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/","title":{"rendered":"Konrad Karpieszuk &#8211; ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet"},"content":{"rendered":"<p><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/DSCN4360.jpg\" rel=\"attachment wp-att-2453\"><img decoding=\"async\" class=\"alignleft wp-image-2453 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/DSCN4360-300x224.jpg\" alt=\"Vermittlung von Computerkenntnissen in Ruanda (nicht genau in dem Moment, als das Foto aufgenommen wurde) ;)\" width=\"300\" height=\"224\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/224;\"><\/a><\/p>\n<p>Konrad ist ein zur\u00fcckhaltender Mann aus Polen. Sie w\u00e4ren \u00fcberrascht, wie reich an Erfahrungen sein Leben ist. Er arbeitete als WordPress-Freiberufler, war zweimal WordCamp-Redner, reiste sogar nach Ruanda, Afrika, um den dortigen Studenten Computerunterricht zu erteilen, um schlie\u00dflich als WordPress-Entwickler bei OnTheGoSystems zu landen.  <\/p>\n<p class=\"clearfix\">Heute erz\u00e4hlt er uns mehr \u00fcber sein Privatleben und seine Arbeit im WPML-Kompatibilit\u00e4tsprojekt.<\/p>\n<h2>Wo genau leben Sie, Konrad?<\/h2>\n<figure id=\"attachment_2484\" aria-describedby=\"caption-attachment-2484\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-poland.jpg\" rel=\"attachment wp-att-2484\"><img decoding=\"async\" class=\"wp-image-2484 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-poland-300x200.jpg\" alt=\"Bia\u0142owie\u017ca-Urwald, Polen, Bilder von Bigul Malayi\" width=\"300\" height=\"200\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-poland-300x200.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-poland-1024x683.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-poland.jpg 1138w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" \/><\/a><figcaption id=\"caption-attachment-2484\" class=\"wp-caption-text\">Bia\u0142owie\u017ca-Urwald, Polen, Bilder von Bigul Malayi<\/figcaption><\/figure>\n<p>Ich lebe in einer mittelgro\u00dfen Stadt mit 270.000 Einwohnern namens Bialystok. Obwohl meine Familie und ich in einem Mehrfamilienhaus wohnen, gef\u00e4llt es mir sehr gut, da es direkt am Stadtrand von Bialystok liegt. Die Menschen kommen in diese Region, nicht so sehr wegen der Stadt, sondern um die nat\u00fcrliche Umgebung zu erkunden.  <\/p>\n<p>Der wundersch\u00f6ne Bialowieza-Urwald ist einer der letzten verbliebenen Teile eines riesigen Urwaldes, der sich einst \u00fcber die europ\u00e4ische Ebene erstreckte.<\/p>\n<p>Dieser Wald ist die Heimat umherziehender Herden des europ\u00e4ischen Wisents. Dieses beeindruckende Tier war fast ausgestorben, aber dank sorgf\u00e4ltiger Erhaltung und Zucht konnten wir den Wisent in andere W\u00e4lder &#8218;exportieren&#8216;. Einige der anderen Arten, die den Wald bewohnen, sind Elche, W\u00f6lfe, Rot- und Rehe, Luchse und Wildschweine. Auch seltene V\u00f6gel haben hier ihr Zuhause &#8211; der Wanderfalke, der Wei\u00dfstorch und der Seeadler.   <\/p>\n<figure id=\"attachment_2485\" aria-describedby=\"caption-attachment-2485\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-forest-poland.jpg\" rel=\"attachment wp-att-2485\"><img decoding=\"async\" class=\"wp-image-2485 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-forest-poland-300x200.jpg\" alt=\"Bia\u0142owie\u017ca-Urwald, Polen, Bilder von Bigul Malayi\" width=\"300\" height=\"200\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-forest-poland-300x200.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-forest-poland-1024x683.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/bialowieza-forest-poland.jpg 1138w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" \/><\/a><figcaption id=\"caption-attachment-2485\" class=\"wp-caption-text\">Bia\u0142owie\u017ca-Urwald, Polen, Bilder von Bigul Malayi<\/figcaption><\/figure>\n<p class=\"clearfix\">Unsere Region ist auch f\u00fcr die gr\u00f6\u00dften Feuchtgebiete Europas bekannt &#8211; 150 km lang und an manchen Stellen 15-50 km breit. Der ungez\u00e4hmte, m\u00e4andrierende Fluss Biebrza ist ein lebendiger Fluss, der im Fr\u00fchjahr \u00fcber die Ufer tritt und gro\u00dfe Wiesen in Seen verwandelt. Die au\u00dfergew\u00f6hnliche Sch\u00f6nheit der Gegend bleibt weitgehend ungest\u00f6rt und ist daher ein erstaunliches Tor f\u00fcr Naturliebhaber, die nach neuen Erfahrungen suchen.  <\/p>\n<h2>Das Familienleben ist Ihnen sehr wichtig&#8230;<\/h2>\n<figure id=\"attachment_2449\" aria-describedby=\"caption-attachment-2449\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/640.jpg\" rel=\"attachment wp-att-2449\"><img decoding=\"async\" class=\"size-medium wp-image-2449 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/640-300x200.jpg\" alt=\"Konrads Fotosession nach der Hochzeit\" width=\"300\" height=\"200\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\"><\/a><figcaption id=\"caption-attachment-2449\" class=\"wp-caption-text\">Konrads Fotosession nach der Hochzeit<\/figcaption><\/figure>\n<p>Das ist es auf jeden Fall. Meine Frau Monika und ich genie\u00dfen jeden Tag mit unserer Tochter Laura. Es ist, als w\u00e4re sie gestern geboren worden, und schon ist sie 6 Monate alt. Laura hat unser Leben wirklich erf\u00fcllt &#8211; und auch ver\u00e4ndert! Ich bin fr\u00fcher viel Fahrrad gefahren, aber seit unser Baby geboren wurde, nicht mehr so oft. Wir haben auch einen Hund &#8211; teils Deutscher Sch\u00e4ferhund, teils Wolf. Sie beh\u00e4lt etwas von der nat\u00fcrlichen Nervosit\u00e4t des Wilden bei und ist sehr vorsichtig, wenn sie etwas Neues sieht, zum Beispiel auf dem B\u00fcrgersteig vor dem Haus, wo sie sich weigert, das Geb\u00e4ude zu verlassen. Sie f\u00fchlt sich im Wald zu Hause, wo ich dreimal t\u00e4glich mit ihr spazieren gehe und sie ohne Leine frei laufen kann.       <\/p>\n<h2 class=\"clear\">Sie m\u00fcssen diese nat\u00fcrliche Umgebung sehr genie\u00dfen. Was machen Sie sonst noch gerne? <\/h2>\n<p>W\u00fcrden Sie es glauben, dass ich es tats\u00e4chlich genie\u00dfe, technische Dokumentationen zu lesen und neue technische Sprachen zu lernen? Nat\u00fcrlich schaue ich auch gerne Dokumentarfilme, besonders wenn sie historisch oder \u00fcber den Kosmos sind. <\/p>\n<h2>Was haben Sie vor Ihrem Eintritt in das Unternehmen gemacht und wie haben Sie von OTGS erfahren?<\/h2>\n<p>Ich war Freiberufler, haupts\u00e4chlich arbeitete ich an Websites f\u00fcr Kunden, aber ich erstellte auch Plugins, wenn ich darum gebeten wurde. Ich kannte Agnes Bury seit Jahren. Sie organisierte WordCamps und stand in Kontakt mit Eyal. Eyal fragte sie, ob sie einen Entwickler empfehlen k\u00f6nne, und sie empfahl mich. Dann kontaktierte mich Eyal und so begann alles.    <\/p>\n<h2>Was umfasst also Ihre Arbeit?<\/h2>\n<figure id=\"attachment_2477\" aria-describedby=\"caption-attachment-2477\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/compatibility-team.jpg\" rel=\"attachment wp-att-2477\"><img decoding=\"async\" class=\"size-medium wp-image-2477 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/compatibility-team-300x200.jpg\" alt=\"WPML Kompatibilit\u00e4tsteam\" width=\"300\" height=\"200\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/compatibility-team-300x200.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/compatibility-team-1024x683.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/compatibility-team.jpg 1072w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" \/><\/a><figcaption id=\"caption-attachment-2477\" class=\"wp-caption-text\">WPML Kompatibilit\u00e4tsteam<\/figcaption><\/figure>\n<p>Einfach ausgedr\u00fcckt, teste ich, ob andere Plugins (insbesondere Woocommerce-Erweiterungen) gut funktionieren, wenn WPML aktiv ist, und umgekehrt, und stelle auch sicher, dass WPML nicht durch diese Erweiterungen beeintr\u00e4chtigt wird.<\/p>\n<p>Wenn es ein Kompatibilit\u00e4tsproblem gibt, kontaktiere ich den Autor und wir versuchen, es gemeinsam zu l\u00f6sen. Ich stelle Informationen \u00fcber unsere APIs zur Verf\u00fcgung, er\/sie liefert Informationen \u00fcber die internen Abl\u00e4ufe seines\/ihres Plugins. Dann versuchen wir, dieses Plugin umzuschreiben. M\u00f6glicherweise m\u00fcssen wir eine Kompatibilit\u00e4tsklasse zu Woocommerce Multilingual hinzuf\u00fcgen und manchmal sogar zu WPML.   <\/p>\n<p>Gelegentlich stellen wir fest, dass ein Problem gr\u00f6\u00dfer ist und eine allgemeinere L\u00f6sung erfordert, wie eine neue API f\u00fcr wp_mail.. Ich gehe dies an, indem ich einen neuen Code f\u00fcr WPML erstelle, diesen dokumentiere und anschlie\u00dfend die Autoren kontaktiere, um zu sehen, ob sie bereit sind, ihn einzuf\u00fchren.<br \/>\nWas wird hierf\u00fcr ben\u00f6tigt? Kenntnisse von WP, WPML und Woocommerce sind selbstverst\u00e4ndlich erforderlich. Zudem sind ausgepr\u00e4gte F\u00e4higkeiten in der Code-\u00dcberpr\u00fcfung und Fehlerbehebung unerl\u00e4sslich. Ein freundlicher Umgang bei der Kontaktaufnahme mit den Autoren ist ein gro\u00dfer Vorteil.    <\/p>\n<h2>Was sind einige der Herausforderungen und Vorteile in Ihrer Arbeit? Was gef\u00e4llt Ihnen am meisten an Ihrer Arbeit? <\/h2>\n<p>Am meisten sch\u00e4tze ich es, wenn eine Problemstellung nicht trivial ist. In solchen F\u00e4llen lade ich die betreffende Erweiterung auf meinen Rechner herunter, erstelle ein Netbeans-Projekt daf\u00fcr und verwende den Debugger, um den Sachverhalt zu ergr\u00fcnden. Noch mehr Freude bereitet es mir, wenn ich den Grund tats\u00e4chlich ausfindig mache und zur L\u00f6sung schreiten kann.   <\/p>\n<p>Ich begr\u00fc\u00dfe es auch, wenn ein einfacher Kompatibilit\u00e4tstest etwas Gr\u00f6\u00dferes ausl\u00f6st, wie beispielsweise diese neue wp_mail-API. Ich habe an einer Erweiterung gearbeitet, die E-Mails fehlerhaft versandte, und stellte dabei fest, dass potenziell jede E-Mail in der falschen Sprache verschickt werden k\u00f6nnte. Es wurde deutlich, dass WP\/WPML\/WordPress tats\u00e4chlich einer Neuorganisation bedurften. W\u00e4hrend der Arbeit daran stie\u00df ich auf zahlreiche F\u00e4lle, in denen ich meine L\u00f6sungsans\u00e4tze \u00fcberdenken und alles (oder fast alles) von Grund auf neu konzipieren musste: das Versenden von E-Mails durch einen englischsprachigen Administrator an einen spanischsprachigen Empf\u00e4nger, der Versand von Massen-E-Mails, das Versenden von E-Mails mit tokenisierten Zeichenfolgen&#8230; Dies ist kein kleines Projekt, aber es bereitet mir gro\u00dfe Freude.<\/p>\n<p>Gegenw\u00e4rtig bereite ich mich darauf vor, WPML-Unterst\u00fctzung zum WordPress-Exportwerkzeug hinzuzuf\u00fcgen, und ich freue mich bereits darauf.<\/p>\n<h2>Was m\u00fcssen Interessenten wissen, die Ihre T\u00e4tigkeit aus\u00fcben m\u00f6chten?<\/h2>\n<p>Es ist unerl\u00e4sslich, dass man WPML gr\u00fcndlich kennt und dessen Funktionsweise versteht. Man sollte in der Lage sein, den Code anderer Plugins zu lesen, um bei Bedarf Fehler beheben zu k\u00f6nnen. Es ist vorteilhaft, \u00fcber ausreichende PHP-Kenntnisse zu verf\u00fcgen, um sich mit fremdem Code wohlzuf\u00fchlen.  <\/p>\n<h2>Wie gestaltet sich Ihr typischer Arbeitstag?<\/h2>\n<p>Jeder Tag folgt einer gewissen Routine \u2013 ich stehe auf und gehe mit dem Hund spazieren, dann fahre ich ins B\u00fcro, das etwa 5 km entfernt liegt. Ich arbeite haupts\u00e4chlich mit unseren Partnern \u2013 Plugin- und Theme-Autoren \u2013 anstatt mit Kunden. In meiner Pause fahre ich nach Hause, um etwas zu essen, sofern Monika etwas zubereitet hat! Ich verbringe einige Zeit mit Baby Laura und gehe erneut mit dem Hund spazieren \u2013 das ist eine gute k\u00f6rperliche Bet\u00e4tigung f\u00fcr mich. Dienstags- und Donnerstagabends nehme ich an Englischunterricht teil.    <\/p>\n<h2>Welche Gedanken haben Sie f\u00fcr die Zukunft?<\/h2>\n<figure id=\"attachment_2455\" aria-describedby=\"caption-attachment-2455\" style=\"width: 225px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/IMG_20150614_094159.jpg\" rel=\"attachment wp-att-2455\"><img decoding=\"async\" class=\"size-medium wp-image-2455 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/IMG_20150614_094159-225x300.jpg\" alt=\"Konrad und seine Tochter Laura \" width=\"225\" height=\"300\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 225px; --smush-placeholder-aspect-ratio: 225\/300;\"><\/a><figcaption id=\"caption-attachment-2455\" class=\"wp-caption-text\">Konrad und seine Tochter Laura<\/figcaption><\/figure>\n<p>Wir w\u00fcrden gerne ein weiteres Kind haben. Meine Frau neigt dazu, sich Sorgen dar\u00fcber zu machen, in welcher Art von Welt unsere Tochter leben wird, aber ich mache mir keine Gedanken \u00fcber den Zustand der Welt. <\/p>\n<p>Ich liebe die Arbeit bei OTGS und m\u00f6chte das Unternehmen niemals verlassen. Ich sch\u00e4tze meine Kollegen sehr und hoffe, dass das Unternehmen weiter wachsen und in Zukunft noch mehr Plugins entwickeln wird! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Konrad ist ein zur\u00fcckhaltender Mann aus Polen. Sie w\u00e4ren \u00fcberrascht, wie reich an Erfahrungen sein Leben ist. Er arbeitete als WordPress-Freiberufler, war zweimal WordCamp-Redner, reiste sogar nach Ruanda, Afrika, um den dortigen Studenten Computerunterricht zu erteilen, um schlie\u00dflich als WordPress-Entwickler bei OnTheGoSystems zu landen. Heute erz\u00e4hlt er uns mehr \u00fcber sein Privatleben und seine Arbeit [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-25930","post","type-post","status-publish","format-standard","hentry","category-treffen-sie-unser-team"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Konrad Karpieszuk - ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Konrad Karpieszuk - ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Konrad ist ein zur\u00fcckhaltender Mann aus Polen. Sie w\u00e4ren \u00fcberrascht, wie reich an Erfahrungen sein Leben ist. Er arbeitete als WordPress-Freiberufler, war zweimal WordCamp-Redner, reiste sogar nach Ruanda, Afrika, um den dortigen Studenten Computerunterricht zu erteilen, um schlie\u00dflich als WordPress-Entwickler bei OnTheGoSystems zu landen. Heute erz\u00e4hlt er uns mehr \u00fcber sein Privatleben und seine Arbeit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-30T11:36:05+00:00\" \/>\n<meta name=\"author\" content=\"Helena Petridou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Petridou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/\"},\"author\":{\"name\":\"Helena Petridou\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\"},\"headline\":\"Konrad Karpieszuk &#8211; ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet\",\"datePublished\":\"2015-10-30T11:36:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/\"},\"wordCount\":1294,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/DSCN4360-300x224.jpg\",\"articleSection\":[\"Treffen Sie unser Team\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/\",\"name\":\"Konrad Karpieszuk - ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/DSCN4360-300x224.jpg\",\"datePublished\":\"2015-10-30T11:36:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/DSCN4360-300x224.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/DSCN4360-300x224.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/10\\\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Konrad Karpieszuk &#8211; ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\",\"name\":\"Helena Petridou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"caption\":\"Helena Petridou\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/author\\\/helena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Konrad Karpieszuk - ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/","og_locale":"de_DE","og_type":"article","og_title":"Konrad Karpieszuk - ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet - OnTheGoSystems","og_description":"Konrad ist ein zur\u00fcckhaltender Mann aus Polen. Sie w\u00e4ren \u00fcberrascht, wie reich an Erfahrungen sein Leben ist. Er arbeitete als WordPress-Freiberufler, war zweimal WordCamp-Redner, reiste sogar nach Ruanda, Afrika, um den dortigen Studenten Computerunterricht zu erteilen, um schlie\u00dflich als WordPress-Entwickler bei OnTheGoSystems zu landen. Heute erz\u00e4hlt er uns mehr \u00fcber sein Privatleben und seine Arbeit [&hellip;]","og_url":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/","og_site_name":"OnTheGoSystems","article_published_time":"2015-10-30T11:36:05+00:00","author":"Helena Petridou","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Helena Petridou","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/"},"author":{"name":"Helena Petridou","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555"},"headline":"Konrad Karpieszuk &#8211; ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet","datePublished":"2015-10-30T11:36:05+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/"},"wordCount":1294,"publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/DSCN4360-300x224.jpg","articleSection":["Treffen Sie unser Team"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/","url":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/","name":"Konrad Karpieszuk - ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/DSCN4360-300x224.jpg","datePublished":"2015-10-30T11:36:05+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/DSCN4360-300x224.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/10\/DSCN4360-300x224.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/de\/2015\/10\/konrad-karpieszuk-ein-entwickler-der-wordpress-plugins-auf-wpml-kompatibilitaet-testet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/de\/"},{"@type":"ListItem","position":2,"name":"Konrad Karpieszuk &#8211; ein Entwickler, der WordPress-Plugins auf WPML-Kompatibilit\u00e4t testet"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/de\/#website","url":"https:\/\/onthegosystems.com\/de\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/de\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555","name":"Helena Petridou","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","caption":"Helena Petridou"},"url":"https:\/\/onthegosystems.com\/de\/author\/helena\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/25930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/comments?post=25930"}],"version-history":[{"count":0,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/25930\/revisions"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/media?parent=25930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/categories?post=25930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/tags?post=25930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}