{"id":25981,"date":"2015-08-07T10:47:21","date_gmt":"2015-08-07T10:47:21","guid":{"rendered":"https:\/\/onthegosystems.com\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/"},"modified":"2015-08-07T10:47:21","modified_gmt":"2015-08-07T10:47:21","slug":"mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/","title":{"rendered":"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben &#8211; die Priorit\u00e4ten eines Views-Plugin-Entwicklers"},"content":{"rendered":"<p><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan2.jpg\" rel=\"attachment wp-att-2259\"><img decoding=\"async\" class=\"alignleft wp-image-2259 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan2-300x231.jpg\" alt=\"Jan liebt die Natur\" width=\"300\" height=\"231\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/231;\"><\/a><\/p>\n<p>Leidenschaftlich f\u00fcr Wandern und Code-Refactoring gleicherma\u00dfen. Wenn Sie unseren Neuigkeiten folgen, haben Sie m\u00f6glicherweise bemerkt, dass die hier arbeitenden Entwickler einzigartige Interessenkombinationen haben. <\/p>\n<p>Allerdings gibt es etwas Au\u00dfergew\u00f6hnliches an Jan \u0160t\u011btina, dem Views-Plugin-Entwickler aus der Tschechischen Republik. Er schlie\u00dft seine Masterarbeit ab, lebt im Laufe des Jahres an drei verschiedenen Orten und beweist, dass, solange eine gute Internetverbindung vorhanden ist, fehlendes flie\u00dfendes Wasser lediglich ein marginales Problem darstellt! <\/p>\n<p>Erfahren Sie mehr \u00fcber diesen scheinbar sch\u00fcchternen Mann in Helenas Interview.<\/p>\n<h2>Erz\u00e4hlen Sie uns etwas \u00fcber sich selbst<\/h2>\n<p>Mein Name ist Jan \u0160t\u011btina und ich komme aus der Tschechischen Republik. Derzeit bereite ich meine Masterarbeit vor, daher arbeite ich momentan in Teilzeit f\u00fcr OTGS. <\/p>\n<p>Ich wurde in Prag geboren, wo meine Eltern und meine j\u00fcngere Schwester noch leben. Mein Vater arbeitet in der Chemieabteilung der Karls-Universit\u00e4t und meine Mutter ist Chefredakteurin eines Wissenschaftsmagazins. <\/p>\n<figure id=\"attachment_2285\" aria-describedby=\"caption-attachment-2285\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/cottage.jpg\" rel=\"attachment wp-att-2261\"><img decoding=\"async\" class=\"wp-image-2285 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/cottage-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\"><\/a><figcaption id=\"caption-attachment-2285\" class=\"wp-caption-text\">Familienhaus, in dem Jan gerne seine Zeit verbringt<\/figcaption><\/figure>\n<p>Ich selbst teile meine Zeit zwischen drei verschiedenen Orten auf. Erstens in Prag, wo ich eine kleine, aber angenehme Wohnung habe. Der zweite Ort ist eine Kleinstadt in M\u00e4hren, wo ich meinem Gro\u00dfvater (der allein lebt) so viel wie m\u00f6glich Gesellschaft leiste. Schlie\u00dflich gibt es ein Familienhaus, das an einem abgelegenen Ort in Westb\u00f6hmen versteckt ist und f\u00fcr das ich nun verantwortlich bin. Sie haben wahrscheinlich die Fotos gesehen, die ich in unserer G+-Community gepostet habe. Das Haus ist nur 15 Minuten zu Fu\u00df vom Dorf entfernt, wo ich Lebensmittel und andere Notwendigkeiten einkaufen kann. Wenn Sie zu Besuch kommen, werden Sie auch die Priorit\u00e4ten einer IT-Person sehen: Es gibt eine 10-Mbit-Internetverbindung, aber kein flie\u00dfendes Wasser. :-) Ich muss es aus einem Brunnen am Fu\u00dfe des H\u00fcgels holen! Ich lebe dort allein, aber meine Freunde sind h\u00e4ufige Besucher.       <\/p>\n<p>Momentan muss das Dach des Hauses repariert werden, um das Eindringen von Regen zu verhindern! Zwischen dieser Reparaturarbeit, dem Reisen zwischen den Orten und der Arbeit an meiner Thesis bleibt mir nicht viel Freizeit. Aber ich bin leidenschaftlich an der Natur und am Wandern interessiert. Mit einer Gruppe von etwa 10 Freunden gehen wir jeweils eine Woche lang wandern und schlafen in den W\u00e4ldern. Unser Ziel ist es, in Etappen die gesamte tschechische Grenze entlang zu wandern, eine Strecke von etwa 2000 km. Wir werden es schlie\u00dflich schaffen!     <\/p>\n<h2>Sie sind noch Student, wie haben Sie also begonnen, mit OTGS zu arbeiten?<\/h2>\n<p>Bis ich meine Thesis abschlie\u00dfe, bin ich streng genommen Student. Ich interessierte mich schon vor sehr langer Zeit f\u00fcr WordPress, als ich meinen eigenen Blog begann. Es machte mir auch Freude, anderen mit ihren Websites zu helfen, und ich erstellte mehrere kleinere WordPress-Websites gegen Bezahlung. Einen Job bei OTGS zu bekommen, war ein sehr gl\u00fccklicher doppelter Zufall. Letztes Jahr entschied ich mich spontan, das WordCamp Prag zu besuchen, und dort traf ich Agnes. Sie hielt eine WPML-Pr\u00e4sentation und stellte einige Testfragen. Der Preis f\u00fcr den Gewinner war eine WPML-Lizenz. Ich bin von Natur aus ziemlich sch\u00fcchtern, hob aber dennoch meine Hand, um zu antworten, und wurde von Agnes bemerkt. Sie gab meine Kontaktinformationen weiter, und ich erhielt eine E-Mail mit der Bitte um meinen Lebenslauf.        <\/p>\n<p>In diesem Sommer gab es jedoch einige Komplikationen zu \u00fcberwinden. Ich sollte mich einer Operation unterziehen, und der Zeitpunkt war ung\u00fcnstig. Erst im November konnte ich schlie\u00dflich anfangen.  <\/p>\n<h2>Ich gebe zu, dass ich nicht viel technisches Wissen habe, aber ich bin wirklich an dem interessiert, was Sie in Ihrem Job machen.<\/h2>\n<figure id=\"attachment_2272\" aria-describedby=\"caption-attachment-2272\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/code-refactoring.png\" rel=\"attachment wp-att-2272\"><img decoding=\"async\" class=\"wp-image-2272 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/code-refactoring-300x168.png\" alt=\"Beispiel f\u00fcr Code-Refactoring, das von Jan durchgef\u00fchrt wird\" width=\"300\" height=\"168\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/168;\"><\/a><figcaption id=\"caption-attachment-2272\" class=\"wp-caption-text\">Beispiel f\u00fcr Code-Refactoring, das von Jan durchgef\u00fchrt wird<\/figcaption><\/figure>\n<p>Ich bin ein Entwickler, der unter Juans Leitung im Toolset-Team arbeitet, haupts\u00e4chlich am Views-Plugin \u2013 ich finde und behebe Fehler, implementiere neue Funktionen und helfe grunds\u00e4tzlich \u00fcberall, wo es n\u00f6tig ist. Ich w\u00fcrde sagen, dies ist eine stabile, &#8217;standardm\u00e4\u00dfige&#8216; Art von Arbeitsbelastung f\u00fcr einen Entwickler, aber ich sch\u00e4tze die ruhige, organisierte und effektive Art, wie wir hier die Dinge angehen. Aus meiner fr\u00fcheren Erfahrung und von dem, was ich von meinen Entwicklerfreunden h\u00f6re, wei\u00df ich, dass dies etwas ist, dem man einen hohen Wert beimessen sollte.  <\/p>\n<p>Ein Teil der Arbeit, den ich besonders sch\u00e4tze, ist das Refactoring. Dies bedeutet, die weniger ansprechenden Teile des Quellcodes zu verbessern, die manchmal von Personen geschrieben wurden, die m\u00f6glicherweise nicht mehr im Unternehmen t\u00e4tig sind, und die schwer zu lesen und zu verstehen sind. Das WordPress-Motto &#8218;Code ist Poesie&#8216; ist f\u00fcr mich keine leere Phrase. Obwohl meine Arbeit nicht offensichtlich im Rampenlicht steht, gibt mir die Unterst\u00fctzung bei der Verbesserung der Views-Codebasis ein Gef\u00fchl der Zufriedenheit, erm\u00f6glicht eine bessere Wartung in der Zukunft und, was langfristig sehr wichtig ist, zufriedenere Kunden.   <\/p>\n<h2>Welche Kenntnisse werden von jemandem verlangt, der an dieser Art von Arbeit interessiert ist?<\/h2>\n<p>Ich w\u00fcrde sagen, fundierte Kenntnisse der von uns verwendeten Sprachen: PHP, JavaScript und CSS. Nat\u00fcrlich ist die F\u00e4higkeit, guten, gut strukturierten, verst\u00e4ndlichen und wartbaren Code zu schreiben, unerl\u00e4sslich. <\/p>\n<p>Man muss auch sehr vertraut mit den spezifischen Tools sein, die wir verwenden, angefangen bei WordPress selbst, einschlie\u00dflich verschiedener JavaScript-Bibliotheken und dergleichen. Nicht zuletzt ist es wichtig, das Produkt, an dem man arbeitet, in- und auswendig zu kennen, aber das kommt mit der Zeit und Erfahrung. Selbst nach 9 Monaten bei OTGS habe ich noch viel zu lernen.  <\/p>\n<p>Zu guter Letzt sind gute allgemeine Kenntnisse der Informatik sehr wichtig, aber das l\u00e4sst sich leider nicht so einfach zusammenfassen.<\/p>\n<h2>Beschreiben Sie einen normalen Tag in Views<\/h2>\n<p>Zuerst haben wir ein t\u00e4gliches Team-Meeting. Das gesamte Toolset-Team nimmt teil, und manchmal auch Denise, Amir, Bigul oder einfach jeder, der mit uns sprechen muss. Wir \u00fcberpr\u00fcfen unsere Arbeit vom Vortag und legen unsere Pl\u00e4ne f\u00fcr den Tag fest. Wir diskutieren alle Probleme, die m\u00f6glicherweise aufgetreten sind. Toolset-Plugins sollen zusammenarbeiten und sind in einigen Aspekten voneinander abh\u00e4ngig. Aus diesem Grund m\u00fcssen wir oft gleichzeitig neue Versionen mehrerer Plugins gemeinsam ver\u00f6ffentlichen. Dies kann eine organisatorische Herausforderung darstellen, daher ist es wichtig, dass jeder im Team einen umfassenden \u00dcberblick dar\u00fcber hat, was vor sich geht.      <\/p>\n<figure id=\"attachment_2266\" aria-describedby=\"caption-attachment-2266\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan_office.jpg\" rel=\"attachment wp-att-2266\"><img decoding=\"async\" class=\"wp-image-2266 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan_office-300x231.jpg\" alt=\"Jans B\u00fcro\" width=\"300\" height=\"231\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/231;\"><\/a><figcaption id=\"caption-attachment-2266\" class=\"wp-caption-text\">Jans B\u00fcro<\/figcaption><\/figure>\n<p>K\u00fcrzlich erwies sich dies als essentiell: Das WordPress 4.2.3 &#8218;Sicherheitsupdate&#8216; hatte einige Views-Funktionalit\u00e4ten selbst auf Produktionsseiten beeintr\u00e4chtigt. Das gesamte Team (insbesondere Juan und auch Bruce, der uns vom WPML-Team zu Hilfe kam) arbeitete sehr hart daran, dies zu beheben. <\/p>\n<p>Nach dem Meeting beginne ich normalerweise mit der Bearbeitung von Tickets aus YouTrack. Es gibt immer so viel zu tun! <\/p>\n<p>Tage und oft Wochen des Programmierens werden gefolgt von einer kurzen Testphase, um sicherzustellen, dass alles noch normal wie zuvor funktioniert. \u00dcblicherweise wechseln wir von unserem &#8218;Heimat&#8216;-Plugin zu einem anderen, um weniger vertraute Funktionen durch ein neues Augenpaar zu testen. Zum Beispiel k\u00f6nnte ich Types, CRED oder Layouts testen, w\u00e4hrend Francesco, Riccardo, Marcin oder Gen die Tests in Views durchf\u00fchren.  <\/p>\n<h2>Irgendwelche Zukunftspl\u00e4ne?<\/h2>\n<figure id=\"attachment_2269\" aria-describedby=\"caption-attachment-2269\" style=\"width: 197px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan-on-the-meadow.jpg\" rel=\"attachment wp-att-2269\"><img decoding=\"async\" class=\"wp-image-2269 size-medium lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan-on-the-meadow-197x300.jpg\" alt=\"Jan beim Ausruhen w\u00e4hrend einer Wanderung\" width=\"197\" height=\"300\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 197px; --smush-placeholder-aspect-ratio: 197\/300;\"><\/a><figcaption id=\"caption-attachment-2269\" class=\"wp-caption-text\">Jan beim Ausruhen w\u00e4hrend einer Wanderung<\/figcaption><\/figure>\n<p>Meine absolute Priorit\u00e4t ist es jetzt, meine Dissertation vor Ende August fertigzustellen, und daher werde ich in diesem Monat abwesend sein. An dieser Stelle m\u00f6chte ich meine Dankbarkeit f\u00fcr das Verst\u00e4ndnis und die Kooperation ausdr\u00fccken, die ich von Laura und Juan erhalten habe, die dies erm\u00f6glicht haben. <\/p>\n<p>Dar\u00fcber hinaus ben\u00f6tigt das Landhaus dringend meine Aufmerksamkeit, und es wird sie so bald wie m\u00f6glich bekommen. Es ist ein gro\u00dfes, altes Haus, aber es wurde mehrere Jahre lang \u00fcberhaupt nicht instand gehalten. Dies wird eine enorme Herausforderung f\u00fcr mich sein, da ich in der Stadt aufgewachsen bin und in dieser Art von Unternehmung unerfahren bin!  <\/p>\n<p>Auch meine gesundheitlichen Probleme m\u00fcssen ber\u00fccksichtigt werden. Ich plane, mehr Sport zu treiben und die Tai-Chi-Stunden wieder aufzunehmen, die ich wegen der Operation im letzten Jahr unterbrechen musste. Tai-Chi ist nicht nur eine gro\u00dfartige Aktivit\u00e4t zur Verbesserung der k\u00f6rperlichen Gesundheit. Urspr\u00fcnglich wurde es zur Selbstverteidigung entwickelt, aber sein selbstgesteuertes System sanfter k\u00f6rperlicher \u00dcbungen und tiefer Atmung wird empfohlen, um Stress abzubauen und die allgemeine Gesundheit zu verbessern, besonders wenn es mit ein wenig \u00f6stlicher Philosophie kombiniert wird. Ich finde es sehr beruhigend, was in meiner Welt wichtig ist. :)     <\/p>\n<p>Oh, ich k\u00f6nnte endlos \u00fcber meine Pl\u00e4ne sprechen! Die Liste ist endlos. Aber eines der wichtigsten Dinge &#8211; ich hoffe, dass ich eines Tages jemanden finden werde, mit dem ich all dies teilen kann&#8230;  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leidenschaftlich f\u00fcr Wandern und Code-Refactoring gleicherma\u00dfen. Wenn Sie unseren Neuigkeiten folgen, haben Sie m\u00f6glicherweise bemerkt, dass die hier arbeitenden Entwickler einzigartige Interessenkombinationen haben. Allerdings gibt es etwas Au\u00dfergew\u00f6hnliches an Jan \u0160t\u011btina, dem Views-Plugin-Entwickler aus der Tschechischen Republik. Er schlie\u00dft seine Masterarbeit ab, lebt im Laufe des Jahres an drei verschiedenen Orten und beweist, dass, solange [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-25981","post","type-post","status-publish","format-standard","hentry","category-treffen-sie-unser-team"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben - die Priorit\u00e4ten eines Views-Plugin-Entwicklers - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben - die Priorit\u00e4ten eines Views-Plugin-Entwicklers - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Leidenschaftlich f\u00fcr Wandern und Code-Refactoring gleicherma\u00dfen. Wenn Sie unseren Neuigkeiten folgen, haben Sie m\u00f6glicherweise bemerkt, dass die hier arbeitenden Entwickler einzigartige Interessenkombinationen haben. Allerdings gibt es etwas Au\u00dfergew\u00f6hnliches an Jan \u0160t\u011btina, dem Views-Plugin-Entwickler aus der Tschechischen Republik. Er schlie\u00dft seine Masterarbeit ab, lebt im Laufe des Jahres an drei verschiedenen Orten und beweist, dass, solange [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-07T10:47:21+00:00\" \/>\n<meta name=\"author\" content=\"Helena Petridou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Petridou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/\"},\"author\":{\"name\":\"Helena Petridou\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\"},\"headline\":\"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben &#8211; die Priorit\u00e4ten eines Views-Plugin-Entwicklers\",\"datePublished\":\"2015-08-07T10:47:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/\"},\"wordCount\":1460,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/jan2-300x231.jpg\",\"articleSection\":[\"Treffen Sie unser Team\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/\",\"name\":\"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben - die Priorit\u00e4ten eines Views-Plugin-Entwicklers - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/jan2-300x231.jpg\",\"datePublished\":\"2015-08-07T10:47:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/jan2-300x231.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/jan2-300x231.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/2015\\\/08\\\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben &#8211; die Priorit\u00e4ten eines Views-Plugin-Entwicklers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\",\"name\":\"Helena Petridou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"caption\":\"Helena Petridou\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/de\\\/author\\\/helena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben - die Priorit\u00e4ten eines Views-Plugin-Entwicklers - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/","og_locale":"de_DE","og_type":"article","og_title":"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben - die Priorit\u00e4ten eines Views-Plugin-Entwicklers - OnTheGoSystems","og_description":"Leidenschaftlich f\u00fcr Wandern und Code-Refactoring gleicherma\u00dfen. Wenn Sie unseren Neuigkeiten folgen, haben Sie m\u00f6glicherweise bemerkt, dass die hier arbeitenden Entwickler einzigartige Interessenkombinationen haben. Allerdings gibt es etwas Au\u00dfergew\u00f6hnliches an Jan \u0160t\u011btina, dem Views-Plugin-Entwickler aus der Tschechischen Republik. Er schlie\u00dft seine Masterarbeit ab, lebt im Laufe des Jahres an drei verschiedenen Orten und beweist, dass, solange [&hellip;]","og_url":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/","og_site_name":"OnTheGoSystems","article_published_time":"2015-08-07T10:47:21+00:00","author":"Helena Petridou","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Helena Petridou","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/"},"author":{"name":"Helena Petridou","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555"},"headline":"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben &#8211; die Priorit\u00e4ten eines Views-Plugin-Entwicklers","datePublished":"2015-08-07T10:47:21+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/"},"wordCount":1460,"publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan2-300x231.jpg","articleSection":["Treffen Sie unser Team"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/","url":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/","name":"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben - die Priorit\u00e4ten eines Views-Plugin-Entwicklers - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan2-300x231.jpg","datePublished":"2015-08-07T10:47:21+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan2-300x231.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2015\/08\/jan2-300x231.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/de\/2015\/08\/mit-einer-10-mbit-internetverbindung-und-ohne-fliessendes-wasser-leben-die-prioritaeten-eines-views-plugin-entwicklers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/de\/"},{"@type":"ListItem","position":2,"name":"Mit einer 10-Mbit-Internetverbindung und ohne flie\u00dfendes Wasser leben &#8211; die Priorit\u00e4ten eines Views-Plugin-Entwicklers"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/de\/#website","url":"https:\/\/onthegosystems.com\/de\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/de\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/de\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555","name":"Helena Petridou","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","caption":"Helena Petridou"},"url":"https:\/\/onthegosystems.com\/de\/author\/helena\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/25981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/comments?post=25981"}],"version-history":[{"count":0,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/posts\/25981\/revisions"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/media?parent=25981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/categories?post=25981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/de\/wp-json\/wp\/v2\/tags?post=25981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}