{"id":18838,"date":"2020-04-22T15:04:46","date_gmt":"2024-06-03T07:27:15","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/"},"modified":"2024-06-03T07:27:26","modified_gmt":"2024-06-03T07:27:26","slug":"trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/","title":{"rendered":"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable?"},"content":{"rendered":"\n<p class=\"lead\">Aunque trabajar desde casa en l\u00ednea tiene muchas ventajas, es comprensible que existan preocupaciones v\u00e1lidas. \u00bfPuedo encontrar trabajo fijo en Internet? Tengo algunas habilidades, pero \u00bfson suficientes para asegurarme un puesto fijo? \u00bfC\u00f3mo es trabajar en Internet? \u00bfSe fijar\u00e1 en m\u00ed mi jefe y me mantendr\u00e1?<\/p>\n\n<p>Este mes, Bruce Pearson de Australia, nuestro Empleado del mes, abordar\u00e1 estas preocupaciones describiendo sus experiencias personales de trabajo con <a href=\"https:\/\/onthegosystems.com\/es\/\">OnTheGoSystems.<\/a><\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"935\" height=\"701\" data-id=\"6797\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-sea-lion.jpg\" alt=\"\" class=\"wp-image-6797 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-sea-lion.jpg 935w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-sea-lion-300x225.jpg 300w\" data-sizes=\"(max-width: 935px) 100vw, 935px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 935px; --smush-placeholder-aspect-ratio: 935\/701;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"591\" data-id=\"6799\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-bike-1024x591.jpg\" alt=\"\" class=\"wp-image-6799 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-bike-1024x591.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-bike-300x173.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-bike.jpg 1214w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/591;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"449\" data-id=\"6796\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-dog-1024x449.jpg\" alt=\"\" class=\"wp-image-6796 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-dog-1024x449.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-dog-300x131.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-dog-1536x673.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-dog.jpg 1600w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/449;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"339\" data-id=\"6798\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-lunch-1024x339.jpg\" alt=\"\" class=\"wp-image-6798 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-lunch-1024x339.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-lunch-300x99.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-lunch-1536x509.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-lunch.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/339;\" \/><\/figure>\n<\/figure>\n\n<h3 class=\"wp-block-heading\">Bruce, empezaste a trabajar para OnTheGoSystems en marzo de 2007. \u00bfCorrecto?<\/h3>\n\n<p>As\u00ed es. Obtuve el t\u00edtulo de Ingeniero El\u00e9ctrico y pas\u00e9 varios a\u00f1os trabajando en la industria manufacturera dise\u00f1ando y trabajando en m\u00e1quinas-herramienta de Control Num\u00e9rico por Ordenador. Despu\u00e9s empec\u00e9 a trabajar en la industria del software y desarroll\u00e9 programas de dise\u00f1o gr\u00e1fico para la industria de la rotulaci\u00f3n. Tambi\u00e9n empec\u00e9 a hacer trabajos de programaci\u00f3n por encargo en Internet durante 10 a\u00f1os antes de empezar con OTGS. Ha resultado ser un trabajo estable para m\u00ed.<\/p>\n\n<p>Al principio empec\u00e9 a trabajar en un par de proyectos de contrataci\u00f3n para OTGS con el fin de desarrollar el software Asistente de Traducci\u00f3n para <a href=\"https:\/\/www.icanlocalize.com\/site\/about-us\/\">ICanLocalize<\/a>. ICL se fund\u00f3 en 2007 con el objetivo de poner la traducci\u00f3n profesional al alcance de todos. Al principio s\u00f3lo lo hac\u00eda a tiempo parcial para complementar mis ingresos, porque la empresa principal para la que trabajaba en Australia estaba de capa ca\u00edda. Con el tiempo, mi trabajo en Australia termin\u00f3 y empec\u00e9 a trabajar a tiempo completo para la OTGS.<\/p>\n\n<p>La OTGS ha cambiado notablemente en los a\u00f1os que llevo trabajando aqu\u00ed. Entonces s\u00f3lo \u00e9ramos 2 personas trabajando juntas y la empresa ha crecido hasta casi 100 en ese periodo. El momento m\u00e1s emocionante fue cuando lanzamos WPML comercialmente en 2011 y a partir de ah\u00ed fue creciendo.<\/p>\n\n<h3 class=\"wp-block-heading\">Has desempe\u00f1ado con \u00e9xito este trabajo en l\u00ednea durante 13 a\u00f1os. \u00bfCu\u00e1l es el secreto?<\/h3>\n\n<p>Obviamente, el trabajo que hago tiene que beneficiar a la empresa. Tambi\u00e9n tiene que aportarme satisfacci\u00f3n personal.<\/p>\n\n<blockquote class=\"wp-block-quote has-text-align-center is-style-default is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Excelentes oportunidades de desarrollo profesional<\/p>\n<\/blockquote>\n\n<p>Mi inter\u00e9s se alimenta de excelentes oportunidades para desarrollar mi carrera. Nunca me aburro hasta el punto de buscar un cambio de empleo. Adem\u00e1s, las habilidades que acumulo benefician a la OTGS porque las utilizo para ayudar a mejorar el c\u00f3digo de <a href=\"https:\/\/wpml.org\/\">WPML<\/a>, un plugin potente pero sencillo que facilita la creaci\u00f3n y el funcionamiento de sitios multiling\u00fces.<\/p>\n\n<p>He tenido la oportunidad de trabajar en muchos lenguajes y entornos de programaci\u00f3n diferentes. Antes de la OTGS, mi principal trabajo de desarrollo era con C++ y algo de Python. Mi primer trabajo en la OTGS fue escribir Asistente de Traducci\u00f3n en Python. Luego pas\u00e9 a PHP trabajando en un m\u00f3dulo de Drupal que ten\u00eda algunas de las funciones de gesti\u00f3n de traducciones que ahora tenemos en WPML. Despu\u00e9s trabaj\u00e9 en Toolset y ahora principalmente en WPML.  <\/p>\n\n<p>Mi principal inter\u00e9s en este momento es la programaci\u00f3n funcional y c\u00f3mo aplicarla para mejorar el c\u00f3digo en WPML.<\/p>\n\n<h3 class=\"wp-block-heading\">  Trabajar en l\u00ednea en un entorno satisfactorio<\/h3>\n\n<p>Trabajar en un entorno satisfactorio tambi\u00e9n es importante para mantener un trabajo en l\u00ednea estable. Trabajo principalmente con el equipo de desarrollo de WPML. Mi objetivo es ser una buena jugadora de equipo y contribuir al ambiente cordial. A veces tenemos desacuerdos sobre c\u00f3mo deben hacerse las cosas y tenemos opiniones firmes sobre la forma correcta de codificar algo. Lo m\u00e1s dif\u00edcil es no tomarse las cosas como algo personal cuando alguien tiene una opini\u00f3n diferente. Tambi\u00e9n debes tener cuidado al comentar el trabajo de otras personas y no ser demasiado pedante.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfSe fijar\u00e1n en m\u00ed y conservar\u00e9 mi trabajo?  <\/h3>\n\n<p>La empresa se beneficia cuando acepto de buen grado nuevos retos y soy m\u00e1s feliz cuando tengo un proyecto en el que trabajar que supone un desaf\u00edo. Esto ocurre tanto en el trabajo como en mi vida personal. Siempre es satisfactorio completar proyectos con \u00e9xito y tener algo bonito que mostrar al final.<\/p>\n\n<p>Es muy importante desconectar al final del d\u00eda, para relajarse y liberar el estr\u00e9s. No me gusta trabajar todo el d\u00eda y suelo hacer un buen descanso en medio, donde saco a pasear a los perros y hago algo de ejercicio. Me encanta montar en mi bicicleta de empuje todos los d\u00edas. Me gusta mucho escuchar m\u00fasica y llevo muchos a\u00f1os tocando. Pero nunca he tenido la habilidad musical natural que tienen algunas personas. \u00a1Ojal\u00e1 tuviera m\u00e1s talento musical!<\/p>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aunque trabajar desde casa en l\u00ednea tiene muchas ventajas, es comprensible que existan preocupaciones v\u00e1lidas. \u00bfPuedo encontrar trabajo fijo en Internet? Tengo algunas habilidades, pero \u00bfson suficientes para asegurarme un puesto fijo? \u00bfC\u00f3mo es trabajar en Internet? \u00bfSe fijar\u00e1 en m\u00ed mi jefe y me mantendr\u00e1? Este mes, Bruce Pearson de Australia, nuestro Empleado del [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150,152],"tags":[],"class_list":["post-18838","post","type-post","status-publish","format-standard","hentry","category-conoce-a-nuestro-equipo","category-trabajos-e-historias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable? - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable? - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Aunque trabajar desde casa en l\u00ednea tiene muchas ventajas, es comprensible que existan preocupaciones v\u00e1lidas. \u00bfPuedo encontrar trabajo fijo en Internet? Tengo algunas habilidades, pero \u00bfson suficientes para asegurarme un puesto fijo? \u00bfC\u00f3mo es trabajar en Internet? \u00bfSe fijar\u00e1 en m\u00ed mi jefe y me mantendr\u00e1? Este mes, Bruce Pearson de Australia, nuestro Empleado del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:27:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-03T07:27:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-sea-lion.jpg\" \/>\n<meta name=\"author\" content=\"Helena Petridou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Petridou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/\"},\"author\":{\"name\":\"Helena Petridou\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\"},\"headline\":\"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable?\",\"datePublished\":\"2024-06-03T07:27:15+00:00\",\"dateModified\":\"2024-06-03T07:27:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/\"},\"wordCount\":787,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/bruce-sea-lion.jpg\",\"articleSection\":[\"Conoce a nuestro equipo\",\"Trabajos e Historias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/\",\"name\":\"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable? - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/bruce-sea-lion.jpg\",\"datePublished\":\"2024-06-03T07:27:15+00:00\",\"dateModified\":\"2024-06-03T07:27:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/bruce-sea-lion.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/bruce-sea-lion.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/04\\\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\",\"name\":\"Helena Petridou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"caption\":\"Helena Petridou\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/author\\\/helena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable? - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/","og_locale":"es_ES","og_type":"article","og_title":"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable? - OnTheGoSystems","og_description":"Aunque trabajar desde casa en l\u00ednea tiene muchas ventajas, es comprensible que existan preocupaciones v\u00e1lidas. \u00bfPuedo encontrar trabajo fijo en Internet? Tengo algunas habilidades, pero \u00bfson suficientes para asegurarme un puesto fijo? \u00bfC\u00f3mo es trabajar en Internet? \u00bfSe fijar\u00e1 en m\u00ed mi jefe y me mantendr\u00e1? Este mes, Bruce Pearson de Australia, nuestro Empleado del [&hellip;]","og_url":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:27:15+00:00","article_modified_time":"2024-06-03T07:27:26+00:00","og_image":[{"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-sea-lion.jpg","type":"","width":"","height":""}],"author":"Helena Petridou","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Helena Petridou","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/"},"author":{"name":"Helena Petridou","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555"},"headline":"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable?","datePublished":"2024-06-03T07:27:15+00:00","dateModified":"2024-06-03T07:27:26+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/"},"wordCount":787,"publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-sea-lion.jpg","articleSection":["Conoce a nuestro equipo","Trabajos e Historias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/","url":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/","name":"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable? - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-sea-lion.jpg","datePublished":"2024-06-03T07:27:15+00:00","dateModified":"2024-06-03T07:27:26+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-sea-lion.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/04\/bruce-sea-lion.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/es\/2020\/04\/trabajar-desde-casa-me-atrae-pero-puedo-encontrar-un-trabajo-online-estable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Trabajar desde casa me atrae, pero \u00bfpuedo encontrar un trabajo online estable?"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/es\/#website","url":"https:\/\/onthegosystems.com\/es\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/es\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555","name":"Helena Petridou","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","caption":"Helena Petridou"},"url":"https:\/\/onthegosystems.com\/es\/author\/helena\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/18838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/comments?post=18838"}],"version-history":[{"count":1,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/18838\/revisions"}],"predecessor-version":[{"id":18840,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/18838\/revisions\/18840"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media?parent=18838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/categories?post=18838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/tags?post=18838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}