{"id":18918,"date":"2020-01-09T10:14:58","date_gmt":"2024-06-03T07:28:34","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/"},"modified":"2024-06-03T07:28:50","modified_gmt":"2024-06-03T07:28:50","slug":"otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/","title":{"rendered":"Otto Wald &#8211; \u00bfEs posible desarrollar tu carrera trabajando desde casa?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Si decides trabajar desde casa, \u00bfcu\u00e1les son tus perspectivas profesionales? Al trabajar desde casa, \u00bfte volver\u00e1s \u00abinvisible\u00bb? \u00bfC\u00f3mo puedes impresionar a tu equipo y a tu jefe de equipo y conseguir buenas evaluaciones de rendimiento y ascensos?<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>El Empleado del Mes de este mes, Otto Federico Wald, de Argentina, est\u00e1 construyendo con \u00e9xito una prometedora carrera en la empresa. Ha estado trabajando con  <\/strong><a href=\"https:\/\/onthegosystems.com\/es\/\">\n  <strong>EnLosSistemasGo<\/strong>\n<\/a><strong> en el <\/strong><a href=\"https:\/\/wpml.org\/forums\/forum\/english-support\/\">\n  <strong>soporte WPML<\/strong>\n<\/a><strong> desde 2015.<\/strong><\/p>\n\n<h2 class=\"wp-block-heading\">Otto, \u00bfdir\u00edas que eres del tipo ambicioso?<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-medium\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/futbol.jpg\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/futbol-225x300.jpg\" alt=\"\" class=\"wp-image-6388 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 225px; --smush-placeholder-aspect-ratio: 225\/300;\" \/><\/a><figcaption class=\"wp-element-caption\">  Una clase abierta en su \u00abescuela\u00bb de f\u00fatbol (con Juan y Mateo)  <\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">\u00bfAmbicioso? Bueno, cuando era peque\u00f1o, con tres o cuatro a\u00f1os, dec\u00eda que quer\u00eda ser \u00abmagnate\u00bb. Es una palabra espa\u00f1ola que tiene el mismo significado en ingl\u00e9s (acabo de buscarlo ;) Los amigos de mis padres sol\u00edan llamarme \u00abel magnate\u00bb, que es un apodo gracioso para un ni\u00f1o tan peque\u00f1o.<strong>  <\/strong>Pero los sue\u00f1os de nuestra infancia y la realidad de la vida no son lo mismo.<\/p>\n\n<p class=\"wp-block-paragraph\">Pas\u00e9 por etapas de estar en paro e incluso cerca de la depresi\u00f3n. No fue ni es f\u00e1cil. Quer\u00eda hacer de mi vida un \u00e9xito, construir una carrera significativa. En mi b\u00fasqueda de una carrera, prob\u00e9 varias v\u00edas. El trabajo m\u00e1s inusual que prob\u00e9 fue el de taxista. Lo hice durante unos meses. Fue un comienzo, pero no una experiencia que disfrutara.<\/p>\n\n<p class=\"wp-block-paragraph\">Buscaba algo m\u00e1s interesante. Lo descubr\u00ed cuando trabajaba en un instituto de investigaci\u00f3n haciendo bibliometr\u00eda y \u00abm\u00e9trica de patentes\u00bb, que son estudios estad\u00edsticos sobre publicaciones tecnol\u00f3gicas y cient\u00edficas para tomar decisiones sobre pol\u00edticas p\u00fablicas de ciencia y tecnolog\u00eda.  <\/p>\n\n<h2 class=\"wp-block-heading clear\">Del instituto de investigaci\u00f3n a la OTGS: \u00a1todo un salto profesional!<\/h2>\n\n<p class=\"wp-block-paragraph\">Llegu\u00e9 aqu\u00ed por casualidad :) M\u00e1s adelante, estuve trabajando con un colega en la creaci\u00f3n de sitios de <a href=\"https:\/\/wordpress.com\/\">WordPress<\/a>. Uno de los proyectos implicaba WPML, por lo que compr\u00f3 la licencia. Poco despu\u00e9s, recibi\u00f3 un correo de reclutamiento y me lo envi\u00f3. Parec\u00eda interesante y ten\u00eda muchas ganas de probar mis habilidades con el objetivo de mejorar mi carrera. Primero conoc\u00ed a Laura de Figueiredo, la Directora de RRHH. Luego me pidieron que hiciera una entrevista t\u00e9cnica. Debo haber causado una buena impresi\u00f3n porque consegu\u00ed entrar ;)<\/p>\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo te ha ayudado la OTGS en tu desarrollo profesional?<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-medium\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/rock.jpg\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/rock-225x300.jpg\" alt=\"\" class=\"wp-image-6389 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 225px; --smush-placeholder-aspect-ratio: 225\/300;\" \/><\/a><figcaption class=\"wp-element-caption\">  Esperando con mi hijo mayor (Mateo) a que empiece un concierto de rock  <\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Cuando empec\u00e9 a trabajar con sitios web, era un usuario habitual de WP. Copi\u00e9\/pegu\u00e9 algunas funciones y cambi\u00e9 algunos estilos, pero en aquella \u00e9poca no entend\u00eda realmente lo que hac\u00eda.  <\/p>\n\n<p class=\"wp-block-paragraph\">Yo era m\u00e1s del tipo \u00abs\u00edndrome del impostor\u00bb, as\u00ed que esperaba que me pillaran. Pero despu\u00e9s de casi cinco a\u00f1os, empiezo a pensar que \u00a1algo debo estar haciendo bien!<\/p>\n\n<p class=\"wp-block-paragraph\">Pas\u00e9 los 3 primeros a\u00f1os dando soporte de primer nivel, ayudando a los clientes a hacer que sus sitios WordPress fueran multiling\u00fces. La experiencia que adquir\u00ed fue inestimable. Aprend\u00ed mucho sobre el apoyo, los distintos procesos y el trabajo a distancia con otras personas.<\/p>\n\n<p class=\"wp-block-paragraph\">Sigo trabajando con el equipo de soporte de WPML, pero ahora en calidad de soporte de<sup>segundo<\/sup> nivel, un paso adelante en mi carrera. Esto significa que cuando un ticket no puede ser resuelto por un colaborador, le echo un vistazo. Me centro en los problemas de compatibilidad con temas y plugins que a\u00fan no se han probado. Esto puede implicar depurar nuestro propio c\u00f3digo utilizando algunas herramientas avanzadas y tambi\u00e9n depurar el c\u00f3digo desarrollado por otros. Adem\u00e1s, presto apoyo a nuestros socios proveedores de servicios ling\u00fc\u00edsticos y a sus clientes.<\/p>\n\n<p class=\"wp-block-paragraph\">Estoy especialmente orgulloso de WPSandbox, una herramienta que ayud\u00e9 a implementar y que nos ayud\u00f3 mucho en nuestro flujo de trabajo de pruebas de compatibilidad. Tomando mi carrera en mis propias manos, he tomado la iniciativa de trabajar en su sustituci\u00f3n.  <\/p>\n\n<p class=\"wp-block-paragraph\">Antes interactuaba sobre todo con el equipo de Soporte, pero recientemente me han pedido que trabaje con el equipo de Compatibilidad, ICanLocalize, Soporte de Herramientas y el equipo de ATE\/Proxy, otro hito en mi carrera Mis compa\u00f1eros m\u00e1s cercanos proceden de diversos pa\u00edses (Argentina, Espa\u00f1a, Chile, Rusia, Egipto, India y Chipre). Todos son geniales, sin malentendidos ni choques de personalidad hasta ahora :)  <\/p>\n\n<p class=\"wp-block-paragraph\">Tengo que decir que la OTGS ha cambiado mucho desde que me incorpor\u00e9 a la empresa. Ha crecido r\u00e1pidamente y ahora somos casi el doble de personas&#8230; Pero la esencia est\u00e1 intacta. Sigue siendo una empresa solidaria y eso, creo, es la clave para desarrollar mi carrera. La empresa y mis compa\u00f1eros siempre muestran respeto y aprecio por mi trabajo. Es realmente gratificante, y un enorme placer trabajar con un equipo tan estupendo.<\/p>\n\n<h2 class=\"wp-block-heading\">Es estupendo escuchar c\u00f3mo se ha desarrollado tu carrera y al mismo tiempo trabajas desde tu casa. \u00bfQu\u00e9 hay de otras oportunidades?<\/h2>\n\n<p class=\"wp-block-paragraph\">Trabajar en OTGS me impuls\u00f3 y me dio la oportunidad de hablar en dos WordCamps: Buenos Aires y Sao Paulo. Fue un reto y mucho trabajo y estaba nerviosa, pero ahora queda muy bien en mi CV :)<\/p>\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n di charlas en meetups y particip\u00e9 activamente en la comunidad WP Argentina. He cofundado los meetups de WordPress de La Plata y asisto regularmente a los meetups mensuales de WP Buenos Aires.<\/p>\n\n<p class=\"wp-block-paragraph\">Trabajar desde casa en OnTheGoSystems ha aumentado realmente mis expectativas profesionales. Por fin he superado los d\u00edas de paro y depresiones. Encontr\u00e9 fuerza y, junto con otras fuentes de ayuda, paz interior con la meditaci\u00f3n Vipassana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabajar desde casa, \u00bfte har\u00e1 \u00abinvisible\u00bb? \u00bfC\u00f3mo puedes impresionar a tu equipo y a tu jefe de equipo y conseguir buenas evaluaciones de rendimiento y ascensos?<\/p>\n<p>El Empleado del Mes de este mes, Otto Federico Wald, de Argentina.<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[],"class_list":["post-18918","post","type-post","status-publish","format-standard","hentry","category-conoce-a-nuestro-equipo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otto Wald - \u00bfEs posible desarrollar tu carrera trabajando desde casa? - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otto Wald - \u00bfEs posible desarrollar tu carrera trabajando desde casa? - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Trabajar desde casa, \u00bfte har\u00e1 &quot;invisible&quot;? \u00bfC\u00f3mo puedes impresionar a tu equipo y a tu jefe de equipo y conseguir buenas evaluaciones de rendimiento y ascensos? El Empleado del Mes de este mes, Otto Federico Wald, de Argentina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:28:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-03T07:28:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/futbol-225x300.jpg\" \/>\n<meta name=\"author\" content=\"Helena Petridou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Petridou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/\"},\"author\":{\"name\":\"Helena Petridou\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\"},\"headline\":\"Otto Wald &#8211; \u00bfEs posible desarrollar tu carrera trabajando desde casa?\",\"datePublished\":\"2024-06-03T07:28:34+00:00\",\"dateModified\":\"2024-06-03T07:28:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/\"},\"wordCount\":945,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/futbol-225x300.jpg\",\"articleSection\":[\"Conoce a nuestro equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/\",\"name\":\"Otto Wald - \u00bfEs posible desarrollar tu carrera trabajando desde casa? - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/futbol-225x300.jpg\",\"datePublished\":\"2024-06-03T07:28:34+00:00\",\"dateModified\":\"2024-06-03T07:28:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/futbol-225x300.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/futbol-225x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/01\\\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otto Wald &#8211; \u00bfEs posible desarrollar tu carrera trabajando desde casa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\",\"name\":\"Helena Petridou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"caption\":\"Helena Petridou\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/author\\\/helena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otto Wald - \u00bfEs posible desarrollar tu carrera trabajando desde casa? - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/","og_locale":"es_ES","og_type":"article","og_title":"Otto Wald - \u00bfEs posible desarrollar tu carrera trabajando desde casa? - OnTheGoSystems","og_description":"Trabajar desde casa, \u00bfte har\u00e1 \"invisible\"? \u00bfC\u00f3mo puedes impresionar a tu equipo y a tu jefe de equipo y conseguir buenas evaluaciones de rendimiento y ascensos? El Empleado del Mes de este mes, Otto Federico Wald, de Argentina.","og_url":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:28:34+00:00","article_modified_time":"2024-06-03T07:28:50+00:00","og_image":[{"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/futbol-225x300.jpg","type":"","width":"","height":""}],"author":"Helena Petridou","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Helena Petridou","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/"},"author":{"name":"Helena Petridou","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555"},"headline":"Otto Wald &#8211; \u00bfEs posible desarrollar tu carrera trabajando desde casa?","datePublished":"2024-06-03T07:28:34+00:00","dateModified":"2024-06-03T07:28:50+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/"},"wordCount":945,"publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/futbol-225x300.jpg","articleSection":["Conoce a nuestro equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/","url":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/","name":"Otto Wald - \u00bfEs posible desarrollar tu carrera trabajando desde casa? - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/futbol-225x300.jpg","datePublished":"2024-06-03T07:28:34+00:00","dateModified":"2024-06-03T07:28:50+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/futbol-225x300.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/01\/futbol-225x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/es\/2020\/01\/otto-wald-es-posible-desarrollar-tu-carrera-trabajando-desde-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/es\/"},{"@type":"ListItem","position":2,"name":"Otto Wald &#8211; \u00bfEs posible desarrollar tu carrera trabajando desde casa?"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/es\/#website","url":"https:\/\/onthegosystems.com\/es\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/es\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555","name":"Helena Petridou","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","caption":"Helena Petridou"},"url":"https:\/\/onthegosystems.com\/es\/author\/helena\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/18918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/comments?post=18918"}],"version-history":[{"count":1,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/18918\/revisions"}],"predecessor-version":[{"id":18920,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/18918\/revisions\/18920"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media?parent=18918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/categories?post=18918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/tags?post=18918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}