{"id":20185,"date":"2017-06-22T08:48:30","date_gmt":"2024-06-03T07:38:06","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/"},"modified":"2024-06-03T07:38:06","modified_gmt":"2024-06-03T07:38:06","slug":"selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/","title":{"rendered":"Selena Salustri &#8211; \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas!"},"content":{"rendered":"<p><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Selena.jpg\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Selena.jpg\" alt=\"\" width=\"276\" height=\"413\" class=\"alignleft size-full wp-image-3900 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 276px; --smush-placeholder-aspect-ratio: 276\/413;\"><\/a><\/p>\n<h2>Selena, cu\u00e9ntanos c\u00f3mo te uniste a la OTGS.<\/h2>\n<p>Estaba haciendo un trabajo para un cliente y mi novio me sugiri\u00f3 utilizar WPML para las traducciones. Yo era muy nuevo en WordPress y por eso decid\u00ed comprar WPML. Todo el mundo dec\u00eda que era la mejor, as\u00ed que fui a por ella. Alg\u00fan tiempo despu\u00e9s de comprar el plugin, recib\u00ed un correo electr\u00f3nico que dec\u00eda que OnTheGoSystems estaba buscando gente nueva para unirse a la empresa. Como en aquel momento estaba buscando un trabajo de verdad, decid\u00ed intentarlo y me present\u00e9 a los puestos de colaborador y probador. Laura me dijo que no buscaban simpatizantes, pero que s\u00ed necesitaban probadores. Despu\u00e9s conoc\u00ed a Andrea Sciamanna, mi entrevistadora. No ten\u00eda experiencia y, aunque la entrevista me pareci\u00f3 un reto, no fue dif\u00edcil. Debo admitir, sin embargo, que estaba muy ansiosa, sobre todo por los aspectos te\u00f3ricos y pr\u00e1cticos de las pruebas. Finalmente me un\u00ed a la OTGS en diciembre de 2014.<\/p>\n<h2>Llevas bastante tiempo en la OTGS, \u00bfen qu\u00e9 est\u00e1s trabajando ahora?<\/h2>\n<figure id=\"attachment_3898\" aria-describedby=\"caption-attachment-3898\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Company-event-in-Porto.jpg\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Company-event-in-Porto-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" class=\"size-medium wp-image-3898 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/187;\"><\/a><figcaption id=\"caption-attachment-3898\" class=\"wp-caption-text\">Evento de empresa en Oporto<\/figcaption><\/figure>\n<p>Como habr\u00e1s deducido, mi tarea principal es la realizaci\u00f3n de pruebas. Esto implica no s\u00f3lo probar y comprobar las funcionalidades de las implementaciones nuevas\/antiguas despu\u00e9s de cada actualizaci\u00f3n, sino tambi\u00e9n investigar los problemas notificados y escalarlos adecuadamente siempre que sea necesario.<br \/>\nRecientemente, he empezado a ocuparme de la configuraci\u00f3n de un sitio de pruebas en un entorno multisitio y de la configuraci\u00f3n local r\u00e1pida, siempre que me lo piden. As\u00ed que tambi\u00e9n apoyo a otros equipos proporcion\u00e1ndoles acceso a los sitios al entorno de pruebas.<\/p>\n<p>Junto con mis tareas de pruebas, mantengo un sitio interno con informaci\u00f3n sobre las funciones y asignaciones de funciones de cada empleado de la familia OnTheGoSystems. Este sitio debe estar actualizado, ya que es posible que nuestros empleados deseen solicitar nuevos puestos a medida que est\u00e9n disponibles.<\/p>\n<p>Hace unos meses, ayud\u00e9 temporalmente en la formaci\u00f3n de los Simpatizantes. De hecho, yo aportaba mi contribuci\u00f3n explicando las funcionalidades espec\u00edficas de nuestro sistema que eran poco conocidas o que no estaban suficientemente claras. Ahora tenemos todo esto f\u00e1cilmente disponible en nuestra documentaci\u00f3n. Esta tarea fue realmente y fuera de lo com\u00fan para m\u00ed y disfrut\u00e9 mucho haci\u00e9ndola.<\/p>\n<h2>En tu opini\u00f3n, \u00bfqu\u00e9 cualidad de tu personalidad es absolutamente necesaria para tener \u00e9xito en tu trabajo?<\/h2>\n<p>Despu\u00e9s de 2 a\u00f1os y medio cubriendo el puesto de pruebas, he llegado a comprender que la clave es la \u00aborganizaci\u00f3n\u00bb. \u00a1Debo admitir que ser organizada es algo que a menudo se me escapa!<\/p>\n<p>Ser organizado es tanto mental como pr\u00e1ctico. Cuando la cuesti\u00f3n est\u00e1 clara en la mente, los siguientes pasos se dan f\u00e1cilmente. En realidad, esto ayuda a la hora de comunicarse con otros equipos para escalar los problemas m\u00e1s r\u00e1pidamente y evitar perder el tiempo. Intentar ser pr\u00e1cticamente organizada me ayuda a trabajar sin problemas con los dem\u00e1s y reduce el estr\u00e9s. Se muestra en cada fase de las pruebas. A veces hay fracasos y tengo que volver a empezar. Pero estoy dispuesta a aprender. Por supuesto, mis estudios universitarios me han ayudado a comprender y manejar con m\u00e1s eficacia las tareas que me han encomendado, pero quiero decir que aprendo mucho m\u00e1s al trabajar a diario con personas incre\u00edbles y con talento.<\/p>\n<h2>\u00bfCon qu\u00e9 equipos y empleados trabajas estrechamente?<\/h2>\n<figure id=\"attachment_3901\" aria-describedby=\"caption-attachment-3901\" style=\"width: 200px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/WCEU-2015.jpg\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/WCEU-2015-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" class=\"size-medium wp-image-3901 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 200px; --smush-placeholder-aspect-ratio: 200\/300;\"><\/a><figcaption id=\"caption-attachment-3901\" class=\"wp-caption-text\">WCEU 2015<\/figcaption><\/figure>\n<p>Trabajo a diario con Ana, nuestra Jefa de Equipo de Sistemas, Abdallah y, sobre todo, con Emerson junto con Kasia, del equipo de Front-End. Debido a mi puesto de pruebas y a que formo parte del Equipo de Sistemas, estoy en contacto con varios equipos. Durante la \u00faltima versi\u00f3n, trabaj\u00e9 estrechamente con el Equipo de Herramientas, y ahora estoy trabajando con el Equipo de Marketing para nuestros sitios de Referencia y Formaci\u00f3n. Adem\u00e1s, para la gesti\u00f3n del sitio interno de Role, estoy en contacto con todos los equipos.<\/p>\n<h2>\u00bfC\u00f3mo te las arreglas para trabajar con personas que viven en una zona horaria diferente?<\/h2>\n<p>\u00a1Esto es algo que me gusta mucho hacer!<br \/>\nEs importante que cuando organice mi jornada me centre en la zona horaria de mis compa\u00f1eros de trabajo. Por ejemplo:<br \/>\nEstoy en contacto sobre todo con Emerson de Filipinas, as\u00ed que tengo que combinar mis pruebas con su trabajo. B\u00e1sicamente, intento cubrir las cosas m\u00e1s urgentes por la ma\u00f1ana (su tarde), y me pongo al d\u00eda con las pruebas por la tarde (su noche), de modo que cualquier asunto nuevo que comunique pueda tratarse por la ma\u00f1ana (mi tarde\/noche). Con suerte, la mayor\u00eda de los casos estar\u00e1n listos para las pruebas al d\u00eda siguiente, a la ma\u00f1ana siguiente. :D<\/p>\n<h2>\u00bfC\u00f3mo te comunicas?<\/h2>\n<p>Todas las comunicaciones se realizan por correo electr\u00f3nico, Skype y Slack. Las reuniones se realizan en Hangouts o en llamadas de grupo de Skype (pero principalmente en Hangouts).<br \/>\nCuriosamente, y esto es en casos muy espor\u00e1dicos, recibo llamadas tambi\u00e9n con Whatsapp. De hecho, WhatsApp es muy pr\u00e1ctico para llamadas directas y r\u00e1pidas cuando yo o la otra parte, no estamos delante del PC. La llamada no tiene coste adicional y todo el mundo tiene WhatsApp. ;)<\/p>\n<h2>\u00bfQu\u00e9 ocurre si hay un corte de electricidad?<\/h2>\n<p>Los cortes de electricidad suelen producirse en los peores momentos. Cuando sufro un corte de luz, ya estoy preparado para trabajar con mi port\u00e1til utilizando mi smartphone o un TP-Link.<\/p>\n<p>H\u00e1blanos de tu equipo: \u00bfos llev\u00e1is bien? \u00bfHay ocasiones en las que hay malentendidos o choques de personalidad? \u00bfC\u00f3mo manejas estas situaciones?<\/p>\n<p>En nuestro equipo, tenemos una persona clave especial que maneja las situaciones de gran tensi\u00f3n sin \u00abestr\u00e9s\u00bb. Ana es la que interviene antes de que una situaci\u00f3n degenere. Desde mi punto de vista, esto nos ayuda a todos a mantener un enfoque muy positivo y fresco del trabajo. Por supuesto, a veces tenemos algunos malentendidos, pero cuando esto ocurre, Ana reconoce el peligro potencial antes que nosotros y modera la situaci\u00f3n para aclarar las cosas y ponernos a todos de nuevo en marcha, centrados en la tarea que tenemos entre manos. Pero estas disputas se deben \u00fanicamente a nuestro enfoque apasionado de nuestro trabajo. Hasta ahora, nunca he tenido ning\u00fan enfrentamiento con nadie, a pesar de que todos somos de pa\u00edses distintos y tenemos personalidades y or\u00edgenes diferentes.<\/p>\n<h2>\u00bfEn la OTGS hay oportunidades para ampliar y enriquecer tu vida?<\/h2>\n<p>Por supuesto. Me alegra decir que me he implicado m\u00e1s en la Comunidad WP italiana. He asistido a los 3 \u00faltimos eventos WordCamp en Italia como voluntaria y he podido asistir a las 2 \u00faltimas conferencias WordCamp en Europa. Fueron grandes oportunidades para conocer a mis colegas de otros pa\u00edses, al menos a algunos de ellos. Tambi\u00e9n ser\u00e9 voluntaria en el pr\u00f3ximo WCEU de Par\u00eds. \u00a1Estoy deseando estar all\u00ed!<\/p>\n<p>Mi objetivo actual es estabilizar el Meetup local de WordPress que inici\u00e9 en Avezzano. Sin embargo, hasta ahora no he sido capaz de convertirlo en un acontecimiento creciente. Mi plan es revisar mi enfoque y encontrar un \u00e1ngulo diferente para atraer a m\u00e1s gente que comparta su inter\u00e9s y experiencia con WP.<\/p>\n<h2>\u00bfHay algunas palabras de \u00e1nimo que quieras compartir con nosotros?<\/h2>\n<figure id=\"attachment_3902\" aria-describedby=\"caption-attachment-3902\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/WCEU.jpg\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/WCEU-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"size-medium wp-image-3902 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\"><\/a><figcaption id=\"caption-attachment-3902\" class=\"wp-caption-text\">WCEU<\/figcaption><\/figure>\n<p>Trabajar a distancia puede ser muy dif\u00edcil si el trabajo no est\u00e1 a la altura de nuestras expectativas. \u00a1OTGS es una gran empresa para trabajar! Todo el tiempo hay nuevas formas de crecer y de mirar m\u00e1s lejos de lo que nunca imaginaste. Nunca pens\u00e9 que llegar\u00eda tan lejos cuando empec\u00e9 a trabajar para OnTheGoSystems.<br \/>\nAcepta el reto y nunca te arrepentir\u00e1s. Estoy impaciente por ver qu\u00e9 nuevos retos se me presentar\u00e1n en el futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selena, cu\u00e9ntanos c\u00f3mo te uniste a la OTGS. Estaba haciendo un trabajo para un cliente y mi novio me sugiri\u00f3 utilizar WPML para las traducciones. Yo era muy nuevo en WordPress y por eso decid\u00ed comprar WPML. Todo el mundo dec\u00eda que era la mejor, as\u00ed que fui a por ella. Alg\u00fan tiempo despu\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[],"class_list":["post-20185","post","type-post","status-publish","format-standard","hentry","category-conoce-a-nuestro-equipo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Selena Salustri - \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas! - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selena Salustri - \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas! - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Selena, cu\u00e9ntanos c\u00f3mo te uniste a la OTGS. Estaba haciendo un trabajo para un cliente y mi novio me sugiri\u00f3 utilizar WPML para las traducciones. Yo era muy nuevo en WordPress y por eso decid\u00ed comprar WPML. Todo el mundo dec\u00eda que era la mejor, as\u00ed que fui a por ella. Alg\u00fan tiempo despu\u00e9s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:38:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Selena.jpg\" \/>\n<meta name=\"author\" content=\"Helena Petridou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Petridou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/\"},\"author\":{\"name\":\"Helena Petridou\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\"},\"headline\":\"Selena Salustri &#8211; \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas!\",\"datePublished\":\"2024-06-03T07:38:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/\"},\"wordCount\":1361,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Selena.jpg\",\"articleSection\":[\"Conoce a nuestro equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/\",\"name\":\"Selena Salustri - \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas! - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Selena.jpg\",\"datePublished\":\"2024-06-03T07:38:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Selena.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Selena.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/06\\\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selena Salustri &#8211; \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\",\"name\":\"Helena Petridou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"caption\":\"Helena Petridou\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/author\\\/helena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selena Salustri - \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas! - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/","og_locale":"es_ES","og_type":"article","og_title":"Selena Salustri - \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas! - OnTheGoSystems","og_description":"Selena, cu\u00e9ntanos c\u00f3mo te uniste a la OTGS. Estaba haciendo un trabajo para un cliente y mi novio me sugiri\u00f3 utilizar WPML para las traducciones. Yo era muy nuevo en WordPress y por eso decid\u00ed comprar WPML. Todo el mundo dec\u00eda que era la mejor, as\u00ed que fui a por ella. Alg\u00fan tiempo despu\u00e9s de [&hellip;]","og_url":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:38:06+00:00","og_image":[{"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Selena.jpg","type":"","width":"","height":""}],"author":"Helena Petridou","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Helena Petridou","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/"},"author":{"name":"Helena Petridou","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555"},"headline":"Selena Salustri &#8211; \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas!","datePublished":"2024-06-03T07:38:06+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/"},"wordCount":1361,"publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Selena.jpg","articleSection":["Conoce a nuestro equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/","url":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/","name":"Selena Salustri - \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas! - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Selena.jpg","datePublished":"2024-06-03T07:38:06+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Selena.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/06\/Selena.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/es\/2017\/06\/selena-salustri-dedicada-apasionada-alegre-y-con-ideas-ingeniosas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Selena Salustri &#8211; \u00a1Dedicada, apasionada, alegre y con ideas ingeniosas!"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/es\/#website","url":"https:\/\/onthegosystems.com\/es\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/es\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555","name":"Helena Petridou","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","caption":"Helena Petridou"},"url":"https:\/\/onthegosystems.com\/es\/author\/helena\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/20185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/comments?post=20185"}],"version-history":[{"count":0,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/20185\/revisions"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media?parent=20185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/categories?post=20185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/tags?post=20185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}