{"id":20203,"date":"2017-04-18T08:34:21","date_gmt":"2024-06-03T07:38:12","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/y-la-primavera-trajo-muchos-wordcamps\/"},"modified":"2024-06-03T07:38:12","modified_gmt":"2024-06-03T07:38:12","slug":"y-la-primavera-trajo-muchos-wordcamps","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/","title":{"rendered":"Y la primavera trajo muchos WordCamps"},"content":{"rendered":"<p><strong>Tras el pasado comienzo fren\u00e9tico en la India, la primavera lleg\u00f3 con mucha actividad en todo el mundo, desde Norteam\u00e9rica hasta Asia. Tuvimos nuevos organizadores y ponentes, por eso queremos compartir contigo noticias sobre nuestros pr\u00f3ximos WordCamps.<\/strong><\/p>\n<h2>WordCamp Atlanta<\/h2>\n<figure id=\"attachment_3808\" aria-describedby=\"caption-attachment-3808\" style=\"width: 260px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-atlanta.jpg\"><img decoding=\"async\" class=\"wp-image-3808 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-atlanta-450x600.jpg\" alt=\"WordCamp Atlanta\" width=\"260\" height=\"347\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-atlanta-450x600.jpg 450w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-atlanta-225x300.jpg 225w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-atlanta.jpg 1224w\" data-sizes=\"(max-width: 260px) 100vw, 260px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 260px; --smush-placeholder-aspect-ratio: 260\/347;\" \/><\/a><figcaption id=\"caption-attachment-3808\" class=\"wp-caption-text\">WordCamp Atlanta<\/figcaption><\/figure>\n<p><strong>Lauren Jeffcoat<\/strong> colabor\u00f3 en <a href=\"https:\/\/2017.atlanta.wordcamp.org\/\">WordCamp Atlanta<\/a> hablando sobre <em>C\u00f3mo conseguir una audiencia global: La importancia de la traducci\u00f3n de sitios web. <\/em>En sus propias palabras:<\/p>\n<blockquote><p>\u00abWordCamp Atlanta fue una gran experiencia para m\u00ed. Fue el mayor campamento al que he asistido y en el que he presentado: \u00a1675 asistentes inscritos! Me lo pas\u00e9 muy bien haciendo contactos y hablando sobre WPML.<\/p>\n<p>Tuve la mejor sesi\u00f3n de preguntas y respuestas que he tenido nunca en ning\u00fan campamento. Los asistentes abr\u00edan sus port\u00e1tiles al final de la sesi\u00f3n y pas\u00e9 30 minutos m\u00e1s hablando con ellos sobre lo que pod\u00eda hacer WPML. Hubo muchas preguntas sobre la traducci\u00f3n autom\u00e1tica frente a la manual. Ha sido una gran sesi\u00f3n\u00bb.<\/p><\/blockquote>\n<p>Y si sientes curiosidad por su sesi\u00f3n, aqu\u00ed puedes ir a sus diapositivas. Compartiremos su charla en cuanto la tengamos en wordpress.tv.<\/p>\n<p><iframe style=\"border: 1px solid #CCC; border-width: 1px; margin-bottom: 5px; max-width: 100%;\" data-src=\"\/\/www.slideshare.net\/slideshow\/embed_code\/key\/Jo5PFE2qSeUmcV\" width=\"595\" height=\"485\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"> <\/iframe><\/p>\n<h2>WordCamp Miami<\/h2>\n<p>Apenas un par de meses despu\u00e9s de convertirse en OTGsian, <strong>Meagan Hanes <\/strong>ya estaba hablando en <a href=\"https:\/\/2017.miami.wordcamp.org\/\">WordCamp<\/a> Miami sobre <em>C\u00f3mo extender WordPress m\u00e1s all\u00e1 de un simple blog<\/em>. Como ella dice:<\/p>\n<blockquote><p>\u00abGracias a todo el equipo de nuestra empresa, pude asistir a uno de los mejores WordCamps de Estados Unidos, WordCamp Miami 2017 y representar a OTGS. Con m\u00e1s de 800 asistentes, \u00a1fue un campamento grande y divertido!\u00bb<\/p><\/blockquote>\n<figure id=\"attachment_3809\" aria-describedby=\"caption-attachment-3809\" style=\"width: 527px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-miami-2.jpg\"><img decoding=\"async\" class=\"wp-image-3809 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-miami-2-600x338.jpg\" alt=\"WordCamp Miami: Inscripci\u00f3n\" width=\"527\" height=\"297\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-miami-2-600x338.jpg 600w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-miami-2-300x169.jpg 300w\" data-sizes=\"(max-width: 527px) 100vw, 527px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 527px; --smush-placeholder-aspect-ratio: 527\/297;\" \/><\/a><figcaption id=\"caption-attachment-3809\" class=\"wp-caption-text\">WordCamp Miami: Inscripci\u00f3n<\/figcaption><\/figure>\n<figure id=\"attachment_3810\" aria-describedby=\"caption-attachment-3810\" style=\"width: 223px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-miami.jpg\"><img decoding=\"async\" class=\"wp-image-3810 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-miami-450x600.jpg\" alt=\"WordCamp Miami: Meagan\" width=\"223\" height=\"297\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-miami-450x600.jpg 450w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-miami-225x300.jpg 225w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-miami.jpg 1920w\" data-sizes=\"(max-width: 223px) 100vw, 223px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 223px; --smush-placeholder-aspect-ratio: 223\/297;\" \/><\/a><figcaption id=\"caption-attachment-3810\" class=\"wp-caption-text\">WordCamp Miami: Meagan<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Si quieres consultar algunos consejos profesionales para ampliar tu WordPress, echa un vistazo a su <a href=\"https:\/\/www.slideshare.net\/mhanes1\">presentaci\u00f3n<\/a>.<\/p>\n<h2>WordCamp Londres<\/h2>\n<p>Al igual que el a\u00f1o pasado, asistimos a <a href=\"https:\/\/2017.london.wordcamp.org\">la WordCamp de<\/a> Londres como patrocinadores <strong>Marine Larmier<\/strong> y yo mismo, <strong>Andr\u00e9s Cifuentes. <\/strong>Fue una gran WordCamp con unos 600 asistentes. \u00a1Todo estaba bien organizado y el ambiente era din\u00e1mico! Fue un fin de semana lleno de trabajo, cultivando relaciones, encontr\u00e1ndonos con viejos amigos y reforzando juntos la comunidad.<\/p>\n<figure id=\"attachment_3814\" aria-describedby=\"caption-attachment-3814\" style=\"width: 530px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wordcamp-london-2.jpg\"><img decoding=\"async\" class=\"wp-image-3814 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wordcamp-london-2-600x337.jpg\" alt=\"WordCamp Londres: Andr\u00e9s, Chris y Marine\" width=\"530\" height=\"298\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wordcamp-london-2-600x337.jpg 600w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wordcamp-london-2-300x169.jpg 300w\" data-sizes=\"(max-width: 530px) 100vw, 530px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 530px; --smush-placeholder-aspect-ratio: 530\/298;\" \/><\/a><figcaption id=\"caption-attachment-3814\" class=\"wp-caption-text\">WordCamp Londres: Andr\u00e9s, Chris y Marine<\/figcaption><\/figure>\n<figure id=\"attachment_3815\" aria-describedby=\"caption-attachment-3815\" style=\"width: 167px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wordcamp-london.jpg\"><img decoding=\"async\" class=\"wp-image-3815 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wordcamp-london-337x600.jpg\" alt=\"WordCamp Londres: un asistente y Marine\" width=\"167\" height=\"332\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 167px; --smush-placeholder-aspect-ratio: 167\/332;\"><\/a><figcaption id=\"caption-attachment-3815\" class=\"wp-caption-text\">WordCamp Londres: un asistente y Marine<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<h2><\/h2>\n<h2><\/h2>\n<h2><\/h2>\n<h2><\/h2>\n<h2><\/h2>\n<h2>WordCamp San Diego:<\/h2>\n<p>\u00bfRecuerdas tu primer WordCamp? Para nuestro OTGSian Bobby Karabinakis, <a href=\"https:\/\/2017.sandiego.wordcamp.org\/\">la WordCamp de San Diego<\/a> fue su primera toma de contacto directa con la comunidad. Se lo pas\u00f3 muy bien durante las charlas, reuniones&#8230; Seg\u00fan \u00e9l:<\/p>\n<blockquote><p>\u00abLa reuni\u00f3n tuvo lugar en el centro de San Diego y fue un placer conocer a otros anfitriones de WooCommerce , WP Engine y otros. Especialmente estimulante fue la experiencia de sumergirse en conversaciones sobre WPML y responder a algunas preguntas. \u00ab<\/p><\/blockquote>\n<figure id=\"attachment_3813\" aria-describedby=\"caption-attachment-3813\" style=\"width: 283px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-san-diego.jpg\"><img decoding=\"async\" class=\"wp-image-3813 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-san-diego-480x600.jpg\" alt=\"WordCamp San Diego: Bobby\" width=\"283\" height=\"354\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-san-diego-480x600.jpg 480w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-san-diego-240x300.jpg 240w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-san-diego.jpg 1991w\" data-sizes=\"(max-width: 283px) 100vw, 283px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 283px; --smush-placeholder-aspect-ratio: 283\/354;\" \/><\/a><figcaption id=\"caption-attachment-3813\" class=\"wp-caption-text\">WordCamp San Diego: Bobby<\/figcaption><\/figure>\n<h2>WordCamp Mumbai<\/h2>\n<figure id=\"attachment_3811\" aria-describedby=\"caption-attachment-3811\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2.jpg\"><img decoding=\"async\" class=\"wp-image-3811 size-large lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2-600x400.jpg\" alt=\"WordCamp Mumbai: Ankit, Bigul, Harshad y Sumit\" width=\"600\" height=\"400\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2-600x400.jpg 600w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2-300x200.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2.jpg 1024w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><\/a><figcaption id=\"caption-attachment-3811\" class=\"wp-caption-text\">WordCamp Mumbai: Ankit, Bigul, Harshad y Sumit<\/figcaption><\/figure>\n<p>Los WordCamps de la India siguen manteniendo su impulso y consolidando la comunidad. Esta vez le toc\u00f3 el turno a <a href=\"https:\/\/2017.mumbai.wordcamp.org\/\">WordCamp Mumbai<\/a>, la mayor WordCamp que se ha celebrado nunca en la India, con unos 600 participantes. <strong>Sumit Singh<\/strong>, <strong>Ankit Gade<\/strong>, <strong>Bigul Malayi<\/strong> y <strong>Harshad Mane <\/strong>no pod\u00edan perderse esta oportunidad. Como dice Bigul<\/p>\n<blockquote><p>\u00abEn general, fue un gran evento. Tuvimos la oportunidad de interactuar con muchas agencias de WordPress y autores de plugins y temas. La mayor\u00eda de los participantes estaban familiarizados con WPML y recibimos excelentes comentarios, especialmente sobre el programa de compatibilidad. Esta vez tambi\u00e9n recibimos muchas preguntas sobre nuestro Toolset. Parece que Toolset no deja de crecer tambi\u00e9n en la India\u00bb.<\/p><\/blockquote>\n<p>Bigul tambi\u00e9n estuvo all\u00ed como uno de los panelistas de un grupo de debate sobre Pruebas Manuales Vs. Pruebas automatizadas, donde le hicieron muchas preguntas relacionadas con nuestro entorno de control de calidad.<\/p>\n<figure id=\"attachment_3812\" aria-describedby=\"caption-attachment-3812\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai.jpg\"><img decoding=\"async\" class=\"size-large wp-image-3812 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-600x400.jpg 600w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-300x200.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai.jpg 1024w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><\/a><figcaption id=\"caption-attachment-3812\" class=\"wp-caption-text\">WordCamp Mumbai: Bigul con camiseta blanca y otros panelistas<\/figcaption><\/figure>\n<h2>WordCamp Torino<\/h2>\n<p><a href=\"https:\/\/2017.torino.wordcamp.org\/\">WordCamp Torino<\/a> fue el escenario para dar la bienvenida a <strong>Francesco Di Candia<\/strong> a nuestra familia OTGS y reunirnos con <strong>Andrea Sciamanna <\/strong>y <strong>Selena Salustri. <\/strong>Francesco es nuestro nuevo miembro de la comunidad italiana, y tambi\u00e9n fue uno de los organizadores de este gran WordCamp. Selena fue voluntaria con energ\u00eda durante el fin de semana y Andrea estuvo all\u00ed tendiendo la mano y hablando con la comunidad de WordPress.<\/p>\n<p>Como todo trabajo duro tiene su recompensa, Selena gan\u00f3 una mochila por su esfuerzo<\/p>\n<figure id=\"attachment_3807\" aria-describedby=\"caption-attachment-3807\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/selena.jpg\"><img decoding=\"async\" class=\"size-large wp-image-3807 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/selena-600x450.jpg\" alt=\"WordCamp Torino: Selena tras ganar una mochila\" width=\"600\" height=\"450\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/selena-600x450.jpg 600w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/selena-300x225.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/selena.jpg 1024w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/450;\" \/><\/a><figcaption id=\"caption-attachment-3807\" class=\"wp-caption-text\">WordCamp Torino: Selena tras ganar una mochila<\/figcaption><\/figure>\n<h2>Pr\u00f3ximos eventos<\/h2>\n<p>Esta vez, har\u00e9 una peque\u00f1a excepci\u00f3n y no empezar\u00e9 cronol\u00f3gicamente como suelo hacer. Para uno de los acontecimientos m\u00e1s importantes de este a\u00f1o,  <a href=\"https:\/\/2017.europe.wordcamp.org\/\">WordCamp Europa 2017<\/a>no s\u00f3lo estamos contentos de ser patrocinadores, sino que tambi\u00e9n estamos orgullosos de anunciar que tendremos  <strong>Dario Jazbec Hrvatin<\/strong>  como ponente, tambi\u00e9n  <strong>Francesco Di Candia  <\/strong>y I (<strong>Andr\u00e9s Cifuentes,  <\/strong>como hemos mencionado anteriormente) como organizadores.  <strong>Selena Salustri <\/strong>tambi\u00e9n compartir\u00e1 su pasi\u00f3n por la comunidad WordPress y estar\u00e1 all\u00ed como voluntaria y haciendo todo lo posible para que el WordCamp sea perfecto.<\/p>\n<p>Parece que abril ser\u00e1 otro mes de actividad.  <strong>Lauren Jeffcoat <\/strong>hablar\u00e1 en <a href=\"https:\/\/2017.raleigh.wordcamp.org\/\">WordCamp Raleigh<\/a> el s\u00e1bado 22 de abril sobre <a href=\"https:\/\/2017.raleigh.wordcamp.org\/session\/destination-anywhere-creating-the-ultimate-dmo-or-directory-website\/\">Destino en cualquier lugar: Creando el mejor sitio web DMO o Directorio.<\/a> El mismo fin de semana, hablar\u00e9 sobre mis propias experiencias en <a href=\"https:\/\/2017.vienna.wordcamp.org\/session\/remote-work-debugging-your-stress-and-improving-your-productivity\/\">Trabajo a distancia: Depurando tu estr\u00e9s y mejorando tu<\/a> productividad en WordCamp Viena.<\/p>\n<p>S\u00f3lo una semana despu\u00e9s, tenemos a nuestro nuevo d\u00fao din\u00e1mico sorprendiendo en <a href=\"https:\/\/2017.chicago.wordcamp.org\/\">WordCamp Chicago<\/a>. Nuestra nueva miembro del equipo <strong>, Meagan Hanes <\/strong>, dar\u00e1 algunos consejos desde su experiencia como bloguera con  <a href=\"https:\/\/2017.chicago.wordcamp.org\/session\/to-the-word-and-beyond-extending-wordpress-past-a-simple-blog\/\">\u00a1A la Palabra y m\u00e1s all\u00e1! Ampliar WordPress m\u00e1s all\u00e1 de un simple blog<\/a>  el domingo 30 de abril. Ese mismo d\u00eda, <strong>Lauren Jeffcoat <\/strong>hablar\u00e1 sobre <a href=\"https:\/\/2017.chicago.wordcamp.org\/session\/support-starts-here-how-to-go-the-extra-mile-to-make-and-keep-your-customers-happy\/\">El apoyo empieza aqu\u00ed: C\u00f3mo hacer un esfuerzo adicional para hacer y MANTENER contentos a tus clientes<\/a>.<\/p>\n<p>Los d\u00edas 13 y 14 de mayo estaremos presentes en <a href=\"https:\/\/2017.belgrade.wordcamp.org\/\">WordCamp Belgrado<\/a>. Junto a <strong>Vuk Vukovic<\/strong>, organizador de este WordCamp, tendremos a <strong>Dario Jazbec Hrvatin <\/strong>y <strong>Mladen Andrejic <\/strong>en la zona de patrocinadores. Adem\u00e1s, \u00a1Dario tambi\u00e9n estar\u00e1 all\u00ed como ponente!<\/p>\n<p>Demos un salto a Asia porque tambi\u00e9n asistiremos a <a href=\"https:\/\/2017.kathmandu.wordcamp.org\/\">WordCamp Katmand\u00fa<\/a>. <strong>Harshad Mane<\/strong> compartir\u00e1 su experiencia con <a href=\"https:\/\/2017.kathmandu.wordcamp.org\/speakers\/\">Unit Testing para WordPress<\/a> el 20 de mayo. Volviendo a Norteam\u00e9rica, durante el mismo fin de semana, <strong>Lauren Jeffcoat <\/strong>se unir\u00e1 a <a href=\"https:\/\/2017.jacksonville.wordcamp.org\/\">WordCamp Jacksonville<\/a> como ponente. Una semana despu\u00e9s, <strong>Meagan Hanes<\/strong> formar\u00e1 parte de un panel de debate sobre <a href=\"https:\/\/2017.halifax.wordcamp.org\/session\/panel-discussion\/\">\u00abRocking A WordPress Business<\/a> \u00bb en <a href=\"https:\/\/2017.halifax.wordcamp.org\/\">WordCamp Halifax<\/a>. Por \u00faltimo, una vez m\u00e1s, nuestra embajadora <strong>Lauren Jeffcoat <\/strong>hablar\u00e1 en <a href=\"https:\/\/2017.portlandme.wordcamp.org\/\">WordCamp Portland<\/a>.<\/p>\n<p>Como puedes ver, \u00a1no hay excusas para no encontrarnos en uno de los muchos WordCamps que se celebran en todo el mundo!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el pasado comienzo fren\u00e9tico en la India, la primavera lleg\u00f3 con mucha actividad en todo el mundo, desde Norteam\u00e9rica hasta Asia. Tuvimos nuevos organizadores y ponentes, por eso queremos compartir contigo noticias sobre nuestros pr\u00f3ximos WordCamps. WordCamp Atlanta Lauren Jeffcoat colabor\u00f3 en WordCamp Atlanta hablando sobre C\u00f3mo conseguir una audiencia global: La importancia de [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":9116,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,152],"tags":[],"class_list":["post-20203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","category-trabajos-e-historias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OnTheGoSystems: Y la primavera trajo muchos WordCamps<\/title>\n<meta name=\"description\" content=\"Y la primavera trajo muchos WordCamps: Comparte las experiencias de nuestros ponentes, organizadores y voluntarios OTGSianos durante los WordCamps. Pr\u00f3ximos eventos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OnTheGoSystems: Y la primavera trajo muchos WordCamps\" \/>\n<meta property=\"og:description\" content=\"Y la primavera trajo muchos WordCamps: Comparte las experiencias de nuestros ponentes, organizadores y voluntarios OTGSianos durante los WordCamps. Pr\u00f3ximos eventos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:38:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andr\u00e9s Cifuentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9s Cifuentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/\"},\"author\":{\"name\":\"Andr\u00e9s Cifuentes\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/f1cc327c0559d348fc6342790d5d7966\"},\"headline\":\"Y la primavera trajo muchos WordCamps\",\"datePublished\":\"2024-06-03T07:38:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/\"},\"wordCount\":1172,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/wc-mumbai-2.jpg\",\"articleSection\":[\"Sin categorizar\",\"Trabajos e Historias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/\",\"name\":\"OnTheGoSystems: Y la primavera trajo muchos WordCamps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/wc-mumbai-2.jpg\",\"datePublished\":\"2024-06-03T07:38:12+00:00\",\"description\":\"Y la primavera trajo muchos WordCamps: Comparte las experiencias de nuestros ponentes, organizadores y voluntarios OTGSianos durante los WordCamps. Pr\u00f3ximos eventos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/wc-mumbai-2.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/wc-mumbai-2.jpg\",\"width\":1024,\"height\":683,\"caption\":\"WordCamp Mumbai: Ankit, Bigul, Harshad and Sumit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2017\\\/04\\\/y-la-primavera-trajo-muchos-wordcamps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Y la primavera trajo muchos WordCamps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/f1cc327c0559d348fc6342790d5d7966\",\"name\":\"Andr\u00e9s Cifuentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g\",\"caption\":\"Andr\u00e9s Cifuentes\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/author\\\/andres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OnTheGoSystems: Y la primavera trajo muchos WordCamps","description":"Y la primavera trajo muchos WordCamps: Comparte las experiencias de nuestros ponentes, organizadores y voluntarios OTGSianos durante los WordCamps. Pr\u00f3ximos eventos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/","og_locale":"es_ES","og_type":"article","og_title":"OnTheGoSystems: Y la primavera trajo muchos WordCamps","og_description":"Y la primavera trajo muchos WordCamps: Comparte las experiencias de nuestros ponentes, organizadores y voluntarios OTGSianos durante los WordCamps. Pr\u00f3ximos eventos.","og_url":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:38:12+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2.jpg","type":"image\/jpeg"}],"author":"Andr\u00e9s Cifuentes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andr\u00e9s Cifuentes","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/"},"author":{"name":"Andr\u00e9s Cifuentes","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/f1cc327c0559d348fc6342790d5d7966"},"headline":"Y la primavera trajo muchos WordCamps","datePublished":"2024-06-03T07:38:12+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/"},"wordCount":1172,"publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2.jpg","articleSection":["Sin categorizar","Trabajos e Historias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/","url":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/","name":"OnTheGoSystems: Y la primavera trajo muchos WordCamps","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2.jpg","datePublished":"2024-06-03T07:38:12+00:00","description":"Y la primavera trajo muchos WordCamps: Comparte las experiencias de nuestros ponentes, organizadores y voluntarios OTGSianos durante los WordCamps. Pr\u00f3ximos eventos.","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2017\/04\/wc-mumbai-2.jpg","width":1024,"height":683,"caption":"WordCamp Mumbai: Ankit, Bigul, Harshad and Sumit"},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/es\/2017\/04\/y-la-primavera-trajo-muchos-wordcamps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/es\/"},{"@type":"ListItem","position":2,"name":"Y la primavera trajo muchos WordCamps"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/es\/#website","url":"https:\/\/onthegosystems.com\/es\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/es\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/f1cc327c0559d348fc6342790d5d7966","name":"Andr\u00e9s Cifuentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g","caption":"Andr\u00e9s Cifuentes"},"url":"https:\/\/onthegosystems.com\/es\/author\/andres\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/20203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/comments?post=20203"}],"version-history":[{"count":0,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/20203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media\/9116"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media?parent=20203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/categories?post=20203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/tags?post=20203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}