{"id":20508,"date":"2022-04-25T05:11:00","date_gmt":"2024-06-03T07:40:00","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/"},"modified":"2025-09-08T07:50:12","modified_gmt":"2025-09-08T07:50:12","slug":"abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/","title":{"rendered":"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir"},"content":{"rendered":"\n<p class=\"lead\">La estrella del mes, Abdallah Deeb, nos cuenta c\u00f3mo comenz\u00f3 su amor por las computadoras, c\u00f3mo trabajar de manera m\u00e1s inteligente y qui\u00e9n manda en su casa.<\/p>\n\n<h2 class=\"wp-block-heading\">Abdallah, cu\u00e9ntanos sobre ti.<\/h2>\n\n<p>Soy del L\u00edbano, nacido y criado en la ciudad de Beirut.<\/p>\n\n<p>Durante mi adolescencia, descubr\u00ed mi inter\u00e9s por la tecnolog\u00eda. Las PC reci\u00e9n comenzaban a ser asequibles, as\u00ed que mis hermanos y yo junt\u00e1bamos nuestros ahorros cada mes para comprar una computadora 386 a plazos. Tan pronto como compramos nuestra computadora, comenzamos a aprender los entresijos de la misma (y, admit\u00e1moslo, nos dedicamos a algunos juegos). Los tres hermanos terminamos estudiando carreras relacionadas con la inform\u00e1tica.   <\/p>\n\n<p>Estoy casado y tenemos un gato llamado Naruto. Naci\u00f3 en nuestra sala de estar en 2012, y es seguro decir que ahora es el due\u00f1o del apartamento en el que vivimos. Cualquiera que haya estado en una reuni\u00f3n por video conmigo seguramente ha visto su regordete ser pelirrojo en la c\u00e1mara.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\" tb-image tb-image-dynamic tb-image-frame-none aligncenter\" data-toolset-blocks-image=\"a79f2d364e633251b7a9788babc45172\"><img decoding=\"async\" width=\"1024\" height=\"461\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image1-1024x461.jpg\" alt=\"\" class=\"wp-image-13838 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image1-1024x461.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image1-300x135.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image1-1536x691.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image1.jpg 1999w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/461;\" \/><figcaption><div class=\"tb-image-caption\"><em>Naruto, tambi\u00e9n conocido como el jefe de la casa<\/em><\/div><\/figcaption><\/figure>\n<\/div>\n<p>Ah, y est\u00e1 Keira, la feliz labrador negro que adoptamos hace 3 a\u00f1os. Ella me hace sonre\u00edr. En realidad, hace sonre\u00edr a todos los que la rodean. Est\u00e1 acostada a mi lado mientras escribo esto, como siempre. Intento llevarla de excursi\u00f3n y de campamento tanto como sea posible, especialmente los fines de semana cuando hace buen tiempo.    <\/p>\n<div class=\"wp-block-image\">\n<figure class=\" tb-image tb-image-dynamic tb-image-frame-none aligncenter\" data-toolset-blocks-image=\"5e088ef71b7f971e523cbc5140de73e2\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image2.jpg\" alt=\"\" class=\"wp-image-13840 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image2.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image2-300x225.jpg 300w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption><div class=\"tb-image-caption\"><em>La perra de Abdallah, Kiera<\/em><\/div><\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\">\u00bfPodr\u00eda describir su trabajo en OnTheGoSystems?<\/h2>\n\n<p>Estoy en el equipo de Sistemas. En resumen, estamos a cargo de mantener todo funcionando de la manera m\u00e1s fluida posible. Los clientes, empleados y colegas de OTGS son nuestra principal preocupaci\u00f3n. Queremos que todos puedan acceder a nuestros sitios sin ning\u00fan problema y tener una experiencia r\u00e1pida y fluida all\u00ed. Nuestro objetivo es facilitar la vida de todos y eliminar cualquier obst\u00e1culo en su camino.    <\/p>\n\n<p>Como dice el lema de OTGS, conc\u00e9ntrese en trabajar de manera m\u00e1s inteligente. Como equipo de Sistemas, lo hacemos adoptando una mejor manera de administrar la infraestructura como c\u00f3digo. Cambiamos a una mentalidad DevOps hace algunos a\u00f1os, pensando en nuestra infraestructura como un proyecto de desarrollo de software en lugar de una configuraci\u00f3n de hardware monol\u00edtica. Esto nos permiti\u00f3 pasar de ejecutar unos pocos servidores dedicados a literalmente cientos de servidores que se activan y terminan seg\u00fan sea necesario.   <\/p>\n\n<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"dcce18c538c0c16ad36e61f88710cdea\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image3.jpg\" alt=\"\" class=\"wp-image-13842 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image3.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image3-300x225.jpg 300w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption><div class=\"tb-image-caption\"><em>Abdallah con su perro en una excursi\u00f3n<\/em><\/div><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 cosas ha aprendido desde que comenz\u00f3 a trabajar en OnTheGoSystems?<\/h2>\n\n<p>Gracias a OTGS, me siento motivado para seguir encontrando diferentes formas de sobresalir en mi trabajo. Recientemente, termin\u00e9 el <a href=\"https:\/\/www.udacity.com\/course\/site-reliability-engineer-nanodegree--nd087\">nano grado de Ingeniero de Confiabilidad del Sitio en udacity.com<\/a>. <\/p>\n\n<p>Esto me ense\u00f1\u00f3 nuevas habilidades y mucho sobre monitoreo, planificaci\u00f3n para alta disponibilidad, preparaci\u00f3n y respuesta a incidentes. Los cursos enfatizaron la importancia de establecer una cultura de confiabilidad y c\u00f3mo desarrollar procesos y marcos que impulsen a los lugares de trabajo a priorizar la confiabilidad. Esto incluye c\u00f3mo realizar revisiones de confiabilidad en nuestros sistemas, c\u00f3mo administrar la capacidad y c\u00f3mo reducir el trabajo pesado. Estoy ansioso por aplicar lo que aprend\u00ed a las tareas diarias que enfrentamos en el equipo de Sistemas.   <\/p>\n\n<p>Nuestros proyectos actualmente est\u00e1n cambiando hacia un proceso m\u00e1s de Infraestructura como C\u00f3digo (IaC). Toda nuestra planificaci\u00f3n e implementaciones se realizan en Git y pasan por las mismas revisiones que cualquier otro proyecto de software. Gracias a esto, me estoy volviendo m\u00e1s eficiente en el uso de herramientas como Terraform, Ansible y GitLab-CI. Estoy ansioso por compartir lo que he aprendido con cualquiera que quiera unirse al equipo de Sistemas o est\u00e9 interesado en estas tecnolog\u00edas.   <\/p>\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1l es la parte m\u00e1s desafiante de su trabajo y c\u00f3mo la supera?<\/h2>\n\n<p>La parte m\u00e1s desafiante de este trabajo es mantenerse al d\u00eda con todas las nuevas tecnolog\u00edas y metodolog\u00edas que est\u00e1n disponibles. Al mismo tiempo, debe mantenerse enfocado en terminar el trabajo en cuesti\u00f3n.  <\/p>\n\n<p>Por ejemplo, algunas de las herramientas con las que comenc\u00e9 a trabajar hace un par de a\u00f1os han sufrido cambios importantes o han sido reemplazadas por completo por otras nuevas. Debe mantenerse al d\u00eda. De lo contrario, corre el riesgo de hacer las cosas de manera menos eficiente, o incluso mal. Seguir con una herramienta o paquete antiguo podr\u00eda causar un riesgo de seguridad.   <\/p>\n\n<h2 class=\"wp-block-heading\">Como trabajador remoto, \u00bfc\u00f3mo es un d\u00eda t\u00edpico para usted?<\/h2>\n\n<p>Un d\u00eda t\u00edpico para m\u00ed comienza caminando o corriendo con mi perra, Keira. Recorremos el vecindario o deambulamos por los peque\u00f1os jardines y parques de la zona.  <\/p>\n\n<p>Una vez que regreso, enciendo mi PC, \u00a1y la m\u00e1quina de caf\u00e9! Por lo general, termino tomando algunas tazas antes de la reuni\u00f3n de la ma\u00f1ana con el resto de mi equipo. Mis ma\u00f1anas implican mucha codificaci\u00f3n y pruebas. Tengo todas estas ideas diferentes nadando en mi cabeza desde la noche anterior, as\u00ed que trato de aplicarlo todo antes de que comiencen a llegar solicitudes externas.   <\/p>\n\n<p>La reuni\u00f3n diaria luego trae las prioridades del equipo para el d\u00eda, que a veces superan cualquier cosa en la que ya comenc\u00e9 a trabajar. Ayudo a resolver problemas y monitoreo nuestros sistemas de cerca para solucionar cualquier problema antes de que comiencen a afectar a los equipos o clientes de OTGS.  <\/p>\n\n<p>Cada dos semanas, estoy de guardia en caso de emergencias.<\/p>\n\n<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"4d285562e94aea15f716a720b6f16b00\"><img decoding=\"async\" width=\"894\" height=\"972\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image4a.jpg\" alt=\"\" class=\"wp-image-13846 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image4a.jpg 894w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image4a-276x300.jpg 276w\" data-sizes=\"auto, (max-width: 894px) 100vw, 894px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 894px; --smush-placeholder-aspect-ratio: 894\/972;\" \/><figcaption><div class=\"tb-image-caption\"><em>La perra de Abdallah, Kiera, durante un paseo matutino<\/em><\/div><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">En su experiencia, \u00bfcu\u00e1les son las mejores cosas y las cosas m\u00e1s desafiantes de trabajar de forma remota?<\/h2>\n\n<p>Siempre me preguntan sobre los desaf\u00edos de trabajar de forma remota. Por supuesto, es importante estar organizado, pero si quiere ser eficiente, eso es un hecho para cualquier tipo de trabajo, en el sitio o de forma remota. Y luego est\u00e1 el desaf\u00edo de poder concentrarse mientras el resto de la familia sigue con sus vidas. Sin embargo, ese no es un problema para m\u00ed, ya que tanto mi esposa como yo trabajamos desde casa.   <\/p>\n\n<p>Lo que me gusta de trabajar de forma remota es c\u00f3mo puedo mantenerme m\u00e1s concentrado en mi trabajo. No tengo que lidiar con las molestias diarias del tr\u00e1fico y la furia en la carretera y dem\u00e1s. Y puedo desayunar, almorzar y cenar con mi esposa. Esa es probablemente la mejor parte de todo para m\u00ed.    <img decoding=\"async\" width=\"17\" height=\"17\" data-src=\"https:\/\/lh5.googleusercontent.com\/ivCc_NMd9ImY00bCNVDT3zkTHMtlTdUtizeA1mrKAAAZTtQWNI2UbFIukaAsqUUdT6EzDcg58K_yn_yOaHSQFovhE6xCBWlpLEwX7dbhW9btShliiPptICsq3d24_xdWlZF7aXU6\" alt=\"&#xBF;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 17px; --smush-placeholder-aspect-ratio: 17\/17;\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La estrella del mes, Abdallah Deeb, nos cuenta c\u00f3mo comenz\u00f3 su amor por las computadoras, c\u00f3mo trabajar de manera m\u00e1s inteligente y qui\u00e9n manda en su casa. Abdallah, cu\u00e9ntanos sobre ti. Soy del L\u00edbano, nacido y criado en la ciudad de Beirut. Durante mi adolescencia, descubr\u00ed mi inter\u00e9s por la tecnolog\u00eda. Las PC reci\u00e9n comenzaban [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":13842,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150,152],"tags":[],"class_list":["post-20508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conoce-a-nuestro-equipo","category-trabajos-e-historias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"La estrella del mes, Abdallah Deeb, nos cuenta c\u00f3mo comenz\u00f3 su amor por las computadoras, c\u00f3mo trabajar de manera m\u00e1s inteligente y qui\u00e9n manda en su casa. Abdallah, cu\u00e9ntanos sobre ti. Soy del L\u00edbano, nacido y criado en la ciudad de Beirut. Durante mi adolescencia, descubr\u00ed mi inter\u00e9s por la tecnolog\u00eda. Las PC reci\u00e9n comenzaban [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T07:50:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kathy Banach\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kathy Banach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/\"},\"author\":{\"name\":\"Kathy Banach\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/2af460740e0f1e95603e7f5a1331bf95\"},\"headline\":\"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir\",\"datePublished\":\"2024-06-03T07:40:00+00:00\",\"dateModified\":\"2025-09-08T07:50:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/\"},\"wordCount\":1143,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/onthegosystems-remote-work-abdallah-deeb-image3.jpg\",\"articleSection\":[\"Conoce a nuestro equipo\",\"Trabajos e Historias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/\",\"name\":\"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/onthegosystems-remote-work-abdallah-deeb-image3.jpg\",\"datePublished\":\"2024-06-03T07:40:00+00:00\",\"dateModified\":\"2025-09-08T07:50:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/onthegosystems-remote-work-abdallah-deeb-image3.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/onthegosystems-remote-work-abdallah-deeb-image3.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2022\\\/04\\\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/2af460740e0f1e95603e7f5a1331bf95\",\"name\":\"Kathy Banach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed3a27f2d1d22c69c8e41811b1f83020f81ce0e6d2917c893c90fb8fdcc3214?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed3a27f2d1d22c69c8e41811b1f83020f81ce0e6d2917c893c90fb8fdcc3214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed3a27f2d1d22c69c8e41811b1f83020f81ce0e6d2917c893c90fb8fdcc3214?s=96&d=mm&r=g\",\"caption\":\"Kathy Banach\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/author\\\/kathy-b\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/","og_locale":"es_ES","og_type":"article","og_title":"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir - OnTheGoSystems","og_description":"La estrella del mes, Abdallah Deeb, nos cuenta c\u00f3mo comenz\u00f3 su amor por las computadoras, c\u00f3mo trabajar de manera m\u00e1s inteligente y qui\u00e9n manda en su casa. Abdallah, cu\u00e9ntanos sobre ti. Soy del L\u00edbano, nacido y criado en la ciudad de Beirut. Durante mi adolescencia, descubr\u00ed mi inter\u00e9s por la tecnolog\u00eda. Las PC reci\u00e9n comenzaban [&hellip;]","og_url":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:40:00+00:00","article_modified_time":"2025-09-08T07:50:12+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image3.jpg","type":"image\/jpeg"}],"author":"Kathy Banach","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Kathy Banach","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/"},"author":{"name":"Kathy Banach","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/2af460740e0f1e95603e7f5a1331bf95"},"headline":"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir","datePublished":"2024-06-03T07:40:00+00:00","dateModified":"2025-09-08T07:50:12+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/"},"wordCount":1143,"publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image3.jpg","articleSection":["Conoce a nuestro equipo","Trabajos e Historias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/","url":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/","name":"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image3.jpg","datePublished":"2024-06-03T07:40:00+00:00","dateModified":"2025-09-08T07:50:12+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image3.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2022\/04\/onthegosystems-remote-work-abdallah-deeb-image3.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/es\/2022\/04\/abdallah-deeb-sobre-la-eliminacion-de-obstaculos-y-por-que-el-trabajo-a-distancia-es-el-camino-a-seguir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Abdallah Deeb sobre c\u00f3mo eliminar obst\u00e1culos y por qu\u00e9 el trabajo remoto es el camino a seguir"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/es\/#website","url":"https:\/\/onthegosystems.com\/es\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/es\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/2af460740e0f1e95603e7f5a1331bf95","name":"Kathy Banach","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9ed3a27f2d1d22c69c8e41811b1f83020f81ce0e6d2917c893c90fb8fdcc3214?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ed3a27f2d1d22c69c8e41811b1f83020f81ce0e6d2917c893c90fb8fdcc3214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ed3a27f2d1d22c69c8e41811b1f83020f81ce0e6d2917c893c90fb8fdcc3214?s=96&d=mm&r=g","caption":"Kathy Banach"},"url":"https:\/\/onthegosystems.com\/es\/author\/kathy-b\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/20508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/comments?post=20508"}],"version-history":[{"count":5,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/20508\/revisions"}],"predecessor-version":[{"id":29289,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/20508\/revisions\/29289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media\/13842"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media?parent=20508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/categories?post=20508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/tags?post=20508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}