{"id":21098,"date":"2023-03-31T14:00:00","date_gmt":"2024-06-03T08:54:47","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/"},"modified":"2025-09-08T07:44:58","modified_gmt":"2025-09-08T07:44:58","slug":"ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/","title":{"rendered":"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n"},"content":{"rendered":"\n<p class=\"lead has-medium-font-size\">En este art\u00edculo, presentamos a nuestra <strong>Estrella del mes<\/strong>, <a href=\"https:\/\/onthegosystems.com\/es\/team\/ahmed-ibrahim\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ahmed Ibrahim<\/a>, subdirector del equipo de proxy de traducci\u00f3n en OTGS. Comparte su experiencia trabajando de forma remota y las habilidades y cualificaciones necesarias para su trabajo. Ahmed habla de su trayectoria desde desarrollador de PHP hasta su puesto actual, donde trabaja en estrecha colaboraci\u00f3n con su equipo para proporcionar asistencia y garantizar un proceso de traducci\u00f3n fluido para los socios y sus clientes.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"935\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-1024x935.jpg\" alt=\"\" class=\"wp-image-15613 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-1024x935.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-300x274.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-1536x1402.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-scaled.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/935;\" \/><figcaption class=\"wp-element-caption\"><em>\u00a1D\u00eda de diversi\u00f3n con amigos en New Cairo City!<\/em><\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\"><strong>\u00bfPuede contarnos un poco sobre usted?<\/strong><\/h2>\n\n<p>Claro. Soy de Alejandr\u00eda, Egipto. Tengo a mis padres, a mi hermana y a mi esposa, y estamos esperando nuestro primer hijo en los pr\u00f3ximos tres meses. En mi tiempo libre, me gusta viajar, leer, ver pel\u00edculas y pasar tiempo con mis amigos y mi familia.   <\/p>\n\n<h2 class=\"wp-block-heading\"><strong><strong>\u00bfQu\u00e9 hac\u00eda antes de unirme a OTGS?<\/strong><\/strong><\/h2>\n\n<p>Antes de unirme a OTGS, trabajaba como desarrollador de PHP para empresas locales aqu\u00ed en El Cairo, Egipto.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo se enter\u00f3 de la empresa? \u00bfCu\u00e1ndo se uni\u00f3? <\/strong><\/h2>\n\n<p>O\u00ed hablar de la empresa por mi amigo Ahmed Mohammed, que tambi\u00e9n es empleado de OTGS. Me un\u00ed a la empresa el 8 de abril de 2015. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfPuede describir su trabajo?<\/strong><\/h2>\n\n<p>Cuando me un\u00ed a la empresa, trabajaba con el equipo de asistencia de WPML. Mi funci\u00f3n era ayudar a los clientes de WPML y depurar cualquier problema notificado, que escalaba al equipo de desarrollo de WPML. Entonces, cuando nuestra empresa comenz\u00f3 con nuestras aplicaciones de Translation Proxy (TP), me convert\u00ed en el primer asistente del equipo. Utilic\u00e9 mis conocimientos de WPML para ayudar a nuestros clientes de TP a enviar y recibir traducciones de nuestros socios de servicios de traducci\u00f3n, y solucion\u00e9 cualquier problema relacionado con WPML o TP.   <\/p>\n\n<p>M\u00e1s tarde, empec\u00e9 a aprender Ruby on Rails para entender mejor nuestras aplicaciones de TP y poder depurar y proponer soluciones para cualquier problema notificado. Ahora, soy el subdirector del equipo de TP, lo que significa que organizo todas las tareas relacionadas con el equipo de TP y me aseguro de que nuestros socios de servicios de traducci\u00f3n y sus clientes reciban una buena asistencia. Adem\u00e1s, estoy trabajando en la mejora de nuestras aplicaciones de TP y en la eliminaci\u00f3n de cualquier posible problema para que el proceso de traducci\u00f3n sea fluido y f\u00e1cil para nuestros clientes.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Hanging-out-with-my-mother-my-wife-and-my-sister-1024x768.jpg\" alt=\"\" class=\"wp-image-15614 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Hanging-out-with-my-mother-my-wife-and-my-sister-1024x768.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Hanging-out-with-my-mother-my-wife-and-my-sister-300x225.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Hanging-out-with-my-mother-my-wife-and-my-sister-1536x1152.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Hanging-out-with-my-mother-my-wife-and-my-sister-scaled.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><em>Pasando tiempo con mi esposa, hermana y madre<\/em><\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 cualificaciones se necesitan para hacer bien su trabajo?<\/strong><\/h2>\n\n<p>Para hacer bien mi trabajo, es necesario conocer muy bien nuestro plugin WPML y entender todas las opciones que ofrece. Adem\u00e1s, debe tener conocimientos de programaci\u00f3n en PHP y Ruby on Rails. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfCon qu\u00e9 equipos o miembros del equipo trabaja en estrecha colaboraci\u00f3n?<\/strong><\/h2>\n\n<p>Todos los d\u00edas, trabajo en estrecha colaboraci\u00f3n con nuestro jefe de proyecto, Eduard, y mis compa\u00f1eros Ahmed Mamdouh, Channa y Benjamin.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo es un d\u00eda normal?<\/strong><\/h2>\n\n<p>Siempre empiezo el d\u00eda con una taza de caf\u00e9 y tengo una reuni\u00f3n con mi equipo para discutir nuestro progreso y cualquier bloqueo que estemos experimentando. Luego, priorizo cualquier solicitud de asistencia de nuestros clientes antes de pasar a las tareas de desarrollo.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/On-a-safari-trip-with-my-wife-1024x768.jpg\" alt=\"\" class=\"wp-image-15615 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/On-a-safari-trip-with-my-wife-1024x768.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/On-a-safari-trip-with-my-wife-300x225.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/On-a-safari-trip-with-my-wife-1536x1152.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/On-a-safari-trip-with-my-wife-scaled.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><em>En un viaje de safari con mi esposa<\/em><\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 le llev\u00f3 a elegir el trabajo a distancia?<\/strong><\/h2>\n\n<p>Hay un n\u00famero limitado de empresas de software ubicadas en Alejandr\u00eda, as\u00ed que tuve que mudarme a El Cairo para encontrar una buena empresa. Despu\u00e9s de unirme a OTGS, puedo vivir cerca de mi familia mientras trabajo para una gran empresa. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>En su experiencia, \u00bfcu\u00e1les son las mejores cosas y las cosas m\u00e1s desafiantes de trabajar de forma remota?<\/strong><\/h2>\n\n<p>Lo mejor de trabajar de forma remota es la flexibilidad que proporciona. Puedo trabajar desde cualquier lugar, as\u00ed que puedo viajar a otra ciudad y seguir siendo capaz de hacer el mismo trabajo. La parte m\u00e1s dif\u00edcil es separar mi vida personal y mi trabajo. Es importante que la gente que me rodea entienda la naturaleza de mi trabajo y me d\u00e9 el espacio que necesito para concentrarme en mis tareas diarias.   <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 le ayuda a sentirse conectado con los dem\u00e1s cuando trabaja en remoto?<\/strong><\/h2>\n\n<p>Hacemos muchas llamadas durante la semana, y tenemos muchos canales que nos ayudan a chatear y trabajar en estrecha colaboraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este art\u00edculo, presentamos a nuestra Estrella del mes, Ahmed Ibrahim, subdirector del equipo de proxy de traducci\u00f3n en OTGS. Comparte su experiencia trabajando de forma remota y las habilidades y cualificaciones necesarias para su trabajo. Ahmed habla de su trayectoria desde desarrollador de PHP hasta su puesto actual, donde trabaja en estrecha colaboraci\u00f3n con [&hellip;]<\/p>\n","protected":false},"author":56,"featured_media":21103,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152],"tags":[],"class_list":["post-21098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trabajos-e-historias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"En este art\u00edculo, presentamos a nuestra Estrella del mes, Ahmed Ibrahim, subdirector del equipo de proxy de traducci\u00f3n en OTGS. Comparte su experiencia trabajando de forma remota y las habilidades y cualificaciones necesarias para su trabajo. Ahmed habla de su trayectoria desde desarrollador de PHP hasta su puesto actual, donde trabaja en estrecha colaboraci\u00f3n con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T08:54:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T07:44:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1869\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eloise Brink\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eloise Brink\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/\"},\"author\":{\"name\":\"Eloise Brink\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/07b6b3fc249abec7934caa520cfbc35f\"},\"headline\":\"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n\",\"datePublished\":\"2024-06-03T08:54:47+00:00\",\"dateModified\":\"2025-09-08T07:44:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/\"},\"wordCount\":756,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/A-Ahmed-scaled.jpg\",\"articleSection\":[\"Trabajos e Historias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/\",\"name\":\"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/A-Ahmed-scaled.jpg\",\"datePublished\":\"2024-06-03T08:54:47+00:00\",\"dateModified\":\"2025-09-08T07:44:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/A-Ahmed-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/A-Ahmed-scaled.jpg\",\"width\":2048,\"height\":1869},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2023\\\/03\\\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/07b6b3fc249abec7934caa520cfbc35f\",\"name\":\"Eloise Brink\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g\",\"caption\":\"Eloise Brink\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/author\\\/eloise-b\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/","og_locale":"es_ES","og_type":"article","og_title":"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n - OnTheGoSystems","og_description":"En este art\u00edculo, presentamos a nuestra Estrella del mes, Ahmed Ibrahim, subdirector del equipo de proxy de traducci\u00f3n en OTGS. Comparte su experiencia trabajando de forma remota y las habilidades y cualificaciones necesarias para su trabajo. Ahmed habla de su trayectoria desde desarrollador de PHP hasta su puesto actual, donde trabaja en estrecha colaboraci\u00f3n con [&hellip;]","og_url":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T08:54:47+00:00","article_modified_time":"2025-09-08T07:44:58+00:00","og_image":[{"width":2048,"height":1869,"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-scaled.jpg","type":"image\/jpeg"}],"author":"Eloise Brink","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eloise Brink","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/"},"author":{"name":"Eloise Brink","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/07b6b3fc249abec7934caa520cfbc35f"},"headline":"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n","datePublished":"2024-06-03T08:54:47+00:00","dateModified":"2025-09-08T07:44:58+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/"},"wordCount":756,"publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-scaled.jpg","articleSection":["Trabajos e Historias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/","url":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/","name":"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-scaled.jpg","datePublished":"2024-06-03T08:54:47+00:00","dateModified":"2025-09-08T07:44:58+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-scaled.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/A-Ahmed-scaled.jpg","width":2048,"height":1869},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/es\/2023\/03\/ahmed-ibrahim-habla-del-trabajo-a-distancia-en-egipto-y-de-como-convertirse-en-jefe-adjunto-del-equipo-de-traduccion-por-delegacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Ahmed Ibrahim sobre c\u00f3mo desenvolverse en el trabajo remoto en Egipto y convertirse en subdirector del equipo de proxy de traducci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/es\/#website","url":"https:\/\/onthegosystems.com\/es\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/es\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/07b6b3fc249abec7934caa520cfbc35f","name":"Eloise Brink","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g","caption":"Eloise Brink"},"url":"https:\/\/onthegosystems.com\/es\/author\/eloise-b\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/21098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/comments?post=21098"}],"version-history":[{"count":5,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/21098\/revisions"}],"predecessor-version":[{"id":29169,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/21098\/revisions\/29169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media\/21103"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media?parent=21098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/categories?post=21098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/tags?post=21098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}