{"id":24530,"date":"2020-06-08T17:10:23","date_gmt":"2020-06-08T17:10:23","guid":{"rendered":"https:\/\/onthegosystems.com\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/"},"modified":"2024-09-05T09:08:04","modified_gmt":"2024-09-05T09:08:04","slug":"tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/","title":{"rendered":"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales"},"content":{"rendered":"\n<p>Asistir a un WordCamp result\u00f3 en un emocionante cambio de carrera para Kruno Golubi\u0107, el Empleado del mes de mayo.\nConoceremos mejor a Kruno en la siguiente entrevista. <\/p>\n\n<h3 class=\"wp-block-heading\">Kruno, \u00bfde d\u00f3nde eres?<\/h3>\n\n<p>Soy de Zagreb, la capital de Croacia.\nDe hecho, he vivido toda mi vida aqu\u00ed. <\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-1024x768.jpg\" alt=\"\" class=\"wp-image-6892 lazyload\" width=\"768\" height=\"576\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-1024x768.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-300x225.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-1536x1152.jpg 1536w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb.jpg 1600w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/576;\" \/><figcaption>Vista de Zagreb<\/figcaption><\/figure><\/div>\n\n<p>Cuando era ni\u00f1o, \u00e9ramos siete viviendo en la misma casa: mis abuelos, mis padres, mis dos hermanos y yo.\nAhora la vida es menos concurrida ya que solo somos tres: mi esposa Ana, mi hijo Nikola y yo.\nLlevo una vida familiar simple y ordinaria.\nLos fines de semana, voy al mercado local a comprar alimentos saludables y todos disfrutamos de actividades familiares como jugar juegos de mesa y dibujar.    <\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Kruno-Ana-and-Nikola-1024x768.jpg\" alt=\"\" class=\"wp-image-6891 lazyload\" width=\"768\" height=\"576\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/576;\" \/><figcaption>Kruno, Ana y Nikola<\/figcaption><\/figure><\/div>\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo te involucraste en la inform\u00e1tica?<\/h3>\n\n<p>Cuando ten\u00eda unos 10 a\u00f1os, obtuve mi primera computadora.\nEra un ZX Spectrum.\nAprend\u00ed BASIC, y esto me interes\u00f3 en las computadoras y todo lo relacionado con ellas.\nLuego, en 1995, descubr\u00ed Internet.\nEse mismo a\u00f1o cre\u00e9 mi primer sitio web.\nDesde ese momento, la inform\u00e1tica se convirti\u00f3 en parte de mi vida cotidiana.\nHe ocupado una variedad de puestos en mi carrera profesional, pero todos estaban enfocados en la tecnolog\u00eda de la informaci\u00f3n, el soporte al usuario y la educaci\u00f3n.      <\/p>\n\n<p>La inform\u00e1tica tambi\u00e9n fue el enfoque de mi educaci\u00f3n formal.\nTengo una licenciatura en Tecnolog\u00eda de la Informaci\u00f3n, una maestr\u00eda en Biblioteconom\u00eda y Ciencias de la Informaci\u00f3n y un doctorado en Ciencias de la Informaci\u00f3n y la Comunicaci\u00f3n. <\/p>\n\n<p>De vez en cuando, asisto a <a href=\"https:\/\/central.wordcamp.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Word Camps <\/a> y <a href=\"https:\/\/www.meetup.com\/topics\/wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">WordPress Meetups<\/a> organizados por la comunidad WP. <\/p>\n\n<p><strong>Esta es la primera raz\u00f3n importante para apoyar los WordCamps y los WP Meetups: son grandes oportunidades para involucrarse m\u00e1s con otros entusiastas de la inform\u00e1tica, compartir ideas y conocer a otros usuarios y desarrolladores.<\/strong><\/p>\n\n<p>OnTheGoSystems anima activamente a sus empleados a participar activamente en los WordCamps e incluso a organizar WP Meetups locales<strong>.<\/strong> <\/p>\n\n<p><strong>La segunda raz\u00f3n para asistir a estos eventos es que puedes conocer personalmente al personal de OTGS.\nComo somos una empresa remota, no tenemos forma de reunirnos regularmente a menos que apoyes regularmente los WordCamps y los WP Meetups. <\/strong><strong>.<\/strong> La gente conoce nuestros productos, WPML y Toolset, m\u00e1s que el nombre de la empresa OTGS.\nLlevamos camisetas que anuncian nuestras marcas y los clientes se acercan a nosotros en un ambiente amigable para hacer preguntas o expresar sus preocupaciones.  <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfAs\u00ed fue como escuchaste sobre la empresa?<\/h3>\n\n<p>\u00a1Exactamente!\nAsist\u00eda a WordCamp Zagreb por primera vez en 2017.\nDario Jazbec Hrvatin de OnTheGoSystems estaba dando una de las conferencias.\nSe titulaba \u201cFuentes Abiertas de Inspiraci\u00f3n\u201d.\nNunca habl\u00e9 con Dario, pero me impresion\u00f3 su uso de H\u00e9rcules Poirot como ilustraci\u00f3n.\nHizo su presentaci\u00f3n personal para m\u00ed, ya que soy fan de Poirot y nunca olvid\u00e9 a Dario.\nAlg\u00fan tiempo despu\u00e9s, mientras segu\u00eda al grupo croata de WordPress en Facebook, me encontr\u00e9 con un anuncio de trabajo que Dario hab\u00eda publicado.\nLo record\u00e9 de inmediato.\nLa oferta de trabajo me atrajo, as\u00ed que apliqu\u00e9.\n\u00a1Si no hubiera asistido a ese WordCamp, probablemente nunca habr\u00eda notado la oferta de trabajo!         <\/p>\n\n<p>Y hoy Dario es mi l\u00edder de equipo :)<\/p>\n\n<p><strong>Esto me lleva a la tercera raz\u00f3n para asistir a los eventos de WP<\/strong> &#8211; <strong>conocer a personas de OTGS en eventos de WordPress puede llevar a un emocionante cambio de carrera.<\/strong><strong> <\/strong>\u00a1As\u00ed fue para m\u00ed!\nMe un\u00ed a OTGS exactamente un a\u00f1o despu\u00e9s de ese WordCamp.\nSiempre hab\u00eda querido trabajar para una empresa verdaderamente internacional para ganar nueva experiencia y habilidades.\nTrabajar para OTGS fue mi primer trabajo remoto.\nFue un refrescante cambio de carrera.\nComenc\u00e9 a trabajar para OTGS en septiembre de 2018 como Redactor T\u00e9cnico.\nMis habilidades fueron r\u00e1pidamente reconocidas y recompensadas.\nSolo un a\u00f1o despu\u00e9s, mi rol fue ascendido a Asistente de Documentaci\u00f3n T\u00e9cnica.       <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfTe gustar\u00eda explicarnos en qu\u00e9 consiste tu trabajo?<\/h3>\n\n<p>Por supuesto. Trabajo como parte del equipo de Documentaci\u00f3n.\nPodr\u00edas pensar que la Documentaci\u00f3n se trata solo de escribir las instrucciones para los usuarios, pero no es as\u00ed.\nEs mucho, mucho m\u00e1s.\nAqu\u00ed en el equipo de Documentaci\u00f3n tambi\u00e9n creamos instrucciones en video, tutoriales, cursos, etc.\nAsistimos al equipo de Marketing cuando se trata de escribir y crear ciertos materiales.\nNuestros WPML y Toolset Supporters tambi\u00e9n dependen de la documentaci\u00f3n que producimos.\nAs\u00ed que, aunque trabajo con todos los equipos, principalmente trabajo con los equipos de Soporte y Marketing.      <\/p>\n\n<p>Tambi\u00e9n soy responsable de mantener actualizadas las traducciones de nuestros sitios web y plugins.\nEsto significa que tengo que trabajar estrechamente con nuestro equipo de sistemas y tambi\u00e9n con nuestros desarrolladores.\nTrabajar con traductores externos tambi\u00e9n es parte de mis tareas diarias.  <\/p>\n\n<p>Las habilidades m\u00e1s importantes para este trabajo son las habilidades de escritura y comunicaci\u00f3n.\nLa clave es poder ponerse en el lugar de un usuario final y ver las cosas desde su perspectiva.  <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 cualificaciones se necesitan?<\/h3>\n\n<p>No necesitas ser un desarrollador, pero una buena comprensi\u00f3n del proceso de desarrollo y habilidades b\u00e1sicas de programaci\u00f3n ayudan mucho.\nSiempre intenta aprender cosas nuevas.\nQA y UX son los campos que me atraen mucho.\nEspero encontrar tiempo para aprender m\u00e1s sobre ellos.   <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfSigues participando en WP eventos?<\/h3>\n\n<p>Por supuesto.<strong> <\/strong>Fui ponente en el <a rel=\"noreferrer noopener\" href=\"https:\/\/www.meetup.com\/Zagreb-WordPress-Meetup\/events\/260060540\/\" target=\"_blank\">Zagreb WordPress Meetup en marzo de 2019<\/a>.\nAcab\u00e1bamos de lanzar la 1<sup>ra<\/sup> Beta de Toolset Blocks y fue un gran honor para m\u00ed dar al mundo este adelanto.  <\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Kruno-at-WP-meetup-1024x682.jpg\" alt=\"\" class=\"wp-image-6890 lazyload\" width=\"768\" height=\"512\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/512;\" \/><\/figure><\/div>\n\n<p>Dario y Danijel Erjavec tambi\u00e9n estaban all\u00ed.\nDanijel y yo hab\u00edamos estado en la universidad juntos hace 20 a\u00f1os.\nVio mi nombre en la <a href=\"https:\/\/onthegosystems.com\/team\/\">P\u00e1gina del equipo<\/a> y me llam\u00f3.\nHoy somos colegas.   <\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/wp-meetups-1-1024x682.jpg\" alt=\"\" class=\"wp-image-6889 lazyload\" width=\"768\" height=\"512\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/512;\" \/><figcaption>De izquierda a derecha Kruno, Dario, Danijel en WP Meetup Zagreb marzo 2019<\/figcaption><\/figure><\/div>\n\n<p>Me gusta trabajar de forma remota.\nMe da flexibilidad cuando se trata de equilibrar la vida personal y profesional.\nSomos una empresa global.\nEsto me da la oportunidad de trabajar con personas de diferentes pa\u00edses y con diversos antecedentes culturales.\nSiempre estoy aprendiendo cosas nuevas.    <\/p>\n\n<p class=\"has-very-light-gray-background-color has-background\">Ver tambi\u00e9n: <a href=\"https:\/\/www.remoter.com\/getting-familiar-with-a-remote-company\" target=\"_blank\" rel=\"noreferrer noopener\">Familiariz\u00e1ndose con una empresa remota<\/a>  <\/p>\n\n<p>En cuanto a los desaf\u00edos del trabajo remoto, debo admitir que a veces extra\u00f1o tener un compa\u00f1ero de trabajo cerca de m\u00ed.\nPor eso disfruto asistiendo a WordCamps y WP meetups \u2013 \u00a1es genial tener interacci\u00f3n humana en vivo de nuevo! <\/p>\n\n<p><strong>En WordCamps y WP Meetups te involucras m\u00e1s con otros entusiastas de TI. Puedes conocernos personalmente de OTGS y obtener las respuestas correctas a tus preguntas.\n\u00a1Qui\u00e9n sabe, puede que decidas unirte a nosotros! <\/strong><\/p>\n\n<p class=\"has-text-align-left\">Echa un vistazo a nuestras posiciones abiertas: <a href=\"https:\/\/onthegosystems.com\/jobs\/\">WordPress Jobs<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asistir a un WordCamp result\u00f3 en un emocionante cambio de carrera para Kruno Golubi\u0107, el Empleado del mes de mayo. Conoceremos mejor a Kruno en la siguiente entrevista. Kruno, \u00bfde d\u00f3nde eres? Soy de Zagreb, la capital de Croacia. De hecho, he vivido toda mi vida aqu\u00ed. Cuando era ni\u00f1o, \u00e9ramos siete viviendo en la [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-24530","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Asistir a un WordCamp result\u00f3 en un emocionante cambio de carrera para Kruno Golubi\u0107, el Empleado del mes de mayo. Conoceremos mejor a Kruno en la siguiente entrevista. Kruno, \u00bfde d\u00f3nde eres? Soy de Zagreb, la capital de Croacia. De hecho, he vivido toda mi vida aqu\u00ed. Cuando era ni\u00f1o, \u00e9ramos siete viviendo en la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-08T17:10:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-05T09:08:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-1024x768.jpg\" \/>\n<meta name=\"author\" content=\"Helena Petridou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Petridou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/\"},\"author\":{\"name\":\"Helena Petridou\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\"},\"headline\":\"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales\",\"datePublished\":\"2020-06-08T17:10:23+00:00\",\"dateModified\":\"2024-09-05T09:08:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/\"},\"wordCount\":1153,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Zagreb-1024x768.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/\",\"name\":\"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Zagreb-1024x768.jpg\",\"datePublished\":\"2020-06-08T17:10:23+00:00\",\"dateModified\":\"2024-09-05T09:08:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Zagreb-1024x768.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Zagreb-1024x768.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/2020\\\/06\\\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/#\\\/schema\\\/person\\\/dc037ea6159c870ded51c4ab8d120555\",\"name\":\"Helena Petridou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g\",\"caption\":\"Helena Petridou\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/es\\\/author\\\/helena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/","og_locale":"es_ES","og_type":"article","og_title":"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales - OnTheGoSystems","og_description":"Asistir a un WordCamp result\u00f3 en un emocionante cambio de carrera para Kruno Golubi\u0107, el Empleado del mes de mayo. Conoceremos mejor a Kruno en la siguiente entrevista. Kruno, \u00bfde d\u00f3nde eres? Soy de Zagreb, la capital de Croacia. De hecho, he vivido toda mi vida aqu\u00ed. Cuando era ni\u00f1o, \u00e9ramos siete viviendo en la [&hellip;]","og_url":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/","og_site_name":"OnTheGoSystems","article_published_time":"2020-06-08T17:10:23+00:00","article_modified_time":"2024-09-05T09:08:04+00:00","og_image":[{"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-1024x768.jpg","type":"","width":"","height":""}],"author":"Helena Petridou","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Helena Petridou","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/"},"author":{"name":"Helena Petridou","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555"},"headline":"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales","datePublished":"2020-06-08T17:10:23+00:00","dateModified":"2024-09-05T09:08:04+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/"},"wordCount":1153,"publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-1024x768.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/","url":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/","name":"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-1024x768.jpg","datePublished":"2020-06-08T17:10:23+00:00","dateModified":"2024-09-05T09:08:04+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-1024x768.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/06\/Zagreb-1024x768.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/es\/2020\/06\/tres-buenas-razones-para-apoyar-los-eventos-wordcamp-y-los-wpmeetups-locales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Tres buenas razones para apoyar los eventos WordCamp y los WPMeetups locales"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/es\/#website","url":"https:\/\/onthegosystems.com\/es\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/es\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/es\/#\/schema\/person\/dc037ea6159c870ded51c4ab8d120555","name":"Helena Petridou","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93ccb36449c6cba73beee4cc657ffb1f960ec71a9e9a8a01d61135606760a589?s=96&d=mm&r=g","caption":"Helena Petridou"},"url":"https:\/\/onthegosystems.com\/es\/author\/helena\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/24530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/comments?post=24530"}],"version-history":[{"count":1,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/24530\/revisions"}],"predecessor-version":[{"id":24531,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/posts\/24530\/revisions\/24531"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/media?parent=24530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/categories?post=24530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/es\/wp-json\/wp\/v2\/tags?post=24530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}