{"id":19461,"date":"2020-12-01T09:41:14","date_gmt":"2024-06-03T07:33:43","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/nouvelles-de-novembre-de-lotgs-2\/"},"modified":"2024-06-03T07:33:46","modified_gmt":"2024-06-03T07:33:46","slug":"nouvelles-de-novembre-de-lotgs-2","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/","title":{"rendered":"Nouvelles de novembre de l&rsquo;OTGS"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Avant d&rsquo;entrer dans la p\u00e9riode des f\u00eates, nous avons pass\u00e9 notre mois de novembre \u00e0 travailler assid\u00fbment sur les prochaines versions de Toolset et de WPML. Dans le m\u00eame temps, notre soutien a continu\u00e9 \u00e0 fonctionner comme une horloge et nous avons poursuivi notre travail avec nos partenaires.  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Nouvelles du jeu d&rsquo;outils<\/strong><\/h2>\n\n<div class=\"wp-block-toolset-blocks-grid tb-grid\" data-toolset-blocks-grid=\"519e2e0078cea32a65130ccb4ae2e1fd\">\n<div class=\"wp-block-toolset-blocks-grid-column tb-grid-column tb-grid-align-top\" data-toolset-blocks-grid-column=\"3034fbe886c11054e95b46b09d3e4112\">\n<p>Le mois de novembre a \u00e9t\u00e9 plac\u00e9 sous le signe de la stabilit\u00e9 et de la performance pour l&rsquo;\u00e9quipe Toolset. Nous venons de publier une version commune de tous les plugins Toolset. Elle contient des tonnes de correctifs et d&rsquo;am\u00e9liorations de la convivialit\u00e9, ainsi que de meilleures performances. Vous trouverez tous les d\u00e9tails dans le <a href=\"https:\/\/toolset.com\/2020\/11\/toolset-blocks-1-3-3-and-types-3-4-3-bugfix-release\/\">billet d&rsquo;annonce<\/a>.<\/p>\n\n\n\n<p>Nous nous pr\u00e9parons \u00e9galement \u00e0 la prochaine version de WordPress 5.6 et aux nouveaux changements apport\u00e9s \u00e0 son \u00e9diteur de blocs. Cela implique de travailler dur pour assurer une compatibilit\u00e9 totale avec PHP 8.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-toolset-blocks-grid-column tb-grid-column tb-grid-align-top\" data-toolset-blocks-grid-column=\"3034fbe886c11054e95b46b09d3e4112\">\n<figure class=\"wp-block-image tb-image tb-image-media tb-image-frame-none\" data-toolset-blocks-image=\"1a1e41eea59385e7fad8c21af5699493\"><img decoding=\"async\" width=\"850\" height=\"510\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/11\/1.3.3.png\" alt=\"\" class=\"wp-image-19462 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/11\/1.3.3.png 850w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/11\/1.3.3-300x180.png 300w\" data-sizes=\"auto, (max-width: 850px) 100vw, 850px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 850px; --smush-placeholder-aspect-ratio: 850\/510;\" \/><\/figure>\n<\/div>\n<\/div>\n\n<p>Notre prochaine version est d\u00e9j\u00e0 presque pr\u00eate et sera test\u00e9e dans les prochains jours. Il apportera quelques fonctionnalit\u00e9s incroyables aux plugins Toolset. Nous vous donnerons tous les d\u00e9tails dans le prochain billet de blog.<\/p>\n\n<p>Enfin, nous pr\u00e9voyons \u00e9galement d&rsquo;achever certaines t\u00e2ches de compatibilit\u00e9 majeures concernant les constructeurs de pages et les blocs de tierces parties, ainsi que certaines am\u00e9liorations de performance li\u00e9es aux scripts et aux styles charg\u00e9s sur le front-end.<\/p>\n\n<p>Pour plus d&rsquo;informations, <a href=\"https:\/\/toolset.com\/blog\/\">visitez notre blog Toolset<\/a>.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Nouvelles WPML<\/strong><\/h2>\n\n<div class=\"wp-block-toolset-blocks-grid tb-grid\" data-toolset-blocks-grid=\"4eaa8132a41f2bbb4635a38a32045971\">\n<div class=\"wp-block-toolset-blocks-grid-column tb-grid-column tb-grid-align-top\" data-toolset-blocks-grid-column=\"3034fbe886c11054e95b46b09d3e4112\">\n<figure class=\"wp-block-image tb-image tb-image-media tb-image-frame-none\" data-toolset-blocks-image=\"9eb1304ece28972dd51a7c048888c23e\"><img decoding=\"async\" width=\"1024\" height=\"800\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/11\/wpml-4-4-5.png\" alt=\"\" class=\"wp-image-19463 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/11\/wpml-4-4-5.png 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/11\/wpml-4-4-5-300x234.png 300w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/800;\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-toolset-blocks-grid-column tb-grid-column tb-grid-align-top\" data-toolset-blocks-grid-column=\"3034fbe886c11054e95b46b09d3e4112\">\n<h3 class=\"wp-block-heading\"><strong>WPML 4.4.5, 4.4.6, et 4.4.7 beta<\/strong><\/h3>\n\n\n\n<p>Nous avons publi\u00e9 trois versions de corrections mineures de WPML : 4.4.5, 4.4.6 et la version b\u00eata pour 4.4.7. Toutes ces versions incluent une s\u00e9rie de probl\u00e8mes de compatibilit\u00e9 avec WordPress 5.6 et PHP 8.0.<\/p>\n\n\n\n<p>Notre exp\u00e9rience nous a appris que jusqu&rsquo;\u00e0 la toute derni\u00e8re version candidate, WordPress pouvait inclure des changements radicaux. Par cons\u00e9quent, nous ne publierons la version officielle de WPML 4.4.7 qu&rsquo;apr\u00e8s la derni\u00e8re version candidate de WordPress 5.6. Vraisemblablement, cela se fera entre le 1er d\u00e9cembre (date de la deuxi\u00e8me version candidate) et le 8 d\u00e9cembre (date pr\u00e9vue pour la sortie de WordPress 5.6).<\/p>\n<\/div>\n<\/div>\n\n<h3 class=\"wp-block-heading\"><strong>\u00c9diteur de traduction avanc\u00e9<\/strong><\/h3>\n\n<p>En novembre, nous avons publi\u00e9 une version importante de notre Advanced Translation Editor (ATE). La principale nouveaut\u00e9 est l&rsquo;ajout du service de traduction automatique DeepL. Nous avons \u00e9galement modifi\u00e9 notre syst\u00e8me de paiement, qui n&rsquo;est plus bas\u00e9 sur les mots mais sur les cr\u00e9dits.<\/p>\n\n<p>Cette version vous permet \u00e9galement de cr\u00e9er des langues personnalis\u00e9es et de visualiser les traductions d&rsquo;autres sources directement dans l&rsquo;ATE.<\/p>\n\n<p>Vous pouvez trouver tous les d\u00e9tails de cette version dans le <a href=\"https:\/\/wpml.org\/announcements\/2020\/11\/deepl-integration-and-new-pricing-for-automatic-translation\/\">billet d&rsquo;annonce<\/a>.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>WPML 4.5.0<\/strong><\/h3>\n\n<p>Nous avons continu\u00e9 \u00e0 travailler \u00e0 un bon rythme sur ce grand projet. Elle comprendra de nombreuses nouvelles fonctionnalit\u00e9s pour les traducteurs et des changements dans l&rsquo;interface utilisateur. Les deux visent \u00e0 rationaliser et \u00e0 am\u00e9liorer l&rsquo;exp\u00e9rience globale.<\/p>\n\n<p><a href=\"https:\/\/wpml.org\/blog\/\">Visitez notre blog WPML<\/a> pour suivre toutes les derni\u00e8res nouvelles.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Compatibilit\u00e9<\/strong><\/h2>\n\n<p>D\u00e9but novembre, nous avons annonc\u00e9 le lancement de notre annuaire de plugins recommand\u00e9s par WPML. Avec plus de 60 plugins diff\u00e9rents r\u00e9pertori\u00e9s, allant des constructeurs de pages et des plugins de calendrier au SEO et aux sliders, nous fournissons maintenant \u00e0 nos clients une gamme compl\u00e8te de plugins compatibles avec WPML sur lesquels ils peuvent compter pour construire un site web multilingue.  <\/p>\n\n<p>Mais le travail ne s&rsquo;arr\u00eate pas l\u00e0 &#8211; la compatibilit\u00e9 WPML est une priorit\u00e9 pour notre \u00e9quipe de partenaires et les auteurs de ces fantastiques plugins. Nous travaillons continuellement \u00e0 la compatibilit\u00e9 de nos plugins et trouvons des moyens de partager cette nouvelle avec nos clients &#8211; comme cette mention \u00e9logieuse de WPML dans un tour d&rsquo;horizon des <a href=\"https:\/\/formidableforms.com\/best-translation-plugins-wordpress\/\">meilleurs plugins de traduction<\/a>.<\/p>\n\n<p>Ensuite, nous faisons le m\u00eame genre de r\u00e9pertoire pour les th\u00e8mes.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Affili\u00e9s et partenariats<\/strong><\/h2>\n\n<p>Chez OnTheGoSystems, nous aimons les partenariats, qu&rsquo;ils soient anciens ou nouveaux.  <\/p>\n\n<p>En novembre, nous avons lanc\u00e9 un nouveau partenariat Toolset important avec le th\u00e8me populaire WooCommerce, WoodMart. Les clients peuvent maintenant utiliser notre th\u00e8me et notre plugin ensemble pour <a href=\"https:\/\/toolset.com\/documentation\/recommended-themes\/using-toolset-with-the-woodmart-theme\/\">construire des sites WooCommerce personnalis\u00e9s sans codage<\/a>, et nous sommes impatients de travailler avec d&rsquo;autres th\u00e8mes WooCommerce \u00e0 l&rsquo;avenir.  <\/p>\n\n<p>En ce qui concerne les nouveaux partenariats, nous avons \u00e9galement accueilli 11 nouveaux partenaires dans le programme Go Global de WPML ce mois-ci et nous avons contact\u00e9 un certain nombre de plugins et de th\u00e8mes populaires afin d&rsquo;assurer la compatibilit\u00e9 WPML pour notre base de clients partag\u00e9e.  <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Partenaires de traduction<\/strong><\/h3>\n\n<p>Nous avons commenc\u00e9 le mois de novembre avec une nouvelle version &#8211; InnovaLang.<\/p>\n\n<p>Avec des bureaux en Italie et en France, InnovaLang rejoint WPML pour apporter sa grande exp\u00e9rience dans la traduction de brevets (ils en ont traduit plus de 20 000 depuis 2003), ainsi que dans la traduction technique, scientifique, juridique et logistique (Travel &amp; Tourism Translation).<\/p>\n\n<p>Vous cherchez un service de traduction en italien ? Vous pouvez en savoir plus sur InnovaLang en lisant leur <a href=\"https:\/\/innovalang.eu\/en\/blog-en\/innovalang-wpml-as-web-translation-partners\/\">annonce d&rsquo;int\u00e9gration<\/a>.<\/p>\n\n<p>D&rsquo;autre part, notre partenaire de traduction de longue date BeTranslated a publi\u00e9 sa propre page sur la <a href=\"https:\/\/www.betranslated.com\/website-translation-services\/wordpress\/\">traduction de WordPress avec WPML<\/a>. D\u00e9couvrez comment BeTranslated peut vous aider \u00e0 rendre votre site multilingue.<\/p>\n\n<p>De nombreuses nouvelles int\u00e9grations sont en cours, alors attendez les nouvelles du mois prochain et restez \u00e0 l&rsquo;\u00e9coute.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Soutien<\/strong><\/h2>\n\n<p>Nous avons eu un mois de novembre tr\u00e8s charg\u00e9 en ce qui concerne le support WPML et Toolset, en accueillant de nouveaux clients et en relevant les nouveaux d\u00e9fis qui en d\u00e9coulent. Nous avons tout de m\u00eame r\u00e9ussi \u00e0 ajouter et \u00e0 conclure quelques nouveaux flux de travail et outils. Il s&rsquo;agit notamment de mieux suivre les questions pour lesquelles nos clients ont le plus besoin d&rsquo;aide. Cela nous aidera \u00e0 mettre en \u0153uvre une nouvelle s\u00e9rie d&rsquo;am\u00e9liorations dans la mani\u00e8re dont nous apportons notre soutien.  <\/p>\n\n<p>Nous avons \u00e9galement interview\u00e9 et recrut\u00e9 de nouveaux candidats pour notre \u00e9quipe talentueuse. Nous sommes heureux d&rsquo;avoir trouv\u00e9 des candidats tr\u00e8s solides et prometteurs qui nous aideront \u00e0 renforcer certains de nos forums et chats d&rsquo;assistance non anglophones.  <\/p>\n\n<p class=\"has-text-align-center\">Merci d&rsquo;avoir lu&#8230;<\/p>\n\n<p class=\"has-text-align-center\"><strong>Et restez \u00e0 l&rsquo;\u00e9coute pour les mises \u00e0 jour du mois prochain !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avant d&rsquo;entrer dans la p\u00e9riode des f\u00eates, nous avons pass\u00e9 notre mois de novembre \u00e0 travailler assid\u00fbment sur les prochaines versions de Toolset et de WPML. Dans le m\u00eame temps, notre soutien a continu\u00e9 \u00e0 fonctionner comme une horloge et nous avons poursuivi notre travail avec nos partenaires. Nouvelles du jeu d&rsquo;outils Notre prochaine version [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":19464,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153],"tags":[],"class_list":["post-19461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-sur-les-produits"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvelles de novembre de l&#039;OTGS - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelles de novembre de l&#039;OTGS - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Avant d&rsquo;entrer dans la p\u00e9riode des f\u00eates, nous avons pass\u00e9 notre mois de novembre \u00e0 travailler assid\u00fbment sur les prochaines versions de Toolset et de WPML. Dans le m\u00eame temps, notre soutien a continu\u00e9 \u00e0 fonctionner comme une horloge et nous avons poursuivi notre travail avec nos partenaires. Nouvelles du jeu d&rsquo;outils Notre prochaine version [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:33:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-03T07:33:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/12\/11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1077\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dario Jazbec Hrvatin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dario Jazbec Hrvatin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/\"},\"author\":{\"name\":\"Dario Jazbec Hrvatin\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/person\\\/b1f055ef760205c01fbe3c4abd79f5fa\"},\"headline\":\"Nouvelles de novembre de l&rsquo;OTGS\",\"datePublished\":\"2024-06-03T07:33:43+00:00\",\"dateModified\":\"2024-06-03T07:33:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/\"},\"wordCount\":1054,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/11.jpg\",\"articleSection\":[\"Nouvelles sur les produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/\",\"name\":\"Nouvelles de novembre de l'OTGS - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/11.jpg\",\"datePublished\":\"2024-06-03T07:33:43+00:00\",\"dateModified\":\"2024-06-03T07:33:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/11.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/11.jpg\",\"width\":1400,\"height\":1077},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2020\\\/12\\\/nouvelles-de-novembre-de-lotgs-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles de novembre de l&#8217;OTGS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/person\\\/b1f055ef760205c01fbe3c4abd79f5fa\",\"name\":\"Dario Jazbec Hrvatin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g\",\"caption\":\"Dario Jazbec Hrvatin\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/author\\\/dario-h\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelles de novembre de l'OTGS - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelles de novembre de l'OTGS - OnTheGoSystems","og_description":"Avant d&rsquo;entrer dans la p\u00e9riode des f\u00eates, nous avons pass\u00e9 notre mois de novembre \u00e0 travailler assid\u00fbment sur les prochaines versions de Toolset et de WPML. Dans le m\u00eame temps, notre soutien a continu\u00e9 \u00e0 fonctionner comme une horloge et nous avons poursuivi notre travail avec nos partenaires. Nouvelles du jeu d&rsquo;outils Notre prochaine version [&hellip;]","og_url":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:33:43+00:00","article_modified_time":"2024-06-03T07:33:46+00:00","og_image":[{"width":1400,"height":1077,"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/12\/11.jpg","type":"image\/jpeg"}],"author":"Dario Jazbec Hrvatin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dario Jazbec Hrvatin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/"},"author":{"name":"Dario Jazbec Hrvatin","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/person\/b1f055ef760205c01fbe3c4abd79f5fa"},"headline":"Nouvelles de novembre de l&rsquo;OTGS","datePublished":"2024-06-03T07:33:43+00:00","dateModified":"2024-06-03T07:33:46+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/"},"wordCount":1054,"publisher":{"@id":"https:\/\/onthegosystems.com\/fr\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/12\/11.jpg","articleSection":["Nouvelles sur les produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/","url":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/","name":"Nouvelles de novembre de l'OTGS - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/12\/11.jpg","datePublished":"2024-06-03T07:33:43+00:00","dateModified":"2024-06-03T07:33:46+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/12\/11.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/12\/11.jpg","width":1400,"height":1077},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/fr\/2020\/12\/nouvelles-de-novembre-de-lotgs-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Nouvelles de novembre de l&#8217;OTGS"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/fr\/#website","url":"https:\/\/onthegosystems.com\/fr\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/fr\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/person\/b1f055ef760205c01fbe3c4abd79f5fa","name":"Dario Jazbec Hrvatin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf495f47d881795fccb25b68d4621b8c9f3a7efd7d4bfa225cd55d6b896143a5?s=96&d=mm&r=g","caption":"Dario Jazbec Hrvatin"},"url":"https:\/\/onthegosystems.com\/fr\/author\/dario-h\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/19461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/comments?post=19461"}],"version-history":[{"count":1,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/19461\/revisions"}],"predecessor-version":[{"id":19467,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/19461\/revisions\/19467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/media\/19464"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/media?parent=19461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/categories?post=19461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/tags?post=19461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}