{"id":20282,"date":"2016-12-30T13:22:44","date_gmt":"2024-06-03T07:38:32","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/bilan-communautaire-de-lotgs-2016\/"},"modified":"2024-06-03T07:38:32","modified_gmt":"2024-06-03T07:38:32","slug":"bilan-communautaire-de-lotgs-2016","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/","title":{"rendered":"Bilan communautaire de l&rsquo;OTGS 2016"},"content":{"rendered":"<p><b>2016 a \u00e9t\u00e9 une excellente ann\u00e9e pour WordPress. Il est pass\u00e9 de 25 % \u00e0 27 % sur l&rsquo;internet aujourd&rsquo;hui. L&rsquo;ann\u00e9e a \u00e9galement \u00e9t\u00e9 excellente pour OnTheGoSystems et la communaut\u00e9 WordPress elle-m\u00eame. Nous constatons que de plus en plus d&rsquo;OTGSiens souhaitent participer, prendre la parole et m\u00eame organiser des WordCamps.<\/b><\/p>\n<p>Tout d&rsquo;abord, chez OnTheGoSystems, nous avons cr\u00e9\u00e9 un nouveau poste au sein de l&rsquo;organisation. Sa mission est de prendre soin de notre participation \u00e0 la communaut\u00e9. Cet espace nous a permis d&rsquo;organiser du mat\u00e9riel, d&rsquo;en cr\u00e9er de nouveaux, d&rsquo;augmenter la quantit\u00e9 et d&rsquo;am\u00e9liorer la qualit\u00e9 de nos pr\u00e9sentations lors des WordCamps. Nous n&rsquo;avons qu&rsquo;un seul objectif : nous rapprocher de vous, la communaut\u00e9 WordPress.<\/p>\n<p>D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, nos OTGSiens sont de plus en plus d\u00e9sireux de s&rsquo;impliquer dans la communaut\u00e9. Nous avons m\u00eame \u00e9crit sur cette <a href=\"https:\/\/onthegosystems.com\/2016\/10\/otgs-wordpress-fever\/\">fi\u00e8vre<\/a>. Des membres de l&rsquo;\u00e9quipe participaient pour la premi\u00e8re fois \u00e0 un WordCamp, mais nous avions aussi de nouveaux organisateurs, des b\u00e9n\u00e9voles, de nouveaux orateurs et des orateurs exp\u00e9riment\u00e9s.<\/p>\n<h2>WordCamps<\/h2>\n<p>Outre le fait que WPML est un <a href=\"https:\/\/central.wordcamp.org\/global-community-sponsors\/\">sponsor de la communaut\u00e9 mondiale<\/a> depuis plusieurs ann\u00e9es, en 2016, OTGS a contribu\u00e9 \u00e0 <b>26<\/b> WordCamps. Gr\u00e2ce \u00e0 notre distribution \u00e0 distance, nous avons pu \u00eatre pr\u00e9sents sur <b>4<\/b> continents diff\u00e9rents.<\/p>\n<p><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2.jpg\"><img decoding=\"async\" class=\"size-large wp-image-3562 aligncenter lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2-600x342.jpg\" alt=\"\" width=\"600\" height=\"342\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2-600x342.jpg 600w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2-300x171.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2.jpg 940w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/342;\" \/><\/a><\/p>\n<p><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/speakers.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-3545 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/speakers.jpg\" alt=\"Les orateurs de l'OTGS\" width=\"279\" height=\"244\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/speakers.jpg 400w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/speakers-300x263.jpg 300w\" data-sizes=\"(max-width: 279px) 100vw, 279px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 279px; --smush-placeholder-aspect-ratio: 279\/244;\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Nous avons \u00e9galement eu <b>11 orateurs<\/b> qui ont donn\u00e9 <b>22<\/b> conf\u00e9rences. Parmi eux, <b>6 ont pr\u00e9sent\u00e9 un <\/b>expos\u00e9 lors d&rsquo;un WordCamp pour la premi\u00e8re fois de leur vie. Je mentionnerai ici <a href=\"https:\/\/onthegosystems.com\/2016\/11\/become-wordcamp-expert-months\/\">Lauren Jeffcoat<\/a> qui n&rsquo;\u00e9tait pas seulement la premi\u00e8re fois qu&rsquo;elle intervenait \u00e0 WordCamp, mais qui a \u00e9galement pr\u00e9sent\u00e9 6 fois 3 conf\u00e9rences diff\u00e9rentes, devenant ainsi notre conf\u00e9renci\u00e8re la plus exp\u00e9riment\u00e9e pour 2016. Elle est en feu !<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignright wp-image-3544 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/organisers-1.jpg\" alt=\"Organisateurs de l'OTGS\" width=\"287\" height=\"249\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 287px; --smush-placeholder-aspect-ratio: 287\/249;\"><\/p>\n<p>&nbsp;<\/p>\n<p>Nous avions \u00e9galement <b>5 organisateurs de WordCamp<\/b>: Harshad a dirig\u00e9 le WordCamp Nashik, Lauren le WordCamp Wilmington, Konstantinos le WordCamp Ath\u00e8nes et j&rsquo;ai particip\u00e9 aux <a href=\"https:\/\/onthegosystems.com\/2016\/11\/wordcamp-incubator-wordcamp-medellin-experience\/\">WordCamp Medellin<\/a> et Sevilla.<\/p>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/7.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-3542 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/7.jpg\" width=\"294\" height=\"198\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 294px; --smush-placeholder-aspect-ratio: 294\/198;\"><\/a><\/p>\n<p>L&rsquo;un des objectifs de cette ann\u00e9e \u00e9tait \u00e9galement de commencer \u00e0 <a href=\"https:\/\/onthegosystems.com\/2016\/11\/lets-get-together-at-a-wordcamp\/\">participer en tant que repr\u00e9sentants des sponsors<\/a>. Le fait d&rsquo;\u00eatre un sponsor mondial est formidable, mais il nous manquait cette interaction en direct avec la communaut\u00e9 et nos utilisateurs. Au total, nous avons particip\u00e9 \u00e0 <b>7 \u00e9v\u00e9nements avec 25 repr\u00e9sentants de sponsors <\/b>. Nous avons d\u00fb pr\u00e9parer de nouveaux documents, mais heureusement, Peter en \u00e9tait responsable. Le temps \u00e9tait compt\u00e9 et il y avait beaucoup de travail \u00e0 accomplir. Cependant, nous avons beaucoup appris au cours de ce processus et nous sommes pr\u00eats et impatients d&rsquo;\u00eatre plus proches de vous en 2017.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/5.jpg\"><img decoding=\"async\" class=\"alignright wp-image-3541 lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/5.jpg\" alt=\"5 volontaires\" width=\"276\" height=\"217\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/5.jpg 445w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/5-300x236.jpg 300w\" data-sizes=\"(max-width: 276px) 100vw, 276px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 276px; --smush-placeholder-aspect-ratio: 276\/217;\" \/><\/a><\/p>\n<p>Au cours de ce billet, nous n&rsquo;avons cess\u00e9 de parler de l&rsquo;importance du premier contact avec la communaut\u00e9. Contribuer \u00e0 un WordCamp en tant que b\u00e9n\u00e9vole est la premi\u00e8re \u00e9tape. Vous rencontrez des orateurs, des organisateurs et vous ressentez toute l&rsquo;\u00e9nergie dynamique des coulisses d&rsquo;un WordCamp, mais dans une position confortable et engag\u00e9e. Cette ann\u00e9e, nous avons eu <b>5 volontaires, <\/b>et je suis presque s\u00fbr que ce sera la premi\u00e8re \u00e9tape pour de nouveaux organisateurs et conf\u00e9renciers en 2017.<\/p>\n<h2><\/h2>\n<h2>WordCamp Europe<\/h2>\n<p><a href=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/logo-wceu-2016.png\"><img decoding=\"async\" class=\"wp-image-3543 aligncenter lazyload\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/logo-wceu-2016.png\" alt=\"logo wceu 2016\" width=\"239\" height=\"185\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 239px; --smush-placeholder-aspect-ratio: 239\/185;\"><\/a><\/p>\n<p>WordCamp Europe m\u00e9rite une mention sp\u00e9ciale car il continue d&rsquo;\u00eatre un point de rencontre pour notre \u00e9quipe. En tant qu&rsquo;\u00e9quipe \u00e0 distance, nous sommes conscients de l&rsquo;importance d&rsquo;organiser une r\u00e9union d&rsquo;entreprise annuelle, mais WordCamp Europe continue d&rsquo;\u00eatre<i> l&rsquo;<\/i> \u00e9v\u00e9nement qui nous permet de nous rencontrer pour la deuxi\u00e8me fois la m\u00eame ann\u00e9e. L&rsquo;ann\u00e9e 2016 n&rsquo;a pas fait exception et nous \u00e9tions environ 25 passionn\u00e9s de WordPress \u00e0 nous amuser \u00e0 Vienne. Cette ann\u00e9e, nous avons eu <b>10 repr\u00e9sentants <\/b>et <b>2 volontaires<\/b>.<\/p>\n<p>Pour l&rsquo;ann\u00e9e prochaine, je (Andr\u00e9s) ferai partie des organisateurs de WordCamp Europe 2017 et nous esp\u00e9rons avoir plusieurs de nos propres intervenants.<\/p>\n<h2>Qu&rsquo;est-ce qui vous attend en 2017 ?<\/h2>\n<p>Notre objectif pour 2017 est de continuer \u00e0 accro\u00eetre notre pr\u00e9sence aux WordCamps dans tous les r\u00f4les possibles. Nous avons d\u00e9j\u00e0 des confirmations pour 2 organisateurs et 2 orateurs pour le premier trimestre, mais en fin de compte, ce que nous voulons, c&rsquo;est entrer en contact avec <i>vous<\/i> et donner quelque chose en retour \u00e0 cette formidable communaut\u00e9 WordPress.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2016 a \u00e9t\u00e9 une excellente ann\u00e9e pour WordPress. Il est pass\u00e9 de 25 % \u00e0 27 % sur l&rsquo;internet aujourd&rsquo;hui. L&rsquo;ann\u00e9e a \u00e9galement \u00e9t\u00e9 excellente pour OnTheGoSystems et la communaut\u00e9 WordPress elle-m\u00eame. Nous constatons que de plus en plus d&rsquo;OTGSiens souhaitent participer, prendre la parole et m\u00eame organiser des WordCamps. Tout d&rsquo;abord, chez OnTheGoSystems, nous [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":20289,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139,147],"tags":[],"class_list":["post-20282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-travail-et-histoires"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bilan communautaire de l&#039;OTGS 2016 - OnTheGoSystems<\/title>\n<meta name=\"description\" content=\"Bilan 2016 des \u00e9v\u00e9nements de la communaut\u00e9 OTGS : statistiques de notre participation aux WordCamp : 11 intervenants, 5 organisateurs, 5 b\u00e9n\u00e9voles, 11 WordCamps en tant que repr\u00e9sentants.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bilan communautaire de l&#039;OTGS 2016 - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Bilan 2016 des \u00e9v\u00e9nements de la communaut\u00e9 OTGS : statistiques de notre participation aux WordCamp : 11 intervenants, 5 organisateurs, 5 b\u00e9n\u00e9voles, 11 WordCamps en tant que repr\u00e9sentants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andr\u00e9s Cifuentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9s Cifuentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/\"},\"author\":{\"name\":\"Andr\u00e9s Cifuentes\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/person\\\/f1cc327c0559d348fc6342790d5d7966\"},\"headline\":\"Bilan communautaire de l&rsquo;OTGS 2016\",\"datePublished\":\"2024-06-03T07:38:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/\"},\"wordCount\":723,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/wordcamps-2.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\",\"Travail et histoires\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/\",\"name\":\"Bilan communautaire de l'OTGS 2016 - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/wordcamps-2.jpg\",\"datePublished\":\"2024-06-03T07:38:32+00:00\",\"description\":\"Bilan 2016 des \u00e9v\u00e9nements de la communaut\u00e9 OTGS : statistiques de notre participation aux WordCamp : 11 intervenants, 5 organisateurs, 5 b\u00e9n\u00e9voles, 11 WordCamps en tant que repr\u00e9sentants.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/wordcamps-2.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/wordcamps-2.jpg\",\"width\":940,\"height\":536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2016\\\/12\\\/bilan-communautaire-de-lotgs-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bilan communautaire de l&#8217;OTGS 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/person\\\/f1cc327c0559d348fc6342790d5d7966\",\"name\":\"Andr\u00e9s Cifuentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g\",\"caption\":\"Andr\u00e9s Cifuentes\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/author\\\/andres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bilan communautaire de l'OTGS 2016 - OnTheGoSystems","description":"Bilan 2016 des \u00e9v\u00e9nements de la communaut\u00e9 OTGS : statistiques de notre participation aux WordCamp : 11 intervenants, 5 organisateurs, 5 b\u00e9n\u00e9voles, 11 WordCamps en tant que repr\u00e9sentants.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/","og_locale":"fr_FR","og_type":"article","og_title":"Bilan communautaire de l'OTGS 2016 - OnTheGoSystems","og_description":"Bilan 2016 des \u00e9v\u00e9nements de la communaut\u00e9 OTGS : statistiques de notre participation aux WordCamp : 11 intervenants, 5 organisateurs, 5 b\u00e9n\u00e9voles, 11 WordCamps en tant que repr\u00e9sentants.","og_url":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T07:38:32+00:00","og_image":[{"width":940,"height":536,"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2.jpg","type":"image\/jpeg"}],"author":"Andr\u00e9s Cifuentes","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Andr\u00e9s Cifuentes","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/"},"author":{"name":"Andr\u00e9s Cifuentes","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/person\/f1cc327c0559d348fc6342790d5d7966"},"headline":"Bilan communautaire de l&rsquo;OTGS 2016","datePublished":"2024-06-03T07:38:32+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/"},"wordCount":723,"publisher":{"@id":"https:\/\/onthegosystems.com\/fr\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2.jpg","articleSection":["Non classifi\u00e9(e)","Travail et histoires"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/","url":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/","name":"Bilan communautaire de l'OTGS 2016 - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2.jpg","datePublished":"2024-06-03T07:38:32+00:00","description":"Bilan 2016 des \u00e9v\u00e9nements de la communaut\u00e9 OTGS : statistiques de notre participation aux WordCamp : 11 intervenants, 5 organisateurs, 5 b\u00e9n\u00e9voles, 11 WordCamps en tant que repr\u00e9sentants.","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2016\/12\/wordcamps-2.jpg","width":940,"height":536},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/fr\/2016\/12\/bilan-communautaire-de-lotgs-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Bilan communautaire de l&#8217;OTGS 2016"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/fr\/#website","url":"https:\/\/onthegosystems.com\/fr\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/fr\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/person\/f1cc327c0559d348fc6342790d5d7966","name":"Andr\u00e9s Cifuentes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98f92b0fe371dda5df3edeb23c86556aa3556878c93398895c0022e1eedf3005?s=96&d=mm&r=g","caption":"Andr\u00e9s Cifuentes"},"url":"https:\/\/onthegosystems.com\/fr\/author\/andres\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/20282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/comments?post=20282"}],"version-history":[{"count":0,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/20282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/media\/20289"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/media?parent=20282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/categories?post=20282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/tags?post=20282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}