{"id":21152,"date":"2023-03-07T14:19:51","date_gmt":"2024-06-03T08:55:12","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/"},"modified":"2025-09-08T07:45:26","modified_gmt":"2025-09-08T07:45:26","slug":"ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/","title":{"rendered":"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance"},"content":{"rendered":"\n<p class=\"lead has-medium-font-size wp-block-paragraph\">Notre Star of the Month Ahmed Mohammed partage ses exp\u00e9riences de travail \u00e0 distance depuis l&rsquo;\u00c9gypte, la cr\u00e9ation de liens avec son \u00e9quipe et l&rsquo;exploration du monde en dehors du travail.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Ahmed, parlez-nous de vous.<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Je vis dans le 6 octobre, une ville du gouvernorat de Gizeh, en \u00c9gypte, qui se trouve \u00e0 seulement 30 minutes des Grandes Pyramides. Je suis p\u00e8re de deux enfants, Bassel et Nelly, et je passe la plupart de mes week-ends avec eux chez ma m\u00e8re. Quand je ne suis pas avec eux, je travaille sur ma cha\u00eene YouTube, o\u00f9 je r\u00e9alise des vid\u00e9os sur WordPress en arabe.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg\" alt=\"\" class=\"wp-image-15496 lazyload\" width=\"512\" height=\"384\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Having-lunch-with-family.-My-sister-mom-wife-and-kids-300x225.jpeg 300w\" data-sizes=\"(max-width: 512px) 100vw, 512px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 512px; --smush-placeholder-aspect-ratio: 512\/384;\" \/><figcaption class=\"wp-element-caption\"><em>D\u00e9jeuner en famille. Ma s\u0153ur, ma m\u00e8re, ma femme et mes enfants <\/em><\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\"><strong>Que faisiez-vous avant de rejoindre OTGS ?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Avant de rejoindre OTGS en juillet 2014, je faisais du travail en freelance li\u00e9 \u00e0 WordPress.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Comment avez-vous entendu parler de l&rsquo;entreprise et quand avez-vous rejoint ?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">J&rsquo;ai trouv\u00e9 le poste apr\u00e8s avoir effectu\u00e9 une recherche sur Google et \u00eatre arriv\u00e9 sur la page Emplois. J&rsquo;ai rejoint OTGS en tant qu&rsquo;assistant de premier niveau pour le plugin WPML (The WordPress Multilingual). J&rsquo;ai ensuite rejoint l&rsquo;\u00e9quipe de compatibilit\u00e9 pour devenir d\u00e9veloppeur de compatibilit\u00e9, travaillant \u00e0 rendre d&rsquo;autres plugins et th\u00e8mes compatibles avec WPML. J&rsquo;ai quitt\u00e9 OTGS en 2021 et je suis revenu fin 2022 en tant qu&rsquo;assistant de premier niveau.   <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/At-WordCamp-Europe-2022-at-Porto.jpeg\" alt=\"\" class=\"wp-image-15498 lazyload\" width=\"576\" height=\"707\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/At-WordCamp-Europe-2022-at-Porto.jpeg 768w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/At-WordCamp-Europe-2022-at-Porto-244x300.jpeg 244w\" data-sizes=\"(max-width: 576px) 100vw, 576px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 576px; --smush-placeholder-aspect-ratio: 576\/707;\" \/><figcaption class=\"wp-element-caption\"><em>Participation au WordCamp Europe 2022 \u00e0 Porto, Portugal<\/em><\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\"><strong>Pourriez-vous d\u00e9crire votre r\u00f4le actuel ?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">En tant qu&rsquo;assistant de premier niveau, ma responsabilit\u00e9 principale est d&rsquo;aider les clients qui utilisent notre plugin avec toutes les demandes d&rsquo;assistance qu&rsquo;ils peuvent avoir. Cela implique de traiter diff\u00e9rents types de demandes d&rsquo;assistance, dont certaines sont li\u00e9es \u00e0 la fonctionnalit\u00e9 WPML, tandis que d&rsquo;autres sont li\u00e9es \u00e0 des probl\u00e8mes de compatibilit\u00e9 avec les th\u00e8mes et plugins. <\/p>\n\n<p class=\"wp-block-paragraph\">Pour \u00eatre un bon assistant, il est essentiel d&rsquo;avoir une compr\u00e9hension approfondie des plugins WPML. De plus, mieux vous connaissez WordPress et son \u00e9cosyst\u00e8me (plugins et th\u00e8mes), mieux vous pouvez fournir une assistance \u00e0 nos clients. Concernant les comp\u00e9tences techniques requises, vous n&rsquo;avez pas besoin de ma\u00eetriser parfaitement PHP, JavaScript et CSS, mais plus vous en savez, plus le travail devient facile.  <\/p>\n\n<p class=\"wp-block-paragraph\">De plus, je travaille en tant que chef d&rsquo;\u00e9quipe, o\u00f9 je fournis une assistance \u00e0 mon \u00e9quipe pour m&rsquo;assurer qu&rsquo;elle ex\u00e9cute ses t\u00e2ches efficacement et que son bien-\u00eatre g\u00e9n\u00e9ral est maintenu.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Avec quelles \u00e9quipes ou quels membres d&rsquo;\u00e9quipe travaillez-vous \u00e9troitement ?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Je travaille en \u00e9troite collaboration avec mon \u00e9quipe d&rsquo;assistants formidables au WordCamp Europe 2022 \u00e0 Porto et l&rsquo;\u00e9quipe des dirigeants.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/With-OTGS-teammates-gathering-at-Elgouna-2022-768x1024.jpg\" alt=\"\" class=\"wp-image-15497 lazyload\" width=\"576\" height=\"768\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/With-OTGS-teammates-gathering-at-Elgouna-2022-768x1024.jpg 768w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/With-OTGS-teammates-gathering-at-Elgouna-2022-225x300.jpg 225w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/With-OTGS-teammates-gathering-at-Elgouna-2022.jpg 960w\" data-sizes=\"(max-width: 576px) 100vw, 576px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 576px; --smush-placeholder-aspect-ratio: 576\/768;\" \/><figcaption class=\"wp-element-caption\"><em>Rassemblement<\/em> a<em>vec les co\u00e9quipiers d&rsquo;OTGS \u00e0 El Gouna, \u00c9gypte<\/em><\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\"><strong>Quelle est la partie la plus difficile de votre travail, et comment la surmontez-vous ?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">En tant qu&rsquo;assistant, la partie la plus difficile est de suivre les changements dans WordPress et les autres plugins et th\u00e8mes. Notre travail quotidien implique de traiter avec de nombreux plugins et th\u00e8mes, et nous devons nous adapter rapidement et comprendre comment ils fonctionnent. Pour surmonter cela, je vais g\u00e9n\u00e9ralement sur les pages de documentation et je les parcours pour avoir un aper\u00e7u du fonctionnement du plugin\/th\u00e8me.  <\/p>\n\n<p class=\"wp-block-paragraph\">Quand les demandes d&rsquo;assistance s&rsquo;accumulent, avec mes autres responsabilit\u00e9s, je priorise les t\u00e2ches urgentes au d\u00e9but de la journ\u00e9e pour rester organis\u00e9 et g\u00e9rer ma charge de travail efficacement.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Qu&rsquo;est-ce qui vous a amen\u00e9 \u00e0 choisir le travail \u00e0 distance ?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Il y a dix ans, je travaillais en tant que freelance et j&rsquo;ai r\u00e9alis\u00e9 \u00e0 quel point je pouvais \u00eatre productif avec la flexibilit\u00e9 in\u00e9gal\u00e9e qui accompagnait le travail \u00e0 distance. Quand j&rsquo;ai commenc\u00e9 \u00e0 chercher un travail \u00e0 temps plein, j&rsquo;\u00e9tais pr\u00eat \u00e0 continuer en tant que travailleur \u00e0 distance et je ne pouvais pas m&rsquo;imaginer faire des trajets pendant des heures vers un bureau pour travailler sur un ordinateur portable. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>S\u00e9parer le temps de travail et le temps personnel peut \u00eatre difficile. Comment g\u00e9rez-vous la fronti\u00e8re entre la vie professionnelle et la maison ? <\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s deux ans de travail \u00e0 distance, je me suis mari\u00e9. Depuis lors, j&rsquo;ai choisi d&rsquo;avoir mon propre espace de bureau. Il a \u00e9volu\u00e9 d&rsquo;une pi\u00e8ce d\u00e9di\u00e9e dans mon appartement \u00e0 un bureau s\u00e9par\u00e9 dans mon immeuble. Je commence ma journ\u00e9e en allant au bureau et quand je termine mon travail, je monte \u00e0 mon appartement pour me d\u00e9connecter compl\u00e8tement du travail.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre Star of the Month Ahmed Mohammed partage ses exp\u00e9riences de travail \u00e0 distance depuis l&rsquo;\u00c9gypte, la cr\u00e9ation de liens avec son \u00e9quipe et l&rsquo;exploration du monde en dehors du travail. Ahmed, parlez-nous de vous. Je vis dans le 6 octobre, une ville du gouvernorat de Gizeh, en \u00c9gypte, qui se trouve \u00e0 seulement 30 [&hellip;]<\/p>\n","protected":false},"author":56,"featured_media":21154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148],"tags":[],"class_list":["post-21152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rencontrez-notre-equipe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Notre Star of the Month Ahmed Mohammed partage ses exp\u00e9riences de travail \u00e0 distance depuis l&rsquo;\u00c9gypte, la cr\u00e9ation de liens avec son \u00e9quipe et l&rsquo;exploration du monde en dehors du travail. Ahmed, parlez-nous de vous. Je vis dans le 6 octobre, une ville du gouvernorat de Gizeh, en \u00c9gypte, qui se trouve \u00e0 seulement 30 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T08:55:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T07:45:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eloise Brink\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eloise Brink\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/\"},\"author\":{\"name\":\"Eloise Brink\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/person\\\/07b6b3fc249abec7934caa520cfbc35f\"},\"headline\":\"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance\",\"datePublished\":\"2024-06-03T08:55:12+00:00\",\"dateModified\":\"2025-09-08T07:45:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/\"},\"wordCount\":782,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg\",\"articleSection\":[\"Rencontrez notre \u00e9quipe\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/\",\"name\":\"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg\",\"datePublished\":\"2024-06-03T08:55:12+00:00\",\"dateModified\":\"2025-09-08T07:45:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/03\\\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/person\\\/07b6b3fc249abec7934caa520cfbc35f\",\"name\":\"Eloise Brink\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g\",\"caption\":\"Eloise Brink\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/author\\\/eloise-b\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/","og_locale":"fr_FR","og_type":"article","og_title":"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance - OnTheGoSystems","og_description":"Notre Star of the Month Ahmed Mohammed partage ses exp\u00e9riences de travail \u00e0 distance depuis l&rsquo;\u00c9gypte, la cr\u00e9ation de liens avec son \u00e9quipe et l&rsquo;exploration du monde en dehors du travail. Ahmed, parlez-nous de vous. Je vis dans le 6 octobre, une ville du gouvernorat de Gizeh, en \u00c9gypte, qui se trouve \u00e0 seulement 30 [&hellip;]","og_url":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T08:55:12+00:00","article_modified_time":"2025-09-08T07:45:26+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg","type":"image\/jpeg"}],"author":"Eloise Brink","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Eloise Brink","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/"},"author":{"name":"Eloise Brink","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/person\/07b6b3fc249abec7934caa520cfbc35f"},"headline":"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance","datePublished":"2024-06-03T08:55:12+00:00","dateModified":"2025-09-08T07:45:26+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/"},"wordCount":782,"publisher":{"@id":"https:\/\/onthegosystems.com\/fr\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg","articleSection":["Rencontrez notre \u00e9quipe"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/","url":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/","name":"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg","datePublished":"2024-06-03T08:55:12+00:00","dateModified":"2025-09-08T07:45:26+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/03\/Having-lunch-with-family.-My-sister-mom-wife-and-kids.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/fr\/2023\/03\/ahmed-mohammed-sur-les-defis-a-relever-la-creation-de-liens-et-le-travail-a-distance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Ahmed Mohammed sur le d\u00e9passement des d\u00e9fis, la cr\u00e9ation de liens et le travail \u00e0 distance"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/fr\/#website","url":"https:\/\/onthegosystems.com\/fr\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/fr\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/person\/07b6b3fc249abec7934caa520cfbc35f","name":"Eloise Brink","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6282e81260bd2ae4b96332ad38103306b5c6632ffedf182f91d6eab18f5f5cb8?s=96&d=mm&r=g","caption":"Eloise Brink"},"url":"https:\/\/onthegosystems.com\/fr\/author\/eloise-b\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/21152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/comments?post=21152"}],"version-history":[{"count":5,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/21152\/revisions"}],"predecessor-version":[{"id":29176,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/21152\/revisions\/29176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/media\/21154"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/media?parent=21152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/categories?post=21152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/tags?post=21152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}