{"id":21923,"date":"2023-11-29T11:15:05","date_gmt":"2024-06-03T09:00:17","guid":{"rendered":"https:\/\/onthegosystems.com\/2024\/06\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/"},"modified":"2025-09-08T07:37:13","modified_gmt":"2025-09-08T07:37:13","slug":"equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems","status":"publish","type":"post","link":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/","title":{"rendered":"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d&rsquo;OnTheGoSystems au Cap"},"content":{"rendered":"\n<p class=\"lead\">Dans un monde o\u00f9 le travail \u00e0 distance fait partie de notre quotidien, il y a quelque chose d&rsquo;extraordinaire \u00e0 se rencontrer en personne. Cette ann\u00e9e, notre \u00e9quipe du Cap a d\u00e9cid\u00e9 de r\u00e9duire l&rsquo;\u00e9cart virtuel et de sortir de derri\u00e8re nos \u00e9crans pour partager des rires, des histoires et le charme de la ville, ensemble. <\/p>\n\n<h3 class=\"wp-block-heading\">Le parcours de solo \u00e0 sept<\/h3>\n\n<p>Il y a environ un an, moi, <a href=\"https:\/\/onthegosystems.com\/team\/dean-jones\/\">Dean Jones<\/a>, j&rsquo;\u00e9tais le seul Sud-Africain de l&rsquo;entreprise. Bien que je me sois toujours senti chez moi aux c\u00f4t\u00e9s de mon groupe cosmopolite de coll\u00e8gues, je me demandais toujours quand des compatriotes sud-africains rejoindraient le club. <\/p>\n\n<p>Avan\u00e7ons rapidement jusqu&rsquo;\u00e0 aujourd&rsquo;hui et nous sommes sept (dont six, moi y compris, bas\u00e9s au Cap). <\/p>\n\n<h3 class=\"wp-block-heading\">Le chemin vers notre premi\u00e8re rencontre<\/h3>\n\n<p>\u00c9tant donn\u00e9 que beaucoup des nouveaux Sud-Africains de l&rsquo;entreprise ont rejoint \u00e0 peu pr\u00e8s au m\u00eame moment, nous n&rsquo;avons jamais eu l&rsquo;occasion d&rsquo;organiser une vraie rencontre car nous devions permettre \u00e0 chacun de trouver ses marques et de s&rsquo;installer dans son r\u00f4le.<\/p>\n\n<p><a href=\"https:\/\/onthegosystems.com\/team\/lauren-carol-chowles\/\">Lauren Chowles<\/a> et moi nous sommes rencontr\u00e9s en personne (puisque nous sommes dans la m\u00eame \u00e9quipe) et nous avions pr\u00e9vu de le faire r\u00e9guli\u00e8rement. Mais la nature \u00e0 distance de notre travail a pris le dessus et nous avons d\u00e9cid\u00e9 de ne pas \u00e9tablir de planning \u00ab officiel \u00bb pour nous rencontrer.  <\/p>\n\n<p>\u00c9tant donn\u00e9 que c&rsquo;\u00e9tait le cas et que les autres Sud-Africains semblaient bien install\u00e9s, j&rsquo;ai pens\u00e9 que novembre serait un bon moment pour que ceux d&rsquo;entre nous bas\u00e9s au Cap se rencontrent avant la fin de l&rsquo;ann\u00e9e et le d\u00e9but des festivit\u00e9s de d\u00e9cembre. <\/p>\n\n<h3 class=\"wp-block-heading\">Une matin\u00e9e au march\u00e9<\/h3>\n\n<p>Nous avions d\u00e9j\u00e0 notre propre \u00ab groupe du Cap \u00bb priv\u00e9 sur Mattermost (notre application de messagerie instantan\u00e9e interne) qui a suscit\u00e9 de belles discussions, il \u00e9tait donc logique de continuer cela en face \u00e0 face. <\/p>\n\n<p>Avec un peu de coordination de base (via ledit groupe), nous avons d\u00e9cid\u00e9 d&rsquo;un moment et d&rsquo;un lieu : <a href=\"https:\/\/ozcf.co.za\/market-day\/\">The Oranjezicht City Farm Market<\/a> \u00e0 9h30 le 18 novembre. <\/p>\n\n<p>\u00ab Pourquoi si t\u00f4t le matin ? \u00bb pourriez-vous demander. Eh bien, ce march\u00e9 est un lieu de rendez-vous extr\u00eamement populaire pour le petit-d\u00e9jeuner et le d\u00e9jeuner en ville, et comme dit le proverbe : l&rsquo;avenir appartient \u00e0 ceux qui se l\u00e8vent t\u00f4t. <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\" tb-image tb-image-dynamic tb-image-frame-none aligncenter\" data-toolset-blocks-image=\"921a9110b89e40c63f91860f50e8a785\"><img decoding=\"async\" width=\"2048\" height=\"1366\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/cape-town-market.jpg\" alt=\"\" class=\"wp-image-21924 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/cape-town-market.jpg 2048w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/cape-town-market-300x200.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/cape-town-market-1024x683.jpg 1024w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/cape-town-market-1536x1025.jpg 1536w\" data-sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1366;\" \/><figcaption><div class=\"tb-image-caption\">C&rsquo;est la saison des cerises au Cap et le march\u00e9 offre parmi les meilleures ! <span style=\"font-size: 10pt; font-family: Arial, sans-serif; background-color: transparent; font-style: italic; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline;\"><\/span>Photo via la page Facebook d&rsquo;OZCFM<\/div><\/figcaption><\/figure>\n<\/div>\n<h3 class=\"wp-block-heading\">Caf\u00e9, conversation et communaut\u00e9<\/h3>\n\n<p>Nous sommes tous arriv\u00e9s (\u00e0 peu pr\u00e8s) \u00e0 l&rsquo;heure et avons fait une tourn\u00e9e caf\u00e9 collective obligatoire. <\/p>\n\n<p>Avec de la caf\u00e9ine dans notre syst\u00e8me, nous \u00e9tions mieux \u00e9quip\u00e9s pour faire notre s\u00e9lection de nourriture parmi l&rsquo;\u00e9norme gamme de choix que le march\u00e9 a \u00e0 offrir. Nous l&rsquo;avons fait juste \u00e0 temps pour trouver une table assez grande pour nous tous (y compris les partenaires et les enfants). <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\" tb-image tb-image-dynamic tb-image-frame-none aligncenter\" data-toolset-blocks-image=\"c4d6e171c85d6c9a6f926d460c8775eb\"><img decoding=\"async\" width=\"1280\" height=\"1074\" data-src=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup.jpg\" alt=\"\" class=\"wp-image-21925 lazyload\" data-srcset=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup.jpg 1280w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup-300x252.jpg 300w, https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup-1024x859.jpg 1024w\" data-sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1074;\" \/><figcaption><div class=\"tb-image-caption\">De gauche \u00e0 droite : Asif, Dean, Lauren et Eloise (avec son nouveau-n\u00e9) <span id=\"docs-internal-guid-e5ccba3f-7fff-1562-abf3-ccc60f374ce9\"><div><span style=\"font-size: 10.5pt; font-family: Roboto, sans-serif; color: rgb(31, 35, 38); background-color: transparent; font-style: italic; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline;\"><\/span><\/div><\/span><\/div><\/figcaption><\/figure>\n<\/div>\n<p>C&rsquo;\u00e9tait merveilleux d&rsquo;\u00eatre ensemble et je pense que nous nous sommes sentis comme une petite famille imm\u00e9diatement. Notre connexion \u00e0 travers l&rsquo;entreprise ainsi que notre pays nous a donn\u00e9 l&rsquo;impression de nous conna\u00eetre depuis des ann\u00e9es.  <\/p>\n\n<p>Nous ne travaillons pas tous dans les m\u00eames \u00e9quipes, donc notre niveau d&rsquo;interaction dans l&rsquo;entreprise variait d&rsquo;une personne \u00e0 l&rsquo;autre. Mais, une fois assis \u00e0 la m\u00eame table, vous auriez facilement pu nous prendre pour une \u00e9quipe qui travaille ensemble depuis des ann\u00e9es. Nous avons trouv\u00e9 un terrain d&rsquo;entente sur de nombreux sujets diff\u00e9rents en dehors de la sph\u00e8re du travail, ce qui \u00e9tait vraiment agr\u00e9able ! De la famille et des voyages aux loisirs et aux int\u00e9r\u00eats personnels, nous avons tout couvert.    <\/p>\n\n<p>Cela montre l&rsquo;importance de la rencontre occasionnelle en personne. Nous appr\u00e9cions tous les nombreux avantages de notre travail \u00e0 distance, mais parfois cela nous fait facilement oublier la valeur de la connexion humaine \u00ab r\u00e9elle \u00bb. Cette rencontre nous en a donn\u00e9 un rappel salutaire.   <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u275d <em>C&rsquo;\u00e9tait formidable de finalement vous rencontrer tous en personne, avec les familles, et d&rsquo;apprendre \u00e0 mieux conna\u00eetre tout le monde. C&rsquo;\u00e9tait aussi ma premi\u00e8re fois au march\u00e9 d&rsquo;Oranjezicht. L&rsquo;ambiance \u00e9tait excellente et je n&rsquo;arrivais pas \u00e0 croire qu&rsquo;il \u00e9tait pass\u00e9 l&rsquo;heure du d\u00e9jeuner quand nous sommes partis !  <\/em>\u275e<\/p>\n<cite>Lauren chowles<\/cite><\/blockquote>\n\n<h3 class=\"wp-block-heading\">La cerise sur le g\u00e2teau de notre rencontre<\/h3>\n\n<p>Le temps a fil\u00e9 et avant que nous nous en rendions compte, nous \u00e9tions l\u00e0 depuis trois bonnes heures ! En nous s\u00e9parant, chacun a fait son propre voyage final \u00e0 travers le march\u00e9 pour choisir (litt\u00e9ralement) quelques articles pour leurs maisons, r\u00e9frig\u00e9rateurs et garde-manger.  <\/p>\n\n<p>J&rsquo;attends avec impatience la prochaine rencontre, et je suis s\u00fbr que nous n&rsquo;attendrons pas une ann\u00e9e enti\u00e8re avant de recommencer !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un monde o\u00f9 le travail \u00e0 distance fait partie de notre quotidien, il y a quelque chose d&rsquo;extraordinaire \u00e0 se rencontrer en personne. Cette ann\u00e9e, notre \u00e9quipe du Cap a d\u00e9cid\u00e9 de r\u00e9duire l&rsquo;\u00e9cart virtuel et de sortir de derri\u00e8re nos \u00e9crans pour partager des rires, des histoires et le charme de la ville, [&hellip;]<\/p>\n","protected":false},"author":51,"featured_media":21925,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[147],"tags":[],"class_list":["post-21923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-travail-et-histoires"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d&#039;OnTheGoSystems au Cap - OnTheGoSystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d&#039;OnTheGoSystems au Cap - OnTheGoSystems\" \/>\n<meta property=\"og:description\" content=\"Dans un monde o\u00f9 le travail \u00e0 distance fait partie de notre quotidien, il y a quelque chose d&rsquo;extraordinaire \u00e0 se rencontrer en personne. Cette ann\u00e9e, notre \u00e9quipe du Cap a d\u00e9cid\u00e9 de r\u00e9duire l&rsquo;\u00e9cart virtuel et de sortir de derri\u00e8re nos \u00e9crans pour partager des rires, des histoires et le charme de la ville, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/\" \/>\n<meta property=\"og:site_name\" content=\"OnTheGoSystems\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T09:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T07:37:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1074\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dean Jones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dean Jones\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/\"},\"author\":{\"name\":\"Dean Jones\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/person\\\/fd992413a05b5c929e0049cbe2004d19\"},\"headline\":\"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d&rsquo;OnTheGoSystems au Cap\",\"datePublished\":\"2024-06-03T09:00:17+00:00\",\"dateModified\":\"2025-09-08T07:37:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/\"},\"wordCount\":863,\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/otgs-cape-town-team-meetup.jpg\",\"articleSection\":[\"Travail et histoires\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/\",\"name\":\"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d'OnTheGoSystems au Cap - OnTheGoSystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/otgs-cape-town-team-meetup.jpg\",\"datePublished\":\"2024-06-03T09:00:17+00:00\",\"dateModified\":\"2025-09-08T07:37:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/otgs-cape-town-team-meetup.jpg\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/otgs-cape-town-team-meetup.jpg\",\"width\":1280,\"height\":1074},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/2023\\\/11\\\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d&#8217;OnTheGoSystems au Cap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\",\"name\":\"OnTheGoSystems\",\"description\":\"WordPress plugins and professional translation\",\"publisher\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#organization\",\"name\":\"OnTheGoSystems\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/onthegosystems.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"OnTheGoSystems\"},\"image\":{\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/#\\\/schema\\\/person\\\/fd992413a05b5c929e0049cbe2004d19\",\"name\":\"Dean Jones\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c61829a35d757c73b9bf1acf7f9fb10ade0702e4911b7b031dcfcfa000fc1117?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c61829a35d757c73b9bf1acf7f9fb10ade0702e4911b7b031dcfcfa000fc1117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c61829a35d757c73b9bf1acf7f9fb10ade0702e4911b7b031dcfcfa000fc1117?s=96&d=mm&r=g\",\"caption\":\"Dean Jones\"},\"url\":\"https:\\\/\\\/onthegosystems.com\\\/fr\\\/author\\\/dean-j\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d'OnTheGoSystems au Cap - OnTheGoSystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d'OnTheGoSystems au Cap - OnTheGoSystems","og_description":"Dans un monde o\u00f9 le travail \u00e0 distance fait partie de notre quotidien, il y a quelque chose d&rsquo;extraordinaire \u00e0 se rencontrer en personne. Cette ann\u00e9e, notre \u00e9quipe du Cap a d\u00e9cid\u00e9 de r\u00e9duire l&rsquo;\u00e9cart virtuel et de sortir de derri\u00e8re nos \u00e9crans pour partager des rires, des histoires et le charme de la ville, [&hellip;]","og_url":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/","og_site_name":"OnTheGoSystems","article_published_time":"2024-06-03T09:00:17+00:00","article_modified_time":"2025-09-08T07:37:13+00:00","og_image":[{"width":1280,"height":1074,"url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup.jpg","type":"image\/jpeg"}],"author":"Dean Jones","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dean Jones","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/#article","isPartOf":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/"},"author":{"name":"Dean Jones","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/person\/fd992413a05b5c929e0049cbe2004d19"},"headline":"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d&rsquo;OnTheGoSystems au Cap","datePublished":"2024-06-03T09:00:17+00:00","dateModified":"2025-09-08T07:37:13+00:00","mainEntityOfPage":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/"},"wordCount":863,"publisher":{"@id":"https:\/\/onthegosystems.com\/fr\/#organization"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup.jpg","articleSection":["Travail et histoires"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/","url":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/","name":"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d'OnTheGoSystems au Cap - OnTheGoSystems","isPartOf":{"@id":"https:\/\/onthegosystems.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/#primaryimage"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/#primaryimage"},"thumbnailUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup.jpg","datePublished":"2024-06-03T09:00:17+00:00","dateModified":"2025-09-08T07:37:13+00:00","breadcrumb":{"@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/#primaryimage","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup.jpg","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2023\/11\/otgs-cape-town-team-meetup.jpg","width":1280,"height":1074},{"@type":"BreadcrumbList","@id":"https:\/\/onthegosystems.com\/fr\/2023\/11\/equipe-a-distance-rencontre-locale-rencontre-au-cap-de-onthegosystems\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onthegosystems.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"\u00c9quipe \u00e0 distance, rencontre locale : le rassemblement d&#8217;OnTheGoSystems au Cap"}]},{"@type":"WebSite","@id":"https:\/\/onthegosystems.com\/fr\/#website","url":"https:\/\/onthegosystems.com\/fr\/","name":"OnTheGoSystems","description":"WordPress plugins and professional translation","publisher":{"@id":"https:\/\/onthegosystems.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onthegosystems.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/onthegosystems.com\/fr\/#organization","name":"OnTheGoSystems","url":"https:\/\/onthegosystems.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","contentUrl":"https:\/\/onthegosystems.com\/wp-content\/uploads\/2020\/07\/cropped-favicon.png","width":512,"height":512,"caption":"OnTheGoSystems"},"image":{"@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onthegosystems.com\/fr\/#\/schema\/person\/fd992413a05b5c929e0049cbe2004d19","name":"Dean Jones","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c61829a35d757c73b9bf1acf7f9fb10ade0702e4911b7b031dcfcfa000fc1117?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c61829a35d757c73b9bf1acf7f9fb10ade0702e4911b7b031dcfcfa000fc1117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c61829a35d757c73b9bf1acf7f9fb10ade0702e4911b7b031dcfcfa000fc1117?s=96&d=mm&r=g","caption":"Dean Jones"},"url":"https:\/\/onthegosystems.com\/fr\/author\/dean-j\/"}]}},"_links":{"self":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/21923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/comments?post=21923"}],"version-history":[{"count":5,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/21923\/revisions"}],"predecessor-version":[{"id":29033,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/posts\/21923\/revisions\/29033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/media\/21925"}],"wp:attachment":[{"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/media?parent=21923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/categories?post=21923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onthegosystems.com\/fr\/wp-json\/wp\/v2\/tags?post=21923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}